{"id":103727,"date":"2021-02-04T17:00:00","date_gmt":"2021-02-04T16:00:00","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=103727"},"modified":"2023-03-01T15:17:43","modified_gmt":"2023-03-01T14:17:43","slug":"bedeutungsschwanger-die-namen-der-lagen","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/","title":{"rendered":"Bedeutungsschwanger: Die Namen der Lagen"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">\u00dcber den Ursprung der Namen der deutschen Weinbergslagen<\/h3>\n\n\n\n<p>Beim St\u00f6bern am Weinregal schon mal verbl\u00fcfft das Etikett einige Zentimeter n\u00e4her an die Augen gehalten und nochmal gelesen? Dann haben Sie sicherlich gerade ein unerwartet g\u00fcnstiges Schn\u00e4ppchen gemacht &#8211; was Ihnen geg\u00f6nnt sei, aber leider nicht allzu h\u00e4ufig geschehen wird &#8211; oder aber Sie sind auf eine der vielen kuriosen Lagebezeichnungen innerhalb des deutschen Weinbaus gesto\u00dfen. Und das d\u00fcrfte wesentlich \u00f6fter passieren, denn von den rund 2600 Einzellagen in Deutschland sind so einige wahre Namensexoten, das gilt besonders f\u00fcr Pfalz und Mosel.<\/p>\n\n\n\n<p>Die Historie der Benennung der Weinlagen ist ein St\u00fcck deutscher Sprach- und Kulturgeschichte und in seiner Vielfalt ein wahrer Bilderbogen damaliger Machtverh\u00e4ltnisse und \u00dcberzeugungen.&nbsp; Hierbei muss man allerdings unterscheiden zwischen tats\u00e4chlich historisch gewachsenen Bezeichnungen und solchen, die im 19. Jahrhundert zum Zweck der Eigenwerbung erdacht wurden. Erst vor etwa 200 Jahren etablierte sich n\u00e4mlich die Abf\u00fcllung des Weines in schlanke, handliche Glasflaschen, vorher verwendete man meist F\u00e4sser. Dadurch er\u00f6ffnete sich f\u00fcr Winzer und H\u00e4ndler die M\u00f6glichkeit, m\u00f6glichst wohlklingende Benennungen zu erfinden &#8211; Kommerz eben, der uns leider nicht viele erz\u00e4hlenswerte Geschichten \u00fcberliefert.&nbsp;<\/p>\n\n\n\n<p>Viele der \u201ealten\u201c Namen hingegen stammen aus der Volkssprache und sind dementsprechend dialektal gef\u00e4rbt oder \u00fcber die Jahrhunderte so verschliffen worden, das sich der Gehalt nur noch erahnen l\u00e4sst: etwa der schon bei Napoleon beliebte Brauneberger \u201eJuffer\u201c an der Mosel. Denn eigentlich m\u00fcsste es eher \u201edie Juffer\u201c hei\u00dfen, bezieht sich das Wort doch auf jene drei T\u00f6chter des kurpf\u00e4lzischen Kammerherrn Wunderlich, die als Unverheiratete, ergo Jungfern, durch ein Erbe in den Besitz der Lage kamen. Andere bilden die Besiedlungsgeschichte eines Ortes ab und weisen vor allem darauf hin, durch wen der Weinbau gegen Ende des 1. Jahrhunderts in deutsche Lande gelangte. Diesseits des Limes erinnern etwa der \u201eR\u00f6merlay\u201c im Ruwertal oder der \u201eR\u00f6mergarten\u201c bei Briedern an die Ahnherren der Mosterzeugung. Die R\u00f6mer brachten jedoch nicht nur die Kunst der Traubenzucht ins kalte Germanien &#8211; die r\u00f6mische Kirche fasste im Fr\u00fchmittelalter nach und nach Fu\u00df und mit ihr immer mehr Kl\u00f6ster, die gro\u00dfe Gebiete unter ihren Einfluss brachten. Der Gro\u00dfteil der deutschen Lagen hat deswegen auch einen meist recht naheliegenden Bezug zum Christentum, \u201eKlosterst\u00fccke\u201c, \u201eJesuiteng\u00e4rten\u201c, \u201eKirchenpfade\u201c oder \u201eAbtsberge\u201c gibt es deutschlandweit zuhauf. Machen wir uns also auf die Suche nach etwas Au\u00dfergew\u00f6hnlicherem, etwa in Lorchhausen. F\u00fcr den sofortigen Eingang der Trinkerseele in das Himmelreich sorgt der Konsum eines von dort stammenden \u201eSeligmachers\u201c wahrscheinlich nicht. Er hat eher etwas mit den Pflanzen zu tun, die dort damals an den Mauern wuchsen: die durch ihre weichen K\u00e4tzchen als Palmsonntagsschmuck beliebten Sal-Weiden standen in mittelhochdeutscher Zeit Pate f\u00fcr die Namensgebung. Diese wurden damals als \u201esalhe\u201c bezeichnet, das durch sie begrenzte Gebiet war lateinisch gesprochen eine \u201emaceria\u201c, eine Einfriedung.<\/p>\n\n\n\n<p>Einen umgekehrt nicht vermuteten, aber tats\u00e4chlichen religi\u00f6sen Hintergrund birgt die Trittenheimer \u201eApotheke\u201c. Diese Mosellage hat n\u00e4mlich nichts mit Gesundheit zu tun und auch wenn ein guter Wein aufs wolkige Gem\u00fct oft wie ein Medikament zu wirken vermag, r\u00fchrt der Name vielmehr daher, dass in fr\u00fcheren Zeiten ein Abt aus dem 30 Kilometer entfernten Trier hier seine Besitzungen hatte, die Lage war somit \u201eaptig\u201c, was der im \u00f6rtlichen Dialekt so bezeichneten \u201eApdikt\u201c, der Apotheke, zum Verwechseln nahe kommt.&nbsp;<\/p>\n\n\n\n<p>Wer statt trockener Herleitungen lieber eine Geschichte erz\u00e4hlt bekommen m\u00f6chte, sollte einen Stopp in Sasbachwalden im Schwarzwald machen. \u201eAlde Gott\u201c hei\u00dft die \u00f6rtliche Weinlage, die in der Mitte des 17. Jahrhunderts wohl \u00e4hnlich brachlag wie die meisten anderen Teile der Landwirtschaft. Der Drei\u00dfigj\u00e4hrige Krieg hatte ganz Deutschland verheert, viele Ortschaften waren niedergebrannt, ihre Bewohner durch Krankheit, Hunger und Gewalt dahingerafft worden. Durch diese trostlose Gegend kam ein einsamer Wanderer, der seit Tagen keine Menschenseele zu Gesicht bekommen hatte. Pl\u00f6tzlich jedoch stand eine junge Frau am Wegesrand, woraufhin er im Freudentaumel ausrief: \u201eDe alde Gott lebt noch!\u201c Eingedenk dieses Zeichens wurde ein Bildstock mit ebenjenen Worten aufgestellt, die man sp\u00e4ter auf den angrenzenden Weinberg \u00fcbertrug.<\/p>\n\n\n\n<p>Hin und wieder trifft man jedoch auch auf ganz und gar nicht christliche Namen, etwa die \u201eH\u00f6lle\u201c in Hochheim im Rheingau. Die S\u00fcdlage, noch dazu fr\u00fcherer Besitz des K\u00f6lner Domkapitels und des Erzbistums Mainz, birgt aber in seinem Tonmergelboden nicht den Zugang zum Reich des Teufels, sondern l\u00e4sst sich wieder einmal aus dem Mittelhochdeutschen herleiten, wo der Begriff \u201ehalda\u201c einen steilen Hang bezeichnete &#8211; gleiches gilt f\u00fcr den \u201eH\u00f6llenberg\u201c in Assmannshausen. Der \u201eH\u00f6llenpfad\u201c im pf\u00e4lzischen Gr\u00fcnstadt hingegen verweist quasi auf das Gegenteil dessen, was vor dem inneren Auge entsteht: kein dunkler Weg in den feurigen Pfuhl, sondern schlicht und einfach ein \u201eheller Pfad\u201c.&nbsp;<\/p>\n\n\n\n<p>Einen weiteren gro\u00dfen Fundus liefern neben R\u00f6mern und Katholizismus Tierbezeichnungen. H\u00e4ufig verband man mit diesen dionysische Kulte, ein Relikt aus heidnischer Zeit, von dem man sich offenbar gute Ernten versprach. Mythologisch besonders aufgeladen ist die Ziege, was sich in Namen wie \u201eGeispfad\u201c in Traben-Trarbach, der \u201eZickelgarten\u201c in Ockfen an der Saar und besonders in diversen Wortsch\u00f6pfungen mit \u201eBock\u201c zeigt. Aber auch der Hase galt als Fruchtbarkeitssymbol und hielt des \u00d6fteren als Namenspate her, etwa beim Neumagener \u201eH\u00e4schen\u201c oder dem \u201eHasenl\u00e4ufer\u201c in Brauneberg. Ebenfalls an der Mosel, in Zell n\u00e4mlich, erwartet uns die Gro\u00dflage \u201eSchwarze Katz\u201c, die es ihrerseits aber noch nicht allzu lange gibt: ihre Vorg\u00e4ngerlagen \u201ePetersborn\u201c und \u201eKapertchen\u201c wurden im 19. Jahrhundert nach dem Tier benannt, das der vor Ort gern und ausschweifend erz\u00e4hlten Begebenheit nach im Jahre 1863 einen Disput zwischen drei Aachener Weinh\u00e4ndlern entschied. Diese konnten sich sp\u00e4tabends nach einer ausgedehnten Probe nicht auf eines von drei F\u00e4ssern festlegen und diskutierten wild herum, als pl\u00f6tzlich die schwarze Katze des Hausbesitzers erschien und sich buckelnd just auf das Fass setzte, aus dem sich die M\u00e4nner gerade noch ein Gl\u00e4schen genehmigen wollten. Zum Erstaunen selbiger verteidigte sie den Tropfen durch Fauchen und Kratzen aufs \u00c4u\u00dferste, was die H\u00e4ndler darauf schlie\u00dfen lie\u00df, dass es sich hierbei ohne Zweifel um den besten Wein handeln m\u00fcsse. Sie kauften also den gesamten Bestand auf und vertrieben ihn zur\u00fcck in der Heimat unter dem Namen des Stubentigers, der sie unfreiwillig so gut beraten hatte.<\/p>\n\n\n\n<p>\u00c4hnlich popul\u00e4r ist ein anderes Tier in einem kleinen Ort an der pf\u00e4lzischen Weinstra\u00dfe: die Mu\u00dfbacher \u201eEselshaut\u201c entstand wohl dadurch, dass auf der Fl\u00e4che, auf der heute die Reben stehen, fr\u00fcher einmal Heu gem\u00e4ht wurde &#8211; dieser Vorgang hei\u00dft im Mittelhochdeutschen \u201ehouwet\u201c. Und da jenes Heu offenbar f\u00fcr die in nahen Stallungen gehaltenen kleinen Verwandten des Pferdes bestimmt war, haben wir es mit einer Esels-Heuernte als Ursprung zu tun.&nbsp;<\/p>\n\n\n\n<p>Beim \u201eSaumagen\u201c in Kallstadt hingegen m\u00fcssen wir nicht allzu lang in der Sprachwissenschaft umherirren, um zum Ursprung zu gelangen: die Parzelle hat, so wird sicher irgendwann einmal jemanden beim Blick auf eine Karte der Region aufgefallen sein, schlicht sackartige Umrisse und gemahnte daher wohl an die pf\u00e4lzische Spezialit\u00e4t. Einen ebenso trivialen Ursprung hat \u00fcbrigens die Oberbergener \u201eBa\u00dfgeige\u201c am Kaiserstuhl.<\/p>\n\n\n\n<p>Oft tauchen neben Haus- und Nutztieren auch durchaus seltsame Fabelwesen auf: die \u201eMeerspinne\u201c in Gimmeldingen etwa. Mitnichten ist aber ein achtbeiniges Monster der Nordsee entstiegen und hat sich dreist in der Pfalz niedergelassen, vielmehr ist die Hanglage schon immer relativ steil gewesen und erforderte aus diesem Grund in vorindustrieller Zeit ein weiteres Zugpferd. Aus dem Einsp\u00e4nner wurde so ein Mehrsp\u00e4nner und dieser im Dialekt der Gegend irgendwann einfach als Lagenbezeichnung \u00fcbernommen. Eine alternative, aber leider deutlich trockenere Herleitung besagt, dass es sich lediglich um eine zusammengesetzte Ortsbeschreibung aus \u201emer\u201c, was vor einigen Jahrhunderten ein Wasserloch meinte, und \u201ew\u00fcnne\u201c handelt, was wiederum f\u00fcr ein Weideland meint. Ein Weinberg am Wiesent\u00fcmpel also.&nbsp;<\/p>\n\n\n\n<p>Eine der bekanntesten Lagen der Pfalz, das Forster \u201eUngeheuer\u201c l\u00e4sst sich wohl genauso wenig auf eine blutr\u00fcnstige mittelalterliche Sage zur\u00fcckf\u00fchren, sondern r\u00fchrt wahrscheinlich daher, dass ein Beamter aus dem nahen Deidesheim im 17. Jahrhundert so hie\u00df: Johann Adam Ungeheuer. Ebenso profan geht es beim Wachenheimer \u201eGer\u00fcmpel\u201c zu: diese Lage ist nicht etwa besonders ungepflegt, sondern hatte in grauer Vorzeit lediglich Vorbesitzer, die sich Grympel nannten.&nbsp;<\/p>\n\n\n\n<p>Ob nun die \u201eGoldgrube\u201c in Bockenheim (Pfalz) etwas damit zu tun hat, dass hier besonders hochpreisiger Wein angebaut wird, soll zum Schluss augenzwinkernd offengelassen werden, klar ist aber: zu einem guten Tropfen gibt es in Deutschland h\u00e4ufig genug eine interessante Anekdote \u00fcber Land und Leute dazu, man muss zwischen zwei Gl\u00e4schen nur mal nachfragen.&nbsp;Text: Dario Sellmeier<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00dcber den Ursprung der Namen der deutschen Weinbergslagen Beim St\u00f6bern am Weinregal schon mal verbl\u00fcfft das Etikett einige Zentimeter n\u00e4her an die Augen gehalten und nochmal gelesen? Dann haben Sie sicherlich gerade ein unerwartet g\u00fcnstiges Schn\u00e4ppchen gemacht &#8211; was Ihnen geg\u00f6nnt sei, aber leider nicht allzu h\u00e4ufig geschehen wird &#8211; oder aber Sie sind auf &#8230; <a title=\"Bedeutungsschwanger: Die Namen der Lagen\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/\" aria-label=\"Mehr dazu unter Bedeutungsschwanger: Die Namen der Lagen\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":143242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[2681,99,120,2682,200,2683,123,2684,2685],"post_folder":[],"class_list":["post-103727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weinwissen","tag-alde-gott","tag-baden","tag-deutschland","tag-hoelle","tag-mosel","tag-namesgebung-von-weinbergen","tag-pfalz","tag-ungeheuer","tag-weinlagen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bedeutungsschwanger: Die Namen der Lagen - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bedeutungsschwanger: Die Namen der Lagen - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"\u00dcber den Ursprung der Namen der deutschen Weinbergslagen Beim St\u00f6bern am Weinregal schon mal verbl\u00fcfft das Etikett einige Zentimeter n\u00e4her an die Augen gehalten und nochmal gelesen? Dann haben Sie sicherlich gerade ein unerwartet g\u00fcnstiges Schn\u00e4ppchen gemacht &#8211; was Ihnen geg\u00f6nnt sei, aber leider nicht allzu h\u00e4ufig geschehen wird &#8211; oder aber Sie sind auf ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-04T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-01T14:17:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/Weingeschichten.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"389\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Bedeutungsschwanger: Die Namen der Lagen\",\"datePublished\":\"2021-02-04T16:00:00+00:00\",\"dateModified\":\"2023-03-01T14:17:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/\"},\"wordCount\":1458,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Weingeschichten.jpg\",\"keywords\":[\"Alde Gott\",\"Baden\",\"Deutschland\",\"H\u00f6lle\",\"Mosel\",\"Namesgebung von Weinbergen\",\"Pfalz\",\"Ungeheuer\",\"Weinlagen\"],\"articleSection\":[\"Weinwissen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/\",\"name\":\"Bedeutungsschwanger: Die Namen der Lagen - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Weingeschichten.jpg\",\"datePublished\":\"2021-02-04T16:00:00+00:00\",\"dateModified\":\"2023-03-01T14:17:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Weingeschichten.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Weingeschichten.jpg\",\"width\":389,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2021\\\/02\\\/bedeutungsschwanger-die-namen-der-lagen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bedeutungsschwanger: Die Namen der Lagen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bedeutungsschwanger: Die Namen der Lagen - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/","og_locale":"de_DE","og_type":"article","og_title":"Bedeutungsschwanger: Die Namen der Lagen - Unterwegs mit Weine &amp; Feinkost","og_description":"\u00dcber den Ursprung der Namen der deutschen Weinbergslagen Beim St\u00f6bern am Weinregal schon mal verbl\u00fcfft das Etikett einige Zentimeter n\u00e4her an die Augen gehalten und nochmal gelesen? Dann haben Sie sicherlich gerade ein unerwartet g\u00fcnstiges Schn\u00e4ppchen gemacht &#8211; was Ihnen geg\u00f6nnt sei, aber leider nicht allzu h\u00e4ufig geschehen wird &#8211; oder aber Sie sind auf ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2021-02-04T16:00:00+00:00","article_modified_time":"2023-03-01T14:17:43+00:00","og_image":[{"width":389,"height":500,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/Weingeschichten.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Bedeutungsschwanger: Die Namen der Lagen","datePublished":"2021-02-04T16:00:00+00:00","dateModified":"2023-03-01T14:17:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/"},"wordCount":1458,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/Weingeschichten.jpg","keywords":["Alde Gott","Baden","Deutschland","H\u00f6lle","Mosel","Namesgebung von Weinbergen","Pfalz","Ungeheuer","Weinlagen"],"articleSection":["Weinwissen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/","name":"Bedeutungsschwanger: Die Namen der Lagen - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/Weingeschichten.jpg","datePublished":"2021-02-04T16:00:00+00:00","dateModified":"2023-03-01T14:17:43+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/Weingeschichten.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/Weingeschichten.jpg","width":389,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2021\/02\/bedeutungsschwanger-die-namen-der-lagen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Bedeutungsschwanger: Die Namen der Lagen"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/Weingeschichten.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-qZ1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/103727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=103727"}],"version-history":[{"count":1,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/103727\/revisions"}],"predecessor-version":[{"id":195430,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/103727\/revisions\/195430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/143242"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=103727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=103727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=103727"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=103727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}