{"id":10622,"date":"2011-01-30T21:52:00","date_gmt":"2011-01-30T21:52:00","guid":{"rendered":"http:\/\/blog-fenske.local\/?p=10622"},"modified":"2011-01-30T21:52:00","modified_gmt":"2011-01-30T21:52:00","slug":"ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/","title":{"rendered":"Ananas-H\u00e4hnchenbrust-Walnuss-Tapa mit Stangenpfeffer, Chili, Limonensalz und Rapshonig."},"content":{"rendered":"<p>><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a href=\"http:\/\/4.bp.blogspot.com\/_jzrLfo08aHY\/TTYMLqLmZEI\/AAAAAAAAGL4\/ORf9Dm-sSgc\/s1600\/IMG_3934.JPG\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"240\" src=\"http:\/\/4.bp.blogspot.com\/_jzrLfo08aHY\/TTYMLqLmZEI\/AAAAAAAAGL4\/ORf9Dm-sSgc\/s320\/IMG_3934.JPG\" width=\"320\" \/><\/a><\/div>\n<div class=\"blogger-post-footer\">www.weine-feinkost.de<\/div>\n","protected":false},"excerpt":{"rendered":"<p>> www.weine-feinkost.de<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[65],"tags":[],"post_folder":[],"class_list":["post-10622","post","type-post","status-publish","format-standard","hentry","category-tapa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ananas-H\u00e4hnchenbrust-Walnuss-Tapa mit Stangenpfeffer, Chili, Limonensalz und Rapshonig. - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ananas-H\u00e4hnchenbrust-Walnuss-Tapa mit Stangenpfeffer, Chili, Limonensalz und Rapshonig. - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"&gt; www.weine-feinkost.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-30T21:52:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/4.bp.blogspot.com\/_jzrLfo08aHY\/TTYMLqLmZEI\/AAAAAAAAGL4\/ORf9Dm-sSgc\/s320\/IMG_3934.JPG\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/01\\\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/01\\\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Ananas-H\u00e4hnchenbrust-Walnuss-Tapa mit Stangenpfeffer, Chili, Limonensalz und Rapshonig.\",\"datePublished\":\"2011-01-30T21:52:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/01\\\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\\\/\"},\"wordCount\":11,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/01\\\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/4.bp.blogspot.com\\\/_jzrLfo08aHY\\\/TTYMLqLmZEI\\\/AAAAAAAAGL4\\\/ORf9Dm-sSgc\\\/s320\\\/IMG_3934.JPG\",\"articleSection\":[\"Viva la TAPA\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/01\\\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/01\\\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\\\/\",\"name\":\"Ananas-H\u00e4hnchenbrust-Walnuss-Tapa mit Stangenpfeffer, Chili, Limonensalz und Rapshonig. - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/01\\\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/01\\\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/4.bp.blogspot.com\\\/_jzrLfo08aHY\\\/TTYMLqLmZEI\\\/AAAAAAAAGL4\\\/ORf9Dm-sSgc\\\/s320\\\/IMG_3934.JPG\",\"datePublished\":\"2011-01-30T21:52:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/01\\\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/01\\\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/01\\\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\\\/#primaryimage\",\"url\":\"http:\\\/\\\/4.bp.blogspot.com\\\/_jzrLfo08aHY\\\/TTYMLqLmZEI\\\/AAAAAAAAGL4\\\/ORf9Dm-sSgc\\\/s320\\\/IMG_3934.JPG\",\"contentUrl\":\"http:\\\/\\\/4.bp.blogspot.com\\\/_jzrLfo08aHY\\\/TTYMLqLmZEI\\\/AAAAAAAAGL4\\\/ORf9Dm-sSgc\\\/s320\\\/IMG_3934.JPG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/01\\\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ananas-H\u00e4hnchenbrust-Walnuss-Tapa mit Stangenpfeffer, Chili, Limonensalz und Rapshonig.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ananas-H\u00e4hnchenbrust-Walnuss-Tapa mit Stangenpfeffer, Chili, Limonensalz und Rapshonig. - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/","og_locale":"de_DE","og_type":"article","og_title":"Ananas-H\u00e4hnchenbrust-Walnuss-Tapa mit Stangenpfeffer, Chili, Limonensalz und Rapshonig. - Unterwegs mit Weine &amp; Feinkost","og_description":"> www.weine-feinkost.de","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2011-01-30T21:52:00+00:00","og_image":[{"url":"http:\/\/4.bp.blogspot.com\/_jzrLfo08aHY\/TTYMLqLmZEI\/AAAAAAAAGL4\/ORf9Dm-sSgc\/s320\/IMG_3934.JPG","type":"","width":"","height":""}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Ananas-H\u00e4hnchenbrust-Walnuss-Tapa mit Stangenpfeffer, Chili, Limonensalz und Rapshonig.","datePublished":"2011-01-30T21:52:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/"},"wordCount":11,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/#primaryimage"},"thumbnailUrl":"http:\/\/4.bp.blogspot.com\/_jzrLfo08aHY\/TTYMLqLmZEI\/AAAAAAAAGL4\/ORf9Dm-sSgc\/s320\/IMG_3934.JPG","articleSection":["Viva la TAPA"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/","name":"Ananas-H\u00e4hnchenbrust-Walnuss-Tapa mit Stangenpfeffer, Chili, Limonensalz und Rapshonig. - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/#primaryimage"},"thumbnailUrl":"http:\/\/4.bp.blogspot.com\/_jzrLfo08aHY\/TTYMLqLmZEI\/AAAAAAAAGL4\/ORf9Dm-sSgc\/s320\/IMG_3934.JPG","datePublished":"2011-01-30T21:52:00+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/#primaryimage","url":"http:\/\/4.bp.blogspot.com\/_jzrLfo08aHY\/TTYMLqLmZEI\/AAAAAAAAGL4\/ORf9Dm-sSgc\/s320\/IMG_3934.JPG","contentUrl":"http:\/\/4.bp.blogspot.com\/_jzrLfo08aHY\/TTYMLqLmZEI\/AAAAAAAAGL4\/ORf9Dm-sSgc\/s320\/IMG_3934.JPG"},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/01\/ananas-hahnchenbrust-walnuss-tapa-mit-stangenpfeffer-chili-limonensalz-und-rapshonig\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Ananas-H\u00e4hnchenbrust-Walnuss-Tapa mit Stangenpfeffer, Chili, Limonensalz und Rapshonig."}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-2Lk","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/10622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=10622"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/10622\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=10622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=10622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=10622"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=10622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}