{"id":10885,"date":"2011-09-24T16:59:00","date_gmt":"2011-09-24T16:59:00","guid":{"rendered":"http:\/\/blog-fenske.local\/?p=10885"},"modified":"2011-09-24T16:59:00","modified_gmt":"2011-09-24T16:59:00","slug":"chorizopuree-mit-bio-ei","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/","title":{"rendered":"Chorizop\u00fcree mit Bio Ei"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/2.bp.blogspot.com\/-dc_g4wCYTc4\/SuP22nBUIvI\/AAAAAAAAD8s\/A4wkDI_CpKQ\/s1600\/Blog+011.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/2.bp.blogspot.com\/-dc_g4wCYTc4\/SuP22nBUIvI\/AAAAAAAAD8s\/A4wkDI_CpKQ\/s320\/Blog+011.JPG\" alt=\"\" width=\"320\" height=\"240\" border=\"0\" \/><\/a><\/div>\n<div style=\"text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/4.bp.blogspot.com\/-IoqU0HhHto0\/TmZR2326QlI\/AAAAAAAAHzk\/iGNys6Ang1I\/s1600\/P1020090.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/4.bp.blogspot.com\/-IoqU0HhHto0\/TmZR2326QlI\/AAAAAAAAHzk\/iGNys6Ang1I\/s320\/P1020090.JPG\" alt=\"\" width=\"320\" height=\"240\" border=\"0\" \/><\/a><br \/>\nEin St\u00fcck spanische Paprikawurst und zwei Zwiebeln in W\u00fcrfel schneiden und in Oliven\u00f6l anbraten.<\/div>\n<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/4.bp.blogspot.com\/-ByievFQkEbQ\/TmZSEeEEe9I\/AAAAAAAAHzo\/vRuhaz2k2e0\/s1600\/P1020091.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/4.bp.blogspot.com\/-ByievFQkEbQ\/TmZSEeEEe9I\/AAAAAAAAHzo\/vRuhaz2k2e0\/s320\/P1020091.JPG\" alt=\"\" width=\"320\" height=\"240\" border=\"0\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Zirka zwei Kilo Kartoffeln sch\u00e4len und w\u00fcrfeln und in Salzwasser gar kochen.<\/div>\n<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/4.bp.blogspot.com\/-McqtBJUJhc8\/TmZSGj-Cv_I\/AAAAAAAAHzs\/LaY3Nn8ONV4\/s1600\/P1020092.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/4.bp.blogspot.com\/-McqtBJUJhc8\/TmZSGj-Cv_I\/AAAAAAAAHzs\/LaY3Nn8ONV4\/s320\/P1020092.JPG\" alt=\"\" width=\"320\" height=\"240\" border=\"0\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Ausd\u00e4mpfen.<\/div>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center;\"><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/4.bp.blogspot.com\/-lC13ZjWcBGw\/TmZSJBL0-1I\/AAAAAAAAHzw\/LsxNZDcIFds\/s1600\/P1020094.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/4.bp.blogspot.com\/-lC13ZjWcBGw\/TmZSJBL0-1I\/AAAAAAAAHzw\/LsxNZDcIFds\/s320\/P1020094.JPG\" alt=\"\" width=\"320\" height=\"240\" border=\"0\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Die Zwiebel- Chorizo- Mischung sch\u00f6n kross werden lassen.<\/div>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center;\"><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/--GBT5cURtXU\/TmZSLufyJ3I\/AAAAAAAAHz0\/m_wOBKXV2N8\/s1600\/P1020095.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/--GBT5cURtXU\/TmZSLufyJ3I\/AAAAAAAAHz0\/m_wOBKXV2N8\/s320\/P1020095.JPG\" alt=\"\" width=\"320\" height=\"240\" border=\"0\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Mit ein wenig frischer Milch die Kartoffeln kurz zerstampfen.<\/div>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center;\"><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-DgPCrWeJFoQ\/TmZSN3UTjdI\/AAAAAAAAHz4\/I9b8rI-LCuc\/s1600\/P1020096.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/-DgPCrWeJFoQ\/TmZSN3UTjdI\/AAAAAAAAHz4\/I9b8rI-LCuc\/s320\/P1020096.JPG\" alt=\"\" width=\"320\" height=\"240\" border=\"0\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Die Chorizo Mischung unter das P\u00fcree geben. Einen guten Schu\u00df Oliven\u00f6l hinzugeben.<\/div>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center;\"><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/3.bp.blogspot.com\/-28MkkbonqDU\/TmZSQYOpHhI\/AAAAAAAAHz8\/j1xjFQVLzfI\/s1600\/P1020097.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/-28MkkbonqDU\/TmZSQYOpHhI\/AAAAAAAAHz8\/j1xjFQVLzfI\/s320\/P1020097.JPG\" alt=\"\" width=\"320\" height=\"240\" border=\"0\" \/><\/a><\/div>\n<div style=\"text-align: center;\">\u00a0Ein Bioei genau 5 Minuten in kochendem Wasser kochen und sofort unter kaltem Wasser abschrecken.<\/div>\n<div style=\"text-align: center;\">Vorsichtig pellen und auf das P\u00fcree geben.<\/div>\n<div style=\"text-align: center;\">Eventuell mit Parmesan bestreuen und mit gutem Oliven\u00f6l betreufeln.<\/div>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center;\"><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-iVGzPnlufLQ\/TmZSS4VsGwI\/AAAAAAAAH0A\/CHfcDhh5YZI\/s1600\/P1020098.JPG\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/-iVGzPnlufLQ\/TmZSS4VsGwI\/AAAAAAAAH0A\/CHfcDhh5YZI\/s320\/P1020098.JPG\" alt=\"\" width=\"320\" height=\"240\" border=\"0\" \/><\/a><\/div>\n<div style=\"text-align: center;\">K\u00f6stliche spanische Hausmannskost!!<\/div>\n<div class=\"blogger-post-footer\">www.weine-feinkost.de<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ein St\u00fcck spanische Paprikawurst und zwei Zwiebeln in W\u00fcrfel schneiden und in Oliven\u00f6l anbraten. &nbsp; Zirka zwei Kilo Kartoffeln sch\u00e4len und w\u00fcrfeln und in Salzwasser gar kochen. &nbsp; Ausd\u00e4mpfen. &nbsp; Die Zwiebel- Chorizo- Mischung sch\u00f6n kross werden lassen. &nbsp; Mit ein wenig frischer Milch die Kartoffeln kurz zerstampfen. &nbsp; Die Chorizo Mischung unter das P\u00fcree &#8230; <a title=\"Chorizop\u00fcree mit Bio Ei\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/\" aria-label=\"Mehr dazu unter Chorizop\u00fcree mit Bio Ei\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":151762,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[17],"tags":[],"post_folder":[],"class_list":["post-10885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezepte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chorizop\u00fcree mit Bio Ei - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chorizop\u00fcree mit Bio Ei - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Ein St\u00fcck spanische Paprikawurst und zwei Zwiebeln in W\u00fcrfel schneiden und in Oliven\u00f6l anbraten. &nbsp; Zirka zwei Kilo Kartoffeln sch\u00e4len und w\u00fcrfeln und in Salzwasser gar kochen. &nbsp; Ausd\u00e4mpfen. &nbsp; Die Zwiebel- Chorizo- Mischung sch\u00f6n kross werden lassen. &nbsp; Mit ein wenig frischer Milch die Kartoffeln kurz zerstampfen. &nbsp; Die Chorizo Mischung unter das P\u00fcree ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-24T16:59:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/05\/picantje_van_fond.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/09\\\/chorizopuree-mit-bio-ei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/09\\\/chorizopuree-mit-bio-ei\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Chorizop\u00fcree mit Bio Ei\",\"datePublished\":\"2011-09-24T16:59:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/09\\\/chorizopuree-mit-bio-ei\\\/\"},\"wordCount\":116,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/09\\\/chorizopuree-mit-bio-ei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/picantje_van_fond.jpg\",\"articleSection\":[\"Rezepte\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/09\\\/chorizopuree-mit-bio-ei\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/09\\\/chorizopuree-mit-bio-ei\\\/\",\"name\":\"Chorizop\u00fcree mit Bio Ei - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/09\\\/chorizopuree-mit-bio-ei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/09\\\/chorizopuree-mit-bio-ei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/picantje_van_fond.jpg\",\"datePublished\":\"2011-09-24T16:59:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/09\\\/chorizopuree-mit-bio-ei\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/09\\\/chorizopuree-mit-bio-ei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/09\\\/chorizopuree-mit-bio-ei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/picantje_van_fond.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/picantje_van_fond.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2011\\\/09\\\/chorizopuree-mit-bio-ei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chorizop\u00fcree mit Bio Ei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chorizop\u00fcree mit Bio Ei - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/","og_locale":"de_DE","og_type":"article","og_title":"Chorizop\u00fcree mit Bio Ei - Unterwegs mit Weine &amp; Feinkost","og_description":"Ein St\u00fcck spanische Paprikawurst und zwei Zwiebeln in W\u00fcrfel schneiden und in Oliven\u00f6l anbraten. &nbsp; Zirka zwei Kilo Kartoffeln sch\u00e4len und w\u00fcrfeln und in Salzwasser gar kochen. &nbsp; Ausd\u00e4mpfen. &nbsp; Die Zwiebel- Chorizo- Mischung sch\u00f6n kross werden lassen. &nbsp; Mit ein wenig frischer Milch die Kartoffeln kurz zerstampfen. &nbsp; Die Chorizo Mischung unter das P\u00fcree ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2011-09-24T16:59:00+00:00","og_image":[{"width":240,"height":180,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/05\/picantje_van_fond.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Chorizop\u00fcree mit Bio Ei","datePublished":"2011-09-24T16:59:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/"},"wordCount":116,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/05\/picantje_van_fond.jpg","articleSection":["Rezepte"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/","name":"Chorizop\u00fcree mit Bio Ei - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/05\/picantje_van_fond.jpg","datePublished":"2011-09-24T16:59:00+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/05\/picantje_van_fond.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/05\/picantje_van_fond.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2011\/09\/chorizopuree-mit-bio-ei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Chorizop\u00fcree mit Bio Ei"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/05\/picantje_van_fond.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-2Pz","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/10885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=10885"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/10885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/151762"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=10885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=10885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=10885"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=10885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}