{"id":11051,"date":"2012-03-15T16:34:00","date_gmt":"2012-03-15T16:34:00","guid":{"rendered":"http:\/\/blog-fenske.local\/?p=11051"},"modified":"2012-03-15T16:34:00","modified_gmt":"2012-03-15T16:34:00","slug":"doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/","title":{"rendered":"Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df"},"content":{"rendered":"<p>><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a href=\"http:\/\/4.bp.blogspot.com\/-K_NfqBXYr2U\/Tx7W-pIcbsI\/AAAAAAAAI1s\/3IPOk6ntoa4\/s1600\/weinsinn_blog.jpg\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"218\" src=\"http:\/\/4.bp.blogspot.com\/-K_NfqBXYr2U\/Tx7W-pIcbsI\/AAAAAAAAI1s\/3IPOk6ntoa4\/s320\/weinsinn_blog.jpg\" width=\"320\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<style type=\"text\/css\"><!--   @page { margin: 2cm }   P { margin-bottom: 0.21cm }  --><\/style>\n<p><b>2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df<\/b><br \/>(Alk. 14%) Str\u00fcmpelbach W\u00fcrttemberg <\/p>\n<div style=\"font-weight: normal; margin-bottom: 0cm;\">Rote s\u00fc\u00dfe Kirschen, Brombeeren, etwas Cassis. Gew\u00fcrzaromen von mildem Pfeffer und Lorbeer, ein Hauch Anis, Nelke, etwas Kakao, zartbittere Schokolade, Lakritze; leicht blumig. Eine dezente Holznote, sanfte, fast s\u00fc\u00dfliche Tannine, gut eingebundene S\u00e4ure. Trotz viel Alkohol sanft, f\u00fcr einen Lemberger fast zu mild.<\/div>\n<div style=\"font-weight: normal; margin-bottom: 0cm;\">Er passt zur asiatischen K\u00fcche.<\/div>\n<div style=\"font-weight: normal; margin-bottom: 0cm;\"><i>(getrunken am 30. Dezember 2011)<\/i><\/div>\n<p><\/p>\n<div class=\"blogger-post-footer\">www.weine-feinkost.de<\/div>\n","protected":false},"excerpt":{"rendered":"<p>> &nbsp; 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df(Alk. 14%) Str\u00fcmpelbach W\u00fcrttemberg Rote s\u00fc\u00dfe Kirschen, Brombeeren, etwas Cassis. Gew\u00fcrzaromen von mildem Pfeffer und Lorbeer, ein Hauch Anis, Nelke, etwas Kakao, zartbittere Schokolade, Lakritze; leicht blumig. Eine dezente Holznote, sanfte, fast s\u00fc\u00dfliche Tannine, gut eingebundene S\u00e4ure. Trotz viel Alkohol sanft, f\u00fcr einen Lemberger fast zu mild. &#8230; <a title=\"Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/\" aria-label=\"Mehr dazu unter Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":141045,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[63],"tags":[],"post_folder":[],"class_list":["post-11051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"&gt; &nbsp; 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df(Alk. 14%) Str\u00fcmpelbach W\u00fcrttemberg Rote s\u00fc\u00dfe Kirschen, Brombeeren, etwas Cassis. Gew\u00fcrzaromen von mildem Pfeffer und Lorbeer, ein Hauch Anis, Nelke, etwas Kakao, zartbittere Schokolade, Lakritze; leicht blumig. Eine dezente Holznote, sanfte, fast s\u00fc\u00dfliche Tannine, gut eingebundene S\u00e4ure. Trotz viel Alkohol sanft, f\u00fcr einen Lemberger fast zu mild. ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-15T16:34:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/06\/weinsinn_blog2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"666\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/03\\\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/03\\\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df\",\"datePublished\":\"2012-03-15T16:34:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/03\\\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\\\/\"},\"wordCount\":82,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/03\\\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/weinsinn_blog2.jpg\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/03\\\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/03\\\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\\\/\",\"name\":\"Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/03\\\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/03\\\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/weinsinn_blog2.jpg\",\"datePublished\":\"2012-03-15T16:34:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/03\\\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/03\\\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/03\\\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/weinsinn_blog2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/weinsinn_blog2.jpg\",\"width\":666,\"height\":454},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/03\\\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/","og_locale":"de_DE","og_type":"article","og_title":"Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df - Unterwegs mit Weine &amp; Feinkost","og_description":"> &nbsp; 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df(Alk. 14%) Str\u00fcmpelbach W\u00fcrttemberg Rote s\u00fc\u00dfe Kirschen, Brombeeren, etwas Cassis. Gew\u00fcrzaromen von mildem Pfeffer und Lorbeer, ein Hauch Anis, Nelke, etwas Kakao, zartbittere Schokolade, Lakritze; leicht blumig. Eine dezente Holznote, sanfte, fast s\u00fc\u00dfliche Tannine, gut eingebundene S\u00e4ure. Trotz viel Alkohol sanft, f\u00fcr einen Lemberger fast zu mild. ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2012-03-15T16:34:00+00:00","og_image":[{"width":666,"height":454,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/06\/weinsinn_blog2.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df","datePublished":"2012-03-15T16:34:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/"},"wordCount":82,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/06\/weinsinn_blog2.jpg","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/","name":"Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/06\/weinsinn_blog2.jpg","datePublished":"2012-03-15T16:34:00+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/06\/weinsinn_blog2.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/06\/weinsinn_blog2.jpg","width":666,"height":454},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/03\/doros-weinsinn-2006-lemberger-r-qualitatswein-trocken-weingut-knaus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Doros WeinSinn: 2006 Lemberger R, Qualit\u00e4tswein trocken, Weingut Knau\u00df"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/06\/weinsinn_blog2.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-2Sf","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/11051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=11051"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/11051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/141045"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=11051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=11051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=11051"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=11051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}