{"id":125112,"date":"2022-02-13T12:00:00","date_gmt":"2022-02-13T11:00:00","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=125112"},"modified":"2023-03-14T19:02:39","modified_gmt":"2023-03-14T18:02:39","slug":"naturwein-wieviel-natur-steckt-im-wein","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/","title":{"rendered":"Naturwein \u2013 Wieviel Natur steckt im Wein?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Was ist Naturwein und was macht ihn aus?&nbsp;<\/h2>\n\n\n\n<p>Der Naturwein oder auch Natural ist eine besondere Art von Wein \u2013 denn er unterscheidet sich von konventionell hergestellten Tropfen. Aber warum hei\u00dft er dann Naturwein \u2013 er ist doch auch aus Trauben gemacht? Das ist vollkommen richtig. Allerdings sind in Europa viele Zusatzstoffe und Methoden zur Weinbereitung erlaubt. Dies entstand durch die technische Entwicklung und die Modernisierung der Winzerbetriebe. F\u00fcr eine m\u00f6glichst effiziente Weinherstellung stehen insbesondere industrielle Betriebe vor Herausforderungen, die sie mit modernen Methoden meistern wollen.<\/p>\n\n\n\n<p><strong>Das Problem: <\/strong>Sch\u00e4dlinge oder nat\u00fcrliche Klimaeinfl\u00fcsse wie Hagel k\u00f6nnen den Reben schaden.<\/p>\n\n\n\n<p><strong>Die L\u00f6sung<\/strong>: Pestizide, Plastikplanen und Vollernter.&nbsp;<\/p>\n\n\n\n<p>Da die Weinherstellung nicht mehr als ein chemischer Ablauf ist, war es oft ungewiss, ob der fertige Wein wirklich schmeckt. So griffen immer mehr Winzer auf <strong>Hilfsmittel <\/strong>zur\u00fcck, was uns zum heutigen Stand der Weinwelt bringt \u2013 alles im Sinne der Fehlervermeidung bei der Vinifizierung. Viele Zusatzstoffe wie zum Beispiel Schwefel konservieren den Wein, Reinzuchthefen bei der G\u00e4rung helfen. Nach und nach entfernte sich der Winzer von den konventionellen Weinbereitungsmethoden.&nbsp;<\/p>\n\n\n\n<p>Dazu kommt, dass <strong>viele Zusatzstoffe und Produktionsabl\u00e4ufe nicht auf dem Etikett deklariert werden m\u00fcssen<\/strong>. Das sorgt beim Endverbraucher f\u00fcr Unwissenheit.<\/p>\n\n\n\n<p>Schon lange wird der Markt von <strong>Industrieweinen <\/strong>dominiert. Ziel hierbei ist es, m\u00f6glichst gro\u00dfe Mengen zu einem niedrigen Preis herzustellen und zu vermarkten. Dabei d\u00fcrfen leider auch<strong> giftige Stoffe, Tierprodukte und chemische Substanzen<\/strong> zugesetzt werden \u2013 nat\u00fcrlich nur nach gesetzlichem Mindestma\u00df.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Naturwein &#8211; ein Wein ohne Zus\u00e4tze?&nbsp;<\/h2>\n\n\n\n<p>\u201eWeniger ist mehr\u201c hat sich die Naturweinszene als Ziel gesetzt. Da es aber keine gesetzlichen Regelungen f\u00fcr Naturweine gibt, ist es schwer zu definieren was ihn ausmacht.&nbsp;<\/p>\n\n\n\n<p>Die Idee des Naturweins ist es, einen<strong> Wein mit m\u00f6glichst wenigen Eingriffen im Weinberg und im Keller herzustellen<\/strong>. Der Wein ist sich im Keller quasi selbst \u00fcberlassen. Daf\u00fcr wird auf Reinzuchthefen, Kohle, Kl\u00e4rung des Weines durch Eiwei\u00dfe, chemische Hilfsmittel wie Pestizide etc. bei der Herstellung verzichtet. Er soll so naturgetreu wie m\u00f6glich sein.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ver\u00e4nderung des Weins durch Hefen:&nbsp;<\/h3>\n\n\n\n<p>Verwendet der Winzer bei der Weinbereitung sogenannte Zuchthefen, die f\u00fcr die Produktion von Wein im Labor hergestellt werden, kann der genaue Ablauf der G\u00e4rung kontrolliert werden. Hefen sorgen daf\u00fcr, dass der Wein z.B. bestimmte Fruchtauspr\u00e4gungen hat. Bei der Naturweinherstellung wird auf <strong>\u201ewilde Hefen\u201c<\/strong> gesetzt. Diese sitzen auf der Traube im Weinberg und auch in der nat\u00fcrlichen Umgebung des Kellers.&nbsp;<\/p>\n\n\n\n<p>Bei dieser Art von Hefen ist es oft <strong>ungewiss<\/strong>, wie sie sich auf den Traubenmost auswirken; geschweige denn, ob genug vorhanden sind.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ver\u00e4nderung des Weins durch Filtration:<\/h3>\n\n\n\n<p>Bei der Filtration wird der Wein <strong>durch Eiwei\u00df oder mechanisch gekl\u00e4rt.<\/strong> Dabei ist es unumg\u00e4nglich, dem Wein keine Stoffe zu entziehen. Schwebeteilchen und Aromastoffe bleiben auf der Strecke und entziehen dem Wein wichtige Geschmacksaromen.&nbsp;<\/p>\n\n\n\n<p>Naturwinzer geben dem Wein mehr Ruhe und Zeit, damit sich Festteile absetzten k\u00f6nnen. Sie kl\u00e4ren den Wein absichtlich nicht, damit er seinen eigenen Charakter beh\u00e4lt.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Was haben Bio Weine und biodynamischer Weinbau damit zu tun?&nbsp;<\/h2>\n\n\n\n<p>F\u00fcr <strong>biozertifizierte Weine<\/strong> gelten nach EU-Recht bestimmte Gesetze. Damit m\u00fcssen Winzer Bedingungen erf\u00fcllen, um ihren Wein als \u201ebiologisch\u201c zu vermarkten. Der Erzeuger muss dann <strong>auf chemische Pflanzenschutzmittel, h\u00f6here Schwefelgehalte, Gentechnik und vieles weitere verzichten<\/strong>. Diese Ma\u00dfnahmen f\u00f6rdern einen umweltschonenden Weinanbau. Zur Kontrolle werden diese Regeln von \u00c4mtern \u00fcberpr\u00fcft, um die Sicherheit des Produktes zu gew\u00e4hren. Biologischer Anbau sch\u00fctzt die Umwelt und f\u00fchrt zu einer nachhaltigeren Landwirtschaft.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Weingut Weinreich &#8211; Rheinhessen<\/h3>\n\n\n\n<p>Das <a href=\"https:\/\/weinreich-wein.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Weingut Weinreich<\/a> ist bio-zertifiziert. Winzer Marc Weinreich verzichtet auf Zusatzstoffe, hohe Schwefelgehalte und Gentechnik. Mit der Ambition, einzigartige Weine zu erzeugen, geht der hohe Anspruch an die Qualit\u00e4t und Nat\u00fcrlichkeit der Weine einher. Nur im Einklang mit den nat\u00fcrlichen und urspr\u00fcnglichen Bedingungen der B\u00f6den, auf denen die Reben wachsen, lassen sich charakteristische Weine erzeugen. Ohne Sch\u00f6nungsmittel sowie gr\u00f6\u00dftenteils ohne Reinzuchthefen entstehen so die Weine, die am Ende die Handschrift des Winzers, aber auch der Herkunft tragen. Hier finden Sie unter anderem auch echte <a href=\"https:\/\/www.weine-feinkost.de\/shop\/Weinreich\/\" target=\"_blank\" rel=\"noreferrer noopener\">Naturweine von Marc Weinreich<\/a>.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><\/p>\n\n\n\n<p>Als <strong>biodynamisch <\/strong>wirtschaftende Weinerzeuger bezeichnet man jene, die ihr Land und Hof als Teil eines <strong>Kreislaufes <\/strong>sehen. Der Boden n\u00e4hrt die Reben, diese wiederum die Trauben. Auch wird dabei auf nat\u00fcrliche D\u00fcngemittel gesetzt, wie z.B. Mist von Tieren. Trester (Trauben nach der Pressung) werden wieder in den Kreislauf gebracht, indem sie im Weinberg verteilt werden. Biodynamische Winzer achten also noch mehr auf Nachhaltigkeit als bio-zertifizierte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Weingut Andres &#8211; Pfalz<\/h3>\n\n\n\n<p>Die beiden Br\u00fcder Michael und Thomas Andres bewirtschaften 15 Hektar Rebland rund um Deidesheim. Naturbelassenes arbeiten sowie ein absoluter Fokus auf Qualit\u00e4t steht bei den Arbeiten im Weinberg und Keller immer im Vordergrund. Sie arbeiten nicht nur \u00f6kologisch sondern auch biodynamisch. Dies bedeutet viel Arbeit und Beobachtung in den Weinbergen, um perfektes Traubenmaterial f\u00fcr die Ernte zu erlangen. Um den Boden fruchtbarer zu machen, gibt man Mist und Hornmistpr\u00e4parate. Hier finden Sie Weine aus biodynamischem Anbau vom <a href=\"https:\/\/www.weine-feinkost.de\/shop\/Weingut-Andres\/\" target=\"_blank\" rel=\"noreferrer noopener\">Weingut Andres<\/a>.<\/p>\n\n\n\n<p>Da diese Prinzipien dem des Naturweins schon sehr nahe kommen,<strong> arbeiten die meisten Winzer, die Naturweine produzieren, sowieso schon biologisch und biodynamisch.<\/strong>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wie schmeckt Naturwein?&nbsp;<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Aussehen:&nbsp;<\/h3>\n\n\n\n<p>Naturwein ist meistens etwas <strong>tr\u00fcb<\/strong>, da er als ungefilterter Wein auf den Markt kommt. Da er l\u00e4nger auf der Maische liegt, schimmern Wei\u00dfweine oft <strong>orange bis hellrosa<\/strong>. F\u00fcr viele Endverbraucher ist diese Farbe ungewohnt.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Geruch:&nbsp;<\/h3>\n\n\n\n<p>Naturweine riechen in den meisten F\u00e4llen muffig und etwas abgestanden \u2013 <strong>hefige <\/strong>Nuancen gesellen sich hinzu. Dieser Geruch kommt von dem Oxidationsprozess, den der Wein durchl\u00e4uft. Die Aromen wirken demnach oft unklar. Je nach Rebsorte kann der Naturwein sehr <strong>aromatisch und fruchtig<\/strong> riechen.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Geschmack:<\/h3>\n\n\n\n<p>Der Duft l\u00e4sst sich sehr gut auf den Geschmack \u00fcbertragen. Diese Art von Wein kann sowohl <strong>hohe als auch niedrige S\u00e4ure- und Zuckerwerte<\/strong> haben. Gleichzeitig schmecken die Aromen oft nicht klar, sondern eher diffus. Nebenbei k\u00f6nnen erdige und bittere Aromen am Gaumen auftauchen. Die sogenannten Prim\u00e4rfruchtnoten gehen dabei oftmals verloren.&nbsp;<\/p>\n\n\n\n<p>Allerdings ist der Unterschied zwischen Naturweinen und konventionellen Weinen in den letzten Jahren immer geringer geworden, da viele Winzer die Produktion von gutem Wein ohne Zusatzstoffe perfektionieren.&nbsp;<\/p>\n\n\n\n<p>Gerne empfehle ich Ihnen folgenden Naturwein als Einstieg: <a href=\"https:\/\/www.weine-feinkost.de\/shop\/Heinrich-Naked-white.html\" target=\"_blank\" rel=\"noreferrer noopener\">Heinrich Naked White<\/a><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.weine-feinkost.de\/shop\/Heinrich-Naked-white.html\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/02\/oesterreich_burgenland_heinrich_naked_white.jpg\" alt=\"\" class=\"wp-image-125147\" width=\"268\" height=\"402\"\/><\/a><figcaption>Heinrich Naked White<\/figcaption><\/figure><\/div>\n\n\n\n<p>Das Weingut <a href=\"https:\/\/www.heinrich.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">Heinrich<\/a> aus dem Burgenland in \u00d6sterreich ist spezialisiert auf Naturweine. Der Naked White ist eine der Einsteigercuv\u00e9es aus den Rebsorten Muskat, Chardonnay, Gr\u00fcner Veltliner, Neuburger, Weissburgunder und Welschriesling. Die Kellerei bewirtschaftet alle Weinberge organisch-biologisch und biodynamisch. Der Wein wurde spontan vergoren, durchlief einen biologischen S\u00e4ureabbau und reifte dann in gro\u00dfen Holzf\u00e4ssern f\u00fcr 14 Monate auf der Feinhefe. Ungefiltert und ohne Zugabe von Schwefel wurde er dann abgef\u00fcllt und zeigt sich mit grasigen Aromen sowie einem Duft nach frischem Heu in der Nase.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fazit \u2013 Lohnt es sich Naturwein zu probieren?&nbsp;<\/h2>\n\n\n\n<p>Neugierige Weintrinker k\u00f6nnen sich nach Beratung im Fachgesch\u00e4ft einen guten \u00dcberblick verschaffen. Jeder Naturwein kann anders schmecken, ist etwas besonderes und individuelles. Daher lohnt es sich in jedem Fall diese Erfahrung zu machen. Schauen Sie sich dazu gerne entweder in unserem <a href=\"https:\/\/www.weine-feinkost.de\/\">Online Shop<\/a> um oder besuchen Sie uns in unserem Ladengesch\u00e4ft in Wuppertal. Wir freuen uns auf Sie!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Jetzt Newsletter abonnieren und keinen Blog Beitrag mehr verpassen:<\/h3>\n\n\n<div class=\"wp-block-jetpack-subscriptions__supports-newline wp-block-jetpack-subscriptions\">\n\t\t<div>\n\t\t\t<div>\n\t\t\t\t<div>\n\t\t\t\t\t<p >\n\t\t\t\t\t\t<a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?post_type=post&#038;p=125112\" style=\"font-size: 16px;padding: 15px 23px 15px 23px;margin: 0; margin-left: 10px;border-radius: 0px;border-width: 1px; background-color: #113AF5; color: #FFFFFF; text-decoration: none; white-space: nowrap; margin-left: 0\">Anmelden<\/a>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-color has-background\" href=\"https:\/\/www.weine-feinkost.de\/shop\/\" style=\"border-radius:2px;background-color:#a52f2f;color:#fffffa\" target=\"_blank\" rel=\"noreferrer noopener\">Zum Shop<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-text-color\" href=\"https:\/\/www.weine-feinkost.de\/shop\/newsletter\" style=\"border-radius:2px;color:#a83535\" target=\"_blank\" rel=\"noreferrer noopener\">Weine&amp;Feinkost Newsletter<\/a><\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-social-links aligncenter has-large-icon-size is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-instagram  wp-block-social-link\"><a href=\"https:\/\/www.instagram.com\/weine_und_feinkost\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Weine&amp;Feinkost Instagram<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-facebook  wp-block-social-link\"><a href=\"https:\/\/www.facebook.com\/WeineFeinkostChristianFenske\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Weine&amp;Feinkost Facebook<\/span><\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Was ist Naturwein und was macht ihn aus?&nbsp; Der Naturwein oder auch Natural ist eine besondere Art von Wein \u2013 denn er unterscheidet sich von konventionell hergestellten Tropfen. Aber warum hei\u00dft er dann Naturwein \u2013 er ist doch auch aus Trauben gemacht? Das ist vollkommen richtig. Allerdings sind in Europa viele Zusatzstoffe und Methoden zur &#8230; <a title=\"Naturwein \u2013 Wieviel Natur steckt im Wein?\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/\" aria-label=\"Mehr dazu unter Naturwein \u2013 Wieviel Natur steckt im Wein?\">Weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":169887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[63,1],"tags":[2896,2541,2897,2898,2899,2710,2382,2900,174,2836],"post_folder":[],"class_list":["post-125112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-weinwissen","tag-bio-weine","tag-biodynamisch","tag-biologisch","tag-nachhaltig","tag-natur","tag-natural","tag-naturwein","tag-vin-nature","tag-wein","tag-weinwissen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Naturwein \u2013 Wieviel Natur steckt im Wein?<\/title>\n<meta name=\"description\" content=\"Wie unterscheidet sich Naturwein von Bio Weinen oder herk\u00f6mmlichen Weinen? Welche Hilfsmittel und Zusatzstoffe sind erlaubt und welche nicht?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Naturwein \u2013 Wieviel Natur steckt im Wein?\" \/>\n<meta property=\"og:description\" content=\"Wie unterscheidet sich Naturwein von Bio Weinen oder herk\u00f6mmlichen Weinen? Welche Hilfsmittel und Zusatzstoffe sind erlaubt und welche nicht?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-13T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-14T18:02:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/02\/weingut_claus_preisinger_burgenland_1-Kopie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Janus Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Janus Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/\"},\"author\":{\"name\":\"Janus Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/1961e2fa9870d64bea2fb8ce341edc01\"},\"headline\":\"Naturwein \u2013 Wieviel Natur steckt im Wein?\",\"datePublished\":\"2022-02-13T11:00:00+00:00\",\"dateModified\":\"2023-03-14T18:02:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/\"},\"wordCount\":1288,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/weingut_claus_preisinger_burgenland_1-Kopie.jpg\",\"keywords\":[\"Bio Weine\",\"biodynamisch\",\"Biologisch\",\"nachhaltig\",\"Natur\",\"Natural\",\"Naturwein\",\"Vin Nature\",\"Wein\",\"Weinwissen\"],\"articleSection\":{\"1\":\"Weinwissen\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/\",\"name\":\"Naturwein \u2013 Wieviel Natur steckt im Wein?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/weingut_claus_preisinger_burgenland_1-Kopie.jpg\",\"datePublished\":\"2022-02-13T11:00:00+00:00\",\"dateModified\":\"2023-03-14T18:02:39+00:00\",\"description\":\"Wie unterscheidet sich Naturwein von Bio Weinen oder herk\u00f6mmlichen Weinen? Welche Hilfsmittel und Zusatzstoffe sind erlaubt und welche nicht?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/weingut_claus_preisinger_burgenland_1-Kopie.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/weingut_claus_preisinger_burgenland_1-Kopie.jpg\",\"width\":640,\"height\":426},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/02\\\/naturwein-wieviel-natur-steckt-im-wein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Naturwein \u2013 Wieviel Natur steckt im Wein?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/1961e2fa9870d64bea2fb8ce341edc01\",\"name\":\"Janus Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-IMG_1664-96x96.jpg\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-IMG_1664-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-IMG_1664-96x96.jpg\",\"caption\":\"Janus Fenske\"},\"description\":\"Wein und Essen sind Emotionen, welche gerne geteilt werden m\u00f6chten.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/janus-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Naturwein \u2013 Wieviel Natur steckt im Wein?","description":"Wie unterscheidet sich Naturwein von Bio Weinen oder herk\u00f6mmlichen Weinen? Welche Hilfsmittel und Zusatzstoffe sind erlaubt und welche nicht?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/","og_locale":"de_DE","og_type":"article","og_title":"Naturwein \u2013 Wieviel Natur steckt im Wein?","og_description":"Wie unterscheidet sich Naturwein von Bio Weinen oder herk\u00f6mmlichen Weinen? Welche Hilfsmittel und Zusatzstoffe sind erlaubt und welche nicht?","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2022-02-13T11:00:00+00:00","article_modified_time":"2023-03-14T18:02:39+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/02\/weingut_claus_preisinger_burgenland_1-Kopie.jpg","type":"image\/jpeg"}],"author":"Janus Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Janus Fenske","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/"},"author":{"name":"Janus Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/1961e2fa9870d64bea2fb8ce341edc01"},"headline":"Naturwein \u2013 Wieviel Natur steckt im Wein?","datePublished":"2022-02-13T11:00:00+00:00","dateModified":"2023-03-14T18:02:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/"},"wordCount":1288,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/02\/weingut_claus_preisinger_burgenland_1-Kopie.jpg","keywords":["Bio Weine","biodynamisch","Biologisch","nachhaltig","Natur","Natural","Naturwein","Vin Nature","Wein","Weinwissen"],"articleSection":{"1":"Weinwissen"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/","name":"Naturwein \u2013 Wieviel Natur steckt im Wein?","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/02\/weingut_claus_preisinger_burgenland_1-Kopie.jpg","datePublished":"2022-02-13T11:00:00+00:00","dateModified":"2023-03-14T18:02:39+00:00","description":"Wie unterscheidet sich Naturwein von Bio Weinen oder herk\u00f6mmlichen Weinen? Welche Hilfsmittel und Zusatzstoffe sind erlaubt und welche nicht?","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/02\/weingut_claus_preisinger_burgenland_1-Kopie.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/02\/weingut_claus_preisinger_burgenland_1-Kopie.jpg","width":640,"height":426},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/02\/naturwein-wieviel-natur-steckt-im-wein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Naturwein \u2013 Wieviel Natur steckt im Wein?"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/1961e2fa9870d64bea2fb8ce341edc01","name":"Janus Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/cropped-IMG_1664-96x96.jpg","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/cropped-IMG_1664-96x96.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/cropped-IMG_1664-96x96.jpg","caption":"Janus Fenske"},"description":"Wein und Essen sind Emotionen, welche gerne geteilt werden m\u00f6chten.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/janus-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/02\/weingut_claus_preisinger_burgenland_1-Kopie.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-wxW","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/125112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=125112"}],"version-history":[{"count":1,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/125112\/revisions"}],"predecessor-version":[{"id":195811,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/125112\/revisions\/195811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/169887"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=125112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=125112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=125112"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=125112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}