{"id":125622,"date":"2022-04-13T11:00:00","date_gmt":"2022-04-13T09:00:00","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=125622"},"modified":"2023-03-19T10:32:52","modified_gmt":"2023-03-19T09:32:52","slug":"stockholm","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/","title":{"rendered":"Stockholmer Momente"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Nordische K\u00fcche und ein paar Prozente <\/h2>\n\n\n\n<div class=\"wp-block-cover has-custom-content-position is-position-top-left\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-125660\" alt=\"\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_1.jpg\" data-object-fit=\"cover\"\/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size\">Abendd\u00e4mmerung in Stockholm<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Das Bistro Oaxen Slip<\/strong><\/h2>\n\n\n\n<p class=\"has-drop-cap\">Magnus Ek und Agneta Green gr\u00fcndeten 1994 auf der Insel Oaxen das Restaurant Oaxen Sk\u00e4rg\u00e5rdskrog. Diese s\u00fcdlich von Stockholm liegende Sch\u00e4reninsel Restaurant wurde dann 2011 geschlossen, um sich neuen Herausforderungen zu stellen. Das beeindruckende Ergebnis wurde 2013 auf der Stockholmer Insel Djurg\u00e5rden vorgestellt.&nbsp;<\/p>\n\n\n\n<p>N\u00e4mlich das Gourmet Restaurant Oaxen Krog, das angeschlossene Bistro&nbsp;<strong>Oaxen Slip<\/strong>&nbsp;und ein Schiffhotel namens Prince van Orangi\u00ebn. Konzeptionell wird im Restaurant und im Bistro auf gro\u00dfe Nachhaltigkeit und lokale Produkte Wert gelegt, welche nach M\u00f6glichkeit sogar direkt auf der Insel angebaut werden.&nbsp;<\/p>\n\n\n\n<p>Im&nbsp;<strong>Oaxen Slip<\/strong>&nbsp;wird dabei eine moderne, skandinavische Bistro K\u00fcche serviert. Viele kleine Portionen sind hier bestellbar, die alle auch zum untereinander teilen in die Mitte des Tisches gestellt werden d\u00fcrfen und sollen. Wie eine gute Vesper, mit einer exzellent selektionierten Weinkarte, mundet dann letztendlich das Ergebnis.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:34.71885%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_2-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_2-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125658\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125658\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_2-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_2-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:30.56230%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_4.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_4.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_4.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125656\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125656\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_4.jpg\" data-width=\"640\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_4.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_3.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_3.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_3.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125657\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125657\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_3.jpg\" data-width=\"640\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_3.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:34.71885%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_11-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_11-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125649\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125649\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_11-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_11-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:26.49419%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_12.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_12.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125648\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125648\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_12.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_12.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:47.01163%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_10.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_10.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_10.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125650\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125650\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_10.jpg\" data-width=\"640\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_10.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:26.49419%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_9-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_9-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125651\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125651\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_9-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_9-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:37.02678%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_8.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_8.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_8.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125652\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125652\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_8.jpg\" data-width=\"640\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_8.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_7.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_7.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_7.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125653\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125653\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_7.jpg\" data-width=\"640\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_7.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_6.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_6.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_6.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125654\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125654\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_6.jpg\" data-width=\"640\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_6.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:62.97322%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_5-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_5-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125655\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125655\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_5-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Oaxen_Slip_5-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p><strong>Oaxen Slip<\/strong>, Beckholmsv\u00e4gen 26, 115 21 Stockholm, Schweden, Telefon: Telefon: +46 8 551 531 05, <a href=\"https:\/\/oaxen.com\/\">https:\/\/oaxen.com\/<\/a><\/p>\n\n\n\n<div class=\"wp-block-cover has-custom-content-position is-position-top-left\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-125672\" alt=\"\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_11-rotated.jpg\" data-object-fit=\"cover\"\/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size\">Die Markthalle \u00d6stermalms Saluhall<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">In der Markthalle bei Lisa Elmqvist<\/h2>\n\n\n\n<p class=\"has-drop-cap\">In einer Markthalle zu speisen geh\u00f6rt pers\u00f6nlich immer noch zu den ganz besonderen Highlights im Leben. Insbesondere, wenn es sich um so ein Schmuckst\u00fcck wie die Markthalle \u00d6stermalms Saluhall in Stockholm handelt. Erst vor kurzem renoviert und umgebaut, verf\u00fcgt diese pr\u00e4chtige Markthalle \u00fcber tolle St\u00e4nde mit herausragenden und h\u00fcbsch pr\u00e4sentierten Lebensmitteln jeglicher Couleur.<\/p>\n\n\n\n<p>Wie in vielen anderen Markthallen dieser Welt gibt es hier aber auch die M\u00f6glichkeit etwas Feines zu speisen. Das Restaurant <strong>Lisa Elmqvist<\/strong> ist so ein Ort, indem sich die G\u00e4ste auf tollen Fisch, Meeresfr\u00fcchte und Schalentiere freuen d\u00fcrfen. In Stockholm ist dieses Restaurant ein absolutes Muss. Da wo diese Produkte gehandelt werden kommen sie auch frischer als frisch in den Kochtopf oder in die Pfanne und dann auf die Teller. Ein Pl\u00e4doyer f\u00fcr mehr Orte dieser Gattung und das <strong>Lisa Elmqvist<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:26.49419%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_10-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125661\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125661\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_10-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_10-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:47.01163%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_2.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_2.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125665\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125665\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_2.jpg\" data-width=\"640\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_2.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:26.49419%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_9-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125662\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125662\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_9-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_9-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:63.96477%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_8.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_8.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125663\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125663\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_8.jpg\" data-width=\"640\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_8.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:36.03523%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_7-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125664\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125664\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_7-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_7-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:46.90519%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_6.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_6.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125669\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125669\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_6.jpg\" data-width=\"640\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_6.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_3-rotated-e1646672820342.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_3-rotated-e1646672820342.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125666\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125666\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_3-rotated-e1646672820342.jpg\" data-width=\"640\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_3-rotated-e1646672820342.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:53.09481%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_4-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125667\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125667\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_4-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_4-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_5.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_5.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125668\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125668\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_5.jpg\" data-width=\"640\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Lisa_Elmqvist_5.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/03\/Schweden_Stockholm_Lisa_Elmqvist_12.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/03\/Schweden_Stockholm_Lisa_Elmqvist_12.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125673\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125673\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/03\/Schweden_Stockholm_Lisa_Elmqvist_12.jpg\" data-width=\"640\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/03\/Schweden_Stockholm_Lisa_Elmqvist_12.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p><strong>Lisa Elmqvist<\/strong>, \u00d6stermalms Saluhall, \u00d6stermalmstorg 29, 114 46 Stockholm, Schweden, Telefon: Telefon: +46 8 553 404 00, <a href=\"https:\/\/www.lisaelmqvist.se\/\">https:\/\/www.lisaelmqvist.se\/<\/a><\/p>\n\n\n\n<div class=\"wp-block-cover is-light has-custom-content-position is-position-top-left\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-125644\" alt=\"\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_2-rotated.jpg\" data-object-fit=\"cover\"\/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size\">KNARKUS Cider: &#8222;I don&#8217;t fill bottles. I empty them.&#8220;<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Lebendige Weine  und kleine Happen in der Savant Bar &#8211; Kaffe &amp; Vin<\/h2>\n\n\n\n<p class=\"has-drop-cap\">Es gibt solche und solche Weinbars. Die spannendsten dieser lokalen Treffpunkte sind f\u00fcr mich die Art von Weinbars, wo ausgesuchte Naturweine ausgeschenkt werden und wo es auch noch die eine oder andere Kleinigkeit zu essen gibt. Die&nbsp;<strong>Savant Bar<\/strong>&nbsp;in Stockholm geh\u00f6rt genau in diese Kategorie.<\/p>\n\n\n\n<p>Der Eigent\u00fcmer der Savant Bar produziert sogar noch vor den Toren Stockholms einen eigenen leckeren Cider und scheint auch genau das richtige H\u00e4ndchen f\u00fcr die Auswahl spannender Weine zu haben. Auch der Koch, der hier in der K\u00fcche werkelt, und strahlend seine einfachen, aber extrem leckeren Kreationen direkt zu den paar Pl\u00e4tzen dieses lukullischen Hotspots man\u00f6vriert, kann nur in den h\u00f6chsten T\u00f6nen gelobt werden. Ein lebendiger Ort, wie seine Produkte, wo es sehr viel zu entdecken gibt, diskutiert werden darf und nat\u00fcrlich auch viel gelacht wird. Hier ist alles auf die Nat\u00fcrlichkeit des Seins abgestimmt.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:36.03523%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_3-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_3-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125643\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125643\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_3-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_3-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:63.96477%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_8.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_8.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_8.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125638\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125638\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_8.jpg\" data-width=\"640\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_8.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:20.94802%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_6-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_6-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125640\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125640\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_6-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_6-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:37.15595%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_5.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_5.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_5.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"125641\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125641\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_5.jpg\" data-width=\"640\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_5.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:20.94802%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_4-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_4-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125642\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125642\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_4-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_4-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:20.94802%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_7-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_7-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125639\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125639\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_7-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_7-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p><strong>Savant Bar- Kaffe &amp; Vin<\/strong>, Tegn\u00e9rgatan 4, 113 58 Stockholm, Schweden, Telefon: +46 76 609 86 07, <a href=\"https:\/\/www.savantbar.se\/\">https:\/\/www.savantbar.se\/<\/a><\/p>\n\n\n\n<div class=\"wp-block-cover\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-125637\" alt=\"\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_9-rotated.jpg\" data-object-fit=\"cover\"\/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">F\u00fcr Nachtschw\u00e4rmer noch kurz in die H\u00f6rno Gin Bar<\/h2>\n\n\n\n<p class=\"has-drop-cap\">Noch Lust auf einen oder zwei Absacker? Daf\u00fcr ist die H\u00f6rno Gin Bar in der schwedischen Hauptstadt genau die richtige St\u00e4tte! Schon 2011 vor dem ganzen Gin Hype gegr\u00fcndet geh\u00f6rt der H\u00f6rno Gin anerkannter Weise zu den besten Gins der Welt, hat unz\u00e4hlige Auszeichnungen eingeheimst und bietet in der Bar f\u00fcr Gin Liebhaber, Cocktailfans und Nachtschw\u00e4rmer genau die richtigen Getr\u00e4nke, um einen sch\u00f6nen Abend in Stockholm genussvoll abschliessen zu k\u00f6nnen.&nbsp;&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:25.00000%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_6-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_6-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125631\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125631\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_6-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_6-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:25.00000%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_4-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_4-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125633\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125633\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_4-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_4-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:25.00000%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_1.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_1.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125630\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125630\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_1.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_1.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:25.00000%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_5-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_5-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125632\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125632\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_5-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_5-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_3-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_3-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125634\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125634\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_3-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_3-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_2-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_2-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"125635\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=125635\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_2-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Hernoe_Gin_Bar_2-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p><strong>H\u00f6rno Gin Bar<\/strong>, Hornsgatan 1, 118 46 Stockholm, Schweden, Telefon: Telefon: +46 73 095 90 00, <a href=\"https:\/\/hernogin.com\/\">https:\/\/hernogin.com\/<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Jetzt Newsletter abonnieren und keinen Blog Beitrag mehr verpassen:<\/h3>\n\n\n<div class=\"wp-block-jetpack-subscriptions__supports-newline wp-block-jetpack-subscriptions\">\n\t\t<div>\n\t\t\t<div>\n\t\t\t\t<div>\n\t\t\t\t\t<p >\n\t\t\t\t\t\t<a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?post_type=post&#038;p=125622\" style=\"font-size: 16px;padding: 15px 23px 15px 23px;margin: 0; margin-left: 10px;border-radius: 0px;border-width: 1px; background-color: #113AF5; color: #FFFFFF; text-decoration: none; white-space: nowrap; margin-left: 0\">Anmelden<\/a>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-7e5fce0a wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-color has-background wp-element-button\" href=\"https:\/\/www.weine-feinkost.de\/shop\/\" style=\"border-radius:2px;color:#fffffa;background-color:#a52f2f\" target=\"_blank\" rel=\"noreferrer noopener\">Zum Shop<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-text-color wp-element-button\" href=\"https:\/\/www.weine-feinkost.de\/shop\/newsletter\" style=\"border-radius:2px;color:#a83535\" target=\"_blank\" rel=\"noreferrer noopener\">Weine&amp;Feinkost Newsletter<\/a><\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-social-links aligncenter has-large-icon-size is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-instagram  wp-block-social-link\"><a href=\"https:\/\/www.instagram.com\/weine_und_feinkost\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Weine&amp;Feinkost Instagram<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-facebook  wp-block-social-link\"><a href=\"https:\/\/www.facebook.com\/WeineFeinkostChristianFenske\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Weine&amp;Feinkost Facebook<\/span><\/a><\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nordische K\u00fcche und ein paar Prozente Das Bistro Oaxen Slip Magnus Ek und Agneta Green gr\u00fcndeten 1994 auf der Insel Oaxen das Restaurant Oaxen Sk\u00e4rg\u00e5rdskrog. Diese s\u00fcdlich von Stockholm liegende Sch\u00e4reninsel Restaurant wurde dann 2011 geschlossen, um sich neuen Herausforderungen zu stellen. Das beeindruckende Ergebnis wurde 2013 auf der Stockholmer Insel Djurg\u00e5rden vorgestellt.&nbsp; N\u00e4mlich das &#8230; <a title=\"Stockholmer Momente\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/\" aria-label=\"Mehr dazu unter Stockholmer Momente\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":170054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[13,40],"tags":[71,2940,2941,2942,73,518,519],"post_folder":[],"class_list":["post-125622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-restaurants","category-schweden","tag-bar","tag-hoerno-gin-bar","tag-lisa-elmqvist","tag-oaxen-slip","tag-restaurant","tag-schweden","tag-stockholm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stockholmer Momente - Unterwegs mit Weine &amp; Feinkost %<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stockholmer Momente - Unterwegs mit Weine &amp; Feinkost %\" \/>\n<meta property=\"og:description\" content=\"Nordische K\u00fcche und ein paar Prozente Das Bistro Oaxen Slip Magnus Ek und Agneta Green gr\u00fcndeten 1994 auf der Insel Oaxen das Restaurant Oaxen Sk\u00e4rg\u00e5rdskrog. Diese s\u00fcdlich von Stockholm liegende Sch\u00e4reninsel Restaurant wurde dann 2011 geschlossen, um sich neuen Herausforderungen zu stellen. Das beeindruckende Ergebnis wurde 2013 auf der Stockholmer Insel Djurg\u00e5rden vorgestellt.&nbsp; N\u00e4mlich das ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-13T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-19T09:32:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Stockholmer Momente\",\"datePublished\":\"2022-04-13T09:00:00+00:00\",\"dateModified\":\"2023-03-19T09:32:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/\"},\"wordCount\":661,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_1.jpg\",\"keywords\":[\"Bar\",\"H\u00f6rno Gin Bar\",\"Lisa Elmqvist\",\"Oaxen Slip\",\"Restaurant\",\"Schweden\",\"Stockholm\"],\"articleSection\":[\"Restaurants\",\"Schweden\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/\",\"name\":\"Stockholmer Momente - Unterwegs mit Weine &amp; Feinkost %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_1.jpg\",\"datePublished\":\"2022-04-13T09:00:00+00:00\",\"dateModified\":\"2023-03-19T09:32:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_1.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/04\\\/stockholm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stockholmer Momente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stockholmer Momente - Unterwegs mit Weine &amp; Feinkost %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/","og_locale":"de_DE","og_type":"article","og_title":"Stockholmer Momente - Unterwegs mit Weine &amp; Feinkost %","og_description":"Nordische K\u00fcche und ein paar Prozente Das Bistro Oaxen Slip Magnus Ek und Agneta Green gr\u00fcndeten 1994 auf der Insel Oaxen das Restaurant Oaxen Sk\u00e4rg\u00e5rdskrog. Diese s\u00fcdlich von Stockholm liegende Sch\u00e4reninsel Restaurant wurde dann 2011 geschlossen, um sich neuen Herausforderungen zu stellen. Das beeindruckende Ergebnis wurde 2013 auf der Stockholmer Insel Djurg\u00e5rden vorgestellt.&nbsp; N\u00e4mlich das ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2022-04-13T09:00:00+00:00","article_modified_time":"2023-03-19T09:32:52+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_1.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Stockholmer Momente","datePublished":"2022-04-13T09:00:00+00:00","dateModified":"2023-03-19T09:32:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/"},"wordCount":661,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_1.jpg","keywords":["Bar","H\u00f6rno Gin Bar","Lisa Elmqvist","Oaxen Slip","Restaurant","Schweden","Stockholm"],"articleSection":["Restaurants","Schweden"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/","name":"Stockholmer Momente - Unterwegs mit Weine &amp; Feinkost %","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_1.jpg","datePublished":"2022-04-13T09:00:00+00:00","dateModified":"2023-03-19T09:32:52+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_1.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_1.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/04\/stockholm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Stockholmer Momente"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/03\/Schweden_Stockholm_Savant_Bar-Kaffe_und_Vin_1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-wGa","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/125622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=125622"}],"version-history":[{"count":1,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/125622\/revisions"}],"predecessor-version":[{"id":196136,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/125622\/revisions\/196136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/170054"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=125622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=125622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=125622"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=125622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}