{"id":126455,"date":"2022-05-15T12:00:00","date_gmt":"2022-05-15T10:00:00","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=126455"},"modified":"2023-03-15T15:58:00","modified_gmt":"2023-03-15T14:58:00","slug":"weinherstellung-der-weg-vom-weinberg-in-die-weinflasche","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/","title":{"rendered":"Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche"},"content":{"rendered":"\n<p>Wie wird Wein produziert und was ist daf\u00fcr an Arbeiten im Weinberg n\u00f6tig? Was muss ein Winzer tun, um das perfekte Traubenmaterial f\u00fcr den fertigen Wein zu gewinnen?&nbsp;<\/p>\n\n\n\n<p>Um die perfekte Arbeit als Vorbereitung f\u00fcr die kommende Lese zu leisten, sind unz\u00e4hlige Arbeitsabl\u00e4ufe notwendig. Angefangen mit dem Rebschnitt im Fr\u00fchling bis hin zur Selektion im fr\u00fchen Herbst geh\u00f6ren auch die Beobachtung und Einsch\u00e4tzung der Wetterverh\u00e4ltnisse zum Prozess, um die perfekte Traube mit gen\u00fcgend Mostgewicht zu ernten. Dabei kann der Winzer Einfluss auf die Entwicklung der Traube nehmen und so den Geschmack des Weines beeinflussen.&nbsp;<\/p>\n\n\n\n<p>Dabei ist die Qualit\u00e4t der Trauben von besonderer Wichtigkeit, vor allem wenn es an die Verarbeitung im Weinkeller geht. Eine gesunde und qualitativ hochwertige Traube kann der Winzer nur im Weinberg gewinnen. Was muss also alles bei der Arbeit im Weinberg passieren?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Reberziehung &#8211; Was die Rebe zum Wachsen braucht<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Die Anatomie der Rebe&nbsp;<\/h3>\n\n\n\n<p>Die Rebe besteht aus mehreren Teilen. Angefangen bei den Wurzeln dienen diese bekanntlich der Wasser- und N\u00e4hrstoffaufnahme. Danach folgt das mehrj\u00e4hrige Holz. Dieses besteht aus Stamm und Trieben, die mehr als ein Jahr alt sind. Das einj\u00e4hrige Holz besteht aus Trieben, die im Laufe des Winters verholzen. Aus den sogenannten Augen (Knospen) entsteht dann im n\u00e4chsten Jahr ein neuer Trieb. Die Rebe h\u00e4lt sich mit ihren \u201eRanken\u201c an nahegelegenen Rebst\u00fctzen fest.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/POV0583-1440x958.jpg\" alt=\"\" class=\"wp-image-126489\"\/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Umgebungsbedingungen<\/h3>\n\n\n\n<p>Die Umgebung der Trauben ist entscheidend f\u00fcr den sp\u00e4teren Weinstil. W\u00e4rme, Sonnenlicht, Wasser, Klima und Wetter wirken sich positiv oder negativ auf das Wachstum und die Arbeit im Weinberg aus. Damit die Rebe ordentlich wachsen kann und genug S\u00e4ure, Zucker und Aromen bildet, ist eine gute Photosynthese notwendig.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">W\u00e4rme und Sonnenlicht:&nbsp;<\/h4>\n\n\n\n<p>Die besten Lagen sind auf der Nordhalbkugel g\u00fcnstig Richtung <strong>S\u00fcd-Osten<\/strong> ausgerichtet. Die Trauben bekommen so mehr Stunden Sonnenlicht ab und k\u00f6nnen besser reifen. Wachsen die Weinberge zu nah am \u00c4quator, werden die Temperaturen zu hei\u00df. Diesen Temperaturen kann man allerdings mit H\u00f6henlagen entgegenwirken. Je h\u00f6her die Weinberge desto k\u00e4lter werden die Temperaturen.&nbsp;<\/p>\n\n\n\n<p><strong>Merke<\/strong>: Nah am \u00c4quator liegende L\u00e4nder wie z.B. Argentinien profitieren von hohen Lagen, welche einen k\u00fchlenden Einfluss auf die Reben haben.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Klima und Wetter<\/h4>\n\n\n\n<p><strong>Tag- und Nachttemperaturschwankungen <\/strong>sind ebenfalls entscheidend f\u00fcr die Qualit\u00e4t der Trauben. Kalte N\u00e4chte regulieren die S\u00e4ure in der Beere und verlangsamen den Abbau von Aromen. Weine aus solchen Gebieten schmecken frischer und knackiger als jene, die in einem sehr hei\u00dfen Klima reifen. Ein gewisser Anteil an S\u00e4ure ist wichtig f\u00fcr einen ausbalancierten Wein, da dieser sonst schnell &#8222;plump&#8220; schmecken kann.<\/p>\n\n\n\n<p>Warme Tage und N\u00e4chte lassen die Trauben besser reifen, was den Zuckergehalt in die H\u00f6he schnellen l\u00e4sst.&nbsp;<\/p>\n\n\n\n<p>Temperaturschwankungen werden durch gro\u00dfe Gew\u00e4sser in der N\u00e4he des Weinbergs verlangsamt, da diese sowohl W\u00e4rme in der Nacht als auch K\u00e4lte am Tag abgeben.&nbsp;<\/p>\n\n\n\n<p>Auch <strong>Nebel <\/strong>kann zur K\u00fchlung einer Weinparzelle f\u00fchren. So profitiert das ber\u00fchmte Weinbaugebiet \u201eMosel\u201c vom morgendlichen Nebel, welcher hin zur Mittagsstunde immer h\u00f6her klettert und sich zwischen den Rebzeilen absetzt.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/Mosel_saar_van_volxem_2.jpeg\" alt=\"\" class=\"wp-image-126459\" width=\"849\" height=\"563\"\/><figcaption class=\"wp-element-caption\">Morgendlicher Nebel an der Mosel<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Temperaturbedingte Risiken sind f\u00fcr jeden Winzer unberechenbar und k\u00f6nnen eine ganze Ernte zerst\u00f6ren. Um erst dem Fr\u00fchlingsfrost und dann dem hei\u00dfen Sommer entgegenzuwirken, setzten Winzer gerne folgende Hilfsmittel ein:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u00d6fen<\/strong> werden in Gebieten mit Fr\u00fchlingsfrost zum Schutz vor Nachtfrost aufgestellt. Die bekanntesten Bilder gibt es aus dem Anbaugebiet Burgund (Chablis und Cote d\u00b4OR).&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Windmaschinen<\/strong> werden anders als vielleicht angenommen auch gegen Frost eingesetzt. Dabei wird warme Luft angesogen und durch den Weinberg gepustet. Moderne Maschinen besitzen zus\u00e4tzlich auch Heizelemente.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sprinkleranlagen <\/strong>werden ebenfalls gegen Frost eingesetzt. Die Idee dahinter ist, mit normal temperiertem Wasser das Gefrieren der Knospen und Triebe zu verhindern.&nbsp;<\/li>\n\n\n\n<li><\/li>\n<\/ul>\n\n\n\n<p><strong>Merke<\/strong>: K\u00fchle Temperaturen regulieren die S\u00e4ure, w\u00e4hrend ein warmes Klima f\u00fcr einen erh\u00f6hten Zuckergehalt im Wein f\u00fchrt.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Bew\u00e4sserung<\/h4>\n\n\n\n<p>Die Rebe braucht neben Sonnenlicht und W\u00e4rme aber auch Wasser. In regenreichen Weinbaugebieten bekommen die Reben genug Wasser, welches durch die Wurzeln aufgenommen wird. In sehr warmen Gebieten verdunstet das Wasser schneller aus Boden und Bl\u00e4ttern. Daher setzten Winzer, sofern nicht verboten, gerne Bew\u00e4sserungssysteme ein:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tropfbew\u00e4sserung<\/strong>: Hierbei werden Schl\u00e4uche entlang der Rebzeilen gelegt, damit jede einzelne Rebe f\u00fcr sich bew\u00e4ssert werden kann. Diese Technik ist sehr kostspielig, hat aber den Vorteil, dass genau gesteuert werden kann, wieviel Wasser eine Rebe bekommt.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/IMG_1229-768x1024.jpg\" alt=\"\" class=\"wp-image-126461\" width=\"423\" height=\"564\"\/><figcaption class=\"wp-element-caption\">Weinberg auf Sizilien mit Tr\u00f6pfchenbew\u00e4sserung<\/figcaption><\/figure>\n<\/div>\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u00dcberflutungsbew\u00e4sserung<\/strong>: Die etwas g\u00fcnstigere Variante der \u00dcberflutung bietet sich haupts\u00e4chlich in flachen Gebieten an. Hierbei werden hohe Wassermassen durch die Rebzeilen geflutet.<br><\/li>\n\n\n\n<li><strong>Sprinkler<\/strong>: Sprinkler verbrauchen zwar viel Wasser und erzeugen eine hohe Feuchtigkeit im Weinberg, jedoch sind sie sehr effektiv was die Bew\u00e4sserung der Reben angeht.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Rebschnitt&nbsp;<\/h3>\n\n\n\n<p>Der Winzer kann <strong>durch den Rebschnitt die Menge der Trauben an den Trieben festlegen<\/strong>. Im Winterschnitt schneidet er daf\u00fcr die Augen (Knospen) zu \u2013 aus diesen entsteht im n\u00e4chsten Jahr der Trieb. Auch im Sommer sollte der Winzer sich um den Rebschnitt k\u00fcmmern. Dabei geht es haupts\u00e4chlich um die <strong>Laubdachpflege<\/strong>. Schneidet der Winzer viele Bl\u00e4tter weg, sorgt er f\u00fcr mehr Sonneneinstrahlung und eine bessere Luftzirkulation. Die Trauben k\u00f6nnen dann besser reifen und die Wahrscheinlichkeit von Pilzkrankheiten sinkt. Bl\u00e4tter k\u00f6nnen allerdings auch einen Schutz vor Sonne oder Regen bieten. L\u00e4sst der Winzer die Bl\u00e4tter an der Rebe h\u00e4ngen, so werden die darunter sitzenden Trauben vor Sonnenlicht gesch\u00fctzt. In zu warmen Gebieten profitieren die Trauben von solchen Methoden.&nbsp;<\/p>\n\n\n\n<p>Werden im Sommer bei warmen Temperaturen die Bl\u00e4tter der Rebe zur\u00fcckgeschnitten, wird die Zuckerproduktion der Pflanze vermehrt in die Traube gelenkt. So bekommt sie mehr Mostgewicht und werden schneller reif.&nbsp;<\/p>\n\n\n\n<p><strong>Merke<\/strong>: Ein rigoroser Schnitt des Laubdachs einer Rebe f\u00f6rdert die Zuckerproduktion und Reife der Traube, w\u00e4hrend ein dezenter Schnitt Schutz vor Regen und zu hoher Hitze bietet.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Laubdachpflege&nbsp;<\/h4>\n\n\n\n<p>Unterst\u00fctzungssysteme im Weinberg helfen dem Winzer, eine gezielte <strong>Laubdachpflege <\/strong>zu f\u00fchren und vereinfachen die Reberziehung. Daf\u00fcr werden Pfosten in jeder Rebzeile aufgestellt, welche mit Dr\u00e4hten waagerecht bespannt werden. An diesen Dr\u00e4hten werden dann die Triebe der Rebe befestigt. Die Sonneneinstrahlung kann so genau bestimmt werden, sodass z.B. in warmen Klimata die Beschattung durch das Laub f\u00fcr Schutz vor Verbrennungen sorgt.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Buscherziehung<\/h4>\n\n\n\n<p>W\u00e4hlt der Winzer eine sogenannte <strong>Buscherziehung<\/strong>, bei welcher die Reben nah am Boden wachsen, ist die Luftzirkulation sehr gering, wodurch sich Pilzkrankheiten schnell ausbreiten. Jedoch finden in warmen Weinanbaugebieten Buscherziehungen h\u00e4ufiger Gefallen als in k\u00fchlen und nassen Regionen. Das Entlauben der Bl\u00e4tter wird von Winzern trotzdem durchgef\u00fchrt, damit sich nicht zu viel Feuchtigkeit an der Rebe bildet. Arbeitet der Winzer mit Vollerntern sind Unterst\u00fctzungssysteme unumg\u00e4nglich, da gerade Reihen notwendig sind, um die Erntemaschinen zum Einsatz zu bringen. F\u00fcr eine Handlese sind beide Erziehungsmethoden geeignet.<br><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/IMG_9471-1365x1024.jpg\" alt=\"\" class=\"wp-image-126463\" width=\"412\" height=\"309\"\/><figcaption class=\"wp-element-caption\">Weinberg in Spanien mit Buscherziehung<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Wachstumszyklus der Rebe&nbsp;<\/h2>\n\n\n\n<p><strong>Winterruhe&nbsp;<\/strong><\/p>\n\n\n\n<p>Im Winter verholzen die Triebe der Rebe. Zudem fallen die Bl\u00e4tter ab und die N\u00e4hrstoffe sammeln sich f\u00fcr den kommenden Austrieb in der Wurzel.<br><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/herbst-0813-1440x962.jpg\" alt=\"\" class=\"wp-image-126491\" width=\"370\" height=\"247\"\/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p><strong>Austrieb&nbsp;<\/strong><\/p>\n\n\n\n<p>Sobald es im Fr\u00fchling w\u00e4rmer wird, fangen die Triebe und Augen an zu wachsen. Wann der Austrieb beginnt, kommt ganz auf die Rebsorte an.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fr\u00fchreifende Rebsorte: <a href=\"https:\/\/www.weine-feinkost.de\/shop\/Weingut-Andres-Spaetburgunder-vom-Kalkmergel.html\" target=\"_blank\" rel=\"noreferrer noopener\">Pinot Noir<\/a>&nbsp;<\/li>\n\n\n\n<li>Sp\u00e4treifende Rebsorte: <a href=\"https:\/\/www.weine-feinkost.de\/shop\/Caliterra-Cabernet-Sauvignon-Tributo.html\" target=\"_blank\" rel=\"noreferrer noopener\">Cabernet Sauvignon<\/a><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"126473\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/IMG_1080-1-768x1024.jpg\" alt=\"\" class=\"wp-image-126473\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"126492\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/POV5539-681x1024.jpg\" alt=\"\" class=\"wp-image-126492\"\/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Best\u00e4ubung&nbsp;<\/strong><\/p>\n\n\n\n<p>In der Regel sind die Reben, welche f\u00fcr den Weinbau verwendet werden, zwittrig. Das bedeutet sie k\u00f6nnen sich selbst best\u00e4uben &#8211; ganz <strong>ohne Insekten<\/strong>.&nbsp;<\/p>\n\n\n\n<p><strong>Blattwuchs&nbsp;<\/strong><\/p>\n\n\n\n<p>Kurz nach dem Austrieb folgt dann der Blattwuchs. Bl\u00e4tter und gr\u00fcne Bestandteile der Rebe f\u00f6rdern die Photosynthese und versorgen die Rebe mit Kohlenhydraten.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/POV5553-681x1024.jpg\" alt=\"\" class=\"wp-image-126493\" width=\"278\" height=\"417\"\/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\"><div class=\"wp-block-image is-style-rounded\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/IMG_1392-1-768x1024.jpg\" alt=\"\" class=\"wp-image-126471\" width=\"310\" height=\"413\"\/><figcaption class=\"wp-element-caption\">Weinbergsschnecken Sizilien<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p><strong>Bl\u00fcte&nbsp;<\/strong><\/p>\n\n\n\n<p>In dieser Zeit braucht die Rebe viel Sonnenlicht. Daf\u00fcr kann der Winzer das Laubdach verringern, um so mehr Sonneneinstrahlung zu gew\u00e4hrleisten. Nun bildet sich auch der Fruchtansatz, welcher der \u00dcbergang zur Beere ist. Nur best\u00e4ubte Bl\u00fcten entwickeln Beeren.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/POV5567-1440x958.jpg\" alt=\"\" class=\"wp-image-126494\" width=\"400\" height=\"265\"\/><\/figure>\n<\/div>\n\n\n<p><strong>V\u00e9raison und Reife der Beere&nbsp;<\/strong><\/p>\n\n\n\n<p>Die V\u00e9raison beschreibt den Moment, in dem die Traubenreife beginnt. Die anfangs kleinen gr\u00fcnen Beeren entwickeln sich nach und nach zu Trauben. F\u00fcr diesen Prozess saugt die Traube so viel Wasser auf wie sie kann. Gleichzeitig steigt auch der Zuckergehalt, Aromen bilden sich und Farbpigmente kommen zum Vorschein. Der Winzer kann nun alle Rebbl\u00e4tter entfernen und auch eine Vorselektion vornehmen, um die sp\u00e4tere Qualit\u00e4t des Weines zu verbessern. Ist er allerdings auf hohe Ertr\u00e4ge aus, l\u00e4sst er alle Beeren h\u00e4ngen.&nbsp;<\/p>\n\n\n\n<p><strong>Lese&nbsp;<\/strong><\/p>\n\n\n\n<p>Je nach Anbaugebiet wird im September\/Oktober geerntet. Zu viel Regen kann die Trauben aufplatzen lassen, woraus verw\u00e4sserte Aromen entstehen k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wein Sch\u00e4dlinge<\/h2>\n\n\n\n<p><strong>V\u00f6gel und Wild<\/strong><\/p>\n\n\n\n<p>V\u00f6gel fressen gerne Trauben und minimieren so den Ertrag. Durch Netze sch\u00fctzt der Winzer seine Reben auch vor Rehen, Wildschweinen und F\u00fcchsen.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/herbst-7405-1440x809.jpg\" alt=\"\" class=\"wp-image-126495\" width=\"488\" height=\"273\"\/><figcaption class=\"wp-element-caption\">Netze zum Schutz vor V\u00f6geln und S\u00e4ugetieren<\/figcaption><\/figure>\n<\/div>\n\n\n<p><strong>Insekten&nbsp;<\/strong><\/p>\n\n\n\n<p>Insekten greifen Trauben, Rebbl\u00e4tter und Stiele an. Durch das Spritzen von Insektiziden kann der Winzer gegen die Angreifer wirken.&nbsp;<\/p>\n\n\n\n<p><strong>Pilzkrankheiten&nbsp;<\/strong><\/p>\n\n\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/IMG_8329-1-768x1024.jpg\" alt=\"\" class=\"wp-image-126465\" width=\"167\" height=\"224\"\/><figcaption class=\"wp-element-caption\"><strong>Trauben, befallen mit Botrytis<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p><em>Falscher Mehltau<\/em> ist ein Pilz, der die komplette Rebe bef\u00e4llt. Befallene Teile der Rebe sollten entfernt oder mit Fungizid bespritzt werden. Allerdings verlieren dadurch die Trauben ihre Aromen und bekommen einen bitteren Nachgeschmack.&nbsp;<\/p>\n\n\n\n<p><em>Grauf\u00e4ule <\/em>wird von Botrytis Cinerea hervorgerufen. Botrytis ist ein Pilz, der sich durch kleine Poren in die Traube bohrt, welche dann ihr Wasser verliert und austrocknet. Jedoch kann Botrytis auch gew\u00fcnscht sein: M\u00f6chte der Winzer einen hochwertigen S\u00fc\u00dfwein wie zum Beispiel Tokaji oder Beerenauslesen produzieren, ist \u201eEdelf\u00e4ule\u201c (Botrytis) notwendig. Durch das Schrumpeln der Traube konzentriert sich auch der Zucker in der Traube und wird so konzentrierter.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/frankreich_languedoc_carrel_morillonrQ3UixADJrZXv.jpg\" alt=\"\" class=\"wp-image-126467\" width=\"188\" height=\"282\"\/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/www.weine-feinkost.de\/shop\/Morillon-blanc-by-Jeff-Carrel.html\" target=\"_blank\" rel=\"noreferrer noopener\">Morillon blanc by Jeff Carrel<\/a><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">Wie kann der Winzer gegen Pilzkrankheiten vorgehen? In Deutschland gibt es genaue Richtlinien, wann und wieviele Chemikalien ein Winzer pro Hektar einsetzen darf. Dazu geh\u00f6ren zum Beispiel Schwefel und Kupfer Pr\u00e4parate gegen Mehltau, Insektizide gegen Kleintiere und andere Fungizide, welche vor Pilzen und Angreifern sch\u00fctzen.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Im <strong>Biologischen Weinbau<\/strong> ist der Gebrauch von Fungiziden zwar erlaubt, aber stark eingeschr\u00e4nkt. So d\u00fcrfen nur wenige zugelassene Chemikalien in geringen Mengen gegen Krankheiten und Pilze eingesetzt werden.&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Traubenlese&nbsp;<\/h2>\n\n\n\n<p>Der alles entscheidende Moment im Herbst ist die Weinlese, bei welcher sich die Arbeit im Weinberg auszahlt. Dabei kann der Winzer entscheiden, ob er mit der Hand liest oder die einfachere Variante mit dem Vollernter w\u00e4hlt.&nbsp;<\/p>\n\n\n\n<p>Die <strong>Handlese <\/strong>ist wesentlich schonender f\u00fcr die Trauben und wird haupts\u00e4chlich f\u00fcr h\u00f6herwertigen Wein angewendet. Zudem ist die Selektionierung und das Entfernen von faulen Beeren direkt am Rebstock m\u00f6glich.&nbsp;<\/p>\n\n\n\n<p>Die <strong>Lese mit dem Vollernter <\/strong>hat genauso viele Vorteile wie auch Nachteile. Selbstverst\u00e4ndlich kommt der Winzer mit der Erntemaschine schneller durch den Weinberg. Zudem braucht er nur wenige bis keine Erntehelfer. Allerdings finden solche Maschinen nur in flachen Gebieten Anwendung, da die maschinelle Traubenlese an Steilh\u00e4ngen nicht m\u00f6glich ist. Der Traubenvollernter besteht aus einer Gabel an der eine R\u00fcttelmaschine befestigt ist. Mit zwei gro\u00dfen St\u00e4ben werden dann die Trauben \u201eabger\u00fcttelt\u201c. Das hat zum Nachteil, dass auch faule Beeren abfallen und sp\u00e4ter mit gepresst werden. Das verunreinigt den Wein und kann ihn bitter schmecken lassen.&nbsp;<\/p>\n\n\n\n<p><strong>Merke<\/strong>: Wichtig f\u00fcr den Winzer ist, dass es bei der Lese nicht regnet, da die Trauben sonst aufplatzen k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"126497\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/herbst-9729-684x1024.jpg\" alt=\"\" class=\"wp-image-126497\"\/><figcaption class=\"wp-element-caption\">Handlese<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"126501\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/herbst-5910-1-684x1024.jpg\" alt=\"\" class=\"wp-image-126501\"\/><figcaption class=\"wp-element-caption\">Handlese<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"126498\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/herbst-6145-1440x960.jpg\" alt=\"\" class=\"wp-image-126498\"\/><figcaption class=\"wp-element-caption\">Abladung der Trauben<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"126499\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/herbst-6116-1440x960.jpg\" alt=\"\" class=\"wp-image-126499\"\/><figcaption class=\"wp-element-caption\">Vollernter<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Die Arbeit im Weinberg in K\u00fcrze<\/h2>\n\n\n\n<p>Die Arbeit des Winzers im Weinberg erfordert wahres Feingef\u00fchl und Kennerwissen, um eine gute Grundlage f\u00fcr die weitere Weinverarbeitung zu schaffen. Vor der Kultivierung muss erst einmal erwogen werden: Welche Rebsorte passt zu den auf meinem Weinberg vorhandenen <strong>Umweltbedingungen hinsichtlich Licht, Klima und Bew\u00e4sserung<\/strong>? Nach der Entscheidung f\u00fcr und Anpflanzung von einer Rebsorte kann ein Weinberg jedoch nicht auf sich allein gestellt bleiben &#8211; denn die Reben bed\u00fcrfen zweimal im Jahr eines <strong>Rebschnitts<\/strong>, um sich bestm\u00f6glich zu entfalten und m\u00fcssen ggf. <strong>vor Sch\u00e4dlingen gesch\u00fctzt<\/strong> werden. Hat das gut geklappt, steht im Herbst die <strong>Weinlese<\/strong> an, welche maschinell oder h\u00e4ndisch vorgenommen werden kann.&nbsp;<br><strong>Bis zu diesem Zeitpunkt spielt sich die ganze Arbeit im Weinberg ab<\/strong>. Anschlie\u00dfend geht es f\u00fcr die Trauben in den Winzerkeller, um dort gekeltert zu werden. Die Weinbergsarbeit ist nur ein kleiner Teil zum fertigen Produkt \u201eWein\u201c. Lesen Sie gerne im n\u00e4chsten Blogbeitrag alles rund um die Kellerarbeit eines Winzers und wie sich der Wein dort ver\u00e4ndert.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Jetzt Newsletter abonnieren und keinen Blog Beitrag mehr verpassen:<\/h3>\n\n\n<div class=\"wp-block-jetpack-subscriptions__supports-newline wp-block-jetpack-subscriptions\">\n\t\t<div>\n\t\t\t<div>\n\t\t\t\t<div>\n\t\t\t\t\t<p >\n\t\t\t\t\t\t<a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?post_type=post&#038;p=126455\" style=\"font-size: 16px;padding: 15px 23px 15px 23px;margin: 0; margin-left: 10px;border-radius: 0px;border-width: 1px; background-color: #113AF5; color: #FFFFFF; text-decoration: none; white-space: nowrap; margin-left: 0\">Anmelden<\/a>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-7e5fce0a wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-color has-background wp-element-button\" href=\"https:\/\/www.weine-feinkost.de\/shop\/\" style=\"border-radius:2px;color:#fffffa;background-color:#a52f2f\" target=\"_blank\" rel=\"noreferrer noopener\">Zum Shop<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--3\"><a class=\"wp-block-button__link has-text-color wp-element-button\" href=\"https:\/\/www.weine-feinkost.de\/shop\/newsletter\" style=\"border-radius:2px;color:#a83535\" target=\"_blank\" rel=\"noreferrer noopener\">Weine&amp;Feinkost Newsletter<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wie wird Wein produziert und was ist daf\u00fcr an Arbeiten im Weinberg n\u00f6tig? Was muss ein Winzer tun, um das perfekte Traubenmaterial f\u00fcr den fertigen Wein zu gewinnen?&nbsp; Um die perfekte Arbeit als Vorbereitung f\u00fcr die kommende Lese zu leisten, sind unz\u00e4hlige Arbeitsabl\u00e4ufe notwendig. Angefangen mit dem Rebschnitt im Fr\u00fchling bis hin zur Selektion im &#8230; <a title=\"Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/\" aria-label=\"Mehr dazu unter Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche\">Weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":195910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[63,1],"tags":[2969,2970,2971,163,2972],"post_folder":[],"class_list":["post-126455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-weinwissen","tag-bewaesserung","tag-rebschnitt","tag-weinbergsarbeit","tag-weinlese","tag-winzer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Weinherstellung: Die Arbeit im Weinberg ist entscheidend f\u00fcr den Weingeschmack. Was von der Reberziehung bis zur Weinlese geschieht, lesen Sie hier:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Weinherstellung: Die Arbeit im Weinberg ist entscheidend f\u00fcr den Weingeschmack. Was von der Reberziehung bis zur Weinlese geschieht, lesen Sie hier:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-15T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-15T14:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/REPORT_ZARATE_FENTO_296-Kopie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1728\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Janus Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Janus Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"15\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/\"},\"author\":{\"name\":\"Janus Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/1961e2fa9870d64bea2fb8ce341edc01\"},\"headline\":\"Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche\",\"datePublished\":\"2022-05-15T10:00:00+00:00\",\"dateModified\":\"2023-03-15T14:58:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/\"},\"wordCount\":2164,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/REPORT_ZARATE_FENTO_296-Kopie.jpg\",\"keywords\":[\"bew\u00e4sserung\",\"rebschnitt\",\"Weinbergsarbeit\",\"Weinlese\",\"Winzer\"],\"articleSection\":{\"1\":\"Weinwissen\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/\",\"name\":\"Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/REPORT_ZARATE_FENTO_296-Kopie.jpg\",\"datePublished\":\"2022-05-15T10:00:00+00:00\",\"dateModified\":\"2023-03-15T14:58:00+00:00\",\"description\":\"Weinherstellung: Die Arbeit im Weinberg ist entscheidend f\u00fcr den Weingeschmack. Was von der Reberziehung bis zur Weinlese geschieht, lesen Sie hier:\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/REPORT_ZARATE_FENTO_296-Kopie.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/REPORT_ZARATE_FENTO_296-Kopie.jpg\",\"width\":1728,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/05\\\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/1961e2fa9870d64bea2fb8ce341edc01\",\"name\":\"Janus Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-IMG_1664-96x96.jpg\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-IMG_1664-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-IMG_1664-96x96.jpg\",\"caption\":\"Janus Fenske\"},\"description\":\"Wein und Essen sind Emotionen, welche gerne geteilt werden m\u00f6chten.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/janus-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche - Unterwegs mit Weine &amp; Feinkost","description":"Weinherstellung: Die Arbeit im Weinberg ist entscheidend f\u00fcr den Weingeschmack. Was von der Reberziehung bis zur Weinlese geschieht, lesen Sie hier:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/","og_locale":"de_DE","og_type":"article","og_title":"Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche - Unterwegs mit Weine &amp; Feinkost","og_description":"Weinherstellung: Die Arbeit im Weinberg ist entscheidend f\u00fcr den Weingeschmack. Was von der Reberziehung bis zur Weinlese geschieht, lesen Sie hier:","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2022-05-15T10:00:00+00:00","article_modified_time":"2023-03-15T14:58:00+00:00","og_image":[{"width":1728,"height":1152,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/REPORT_ZARATE_FENTO_296-Kopie.jpg","type":"image\/jpeg"}],"author":"Janus Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Janus Fenske","Gesch\u00e4tzte Lesezeit":"15\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/"},"author":{"name":"Janus Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/1961e2fa9870d64bea2fb8ce341edc01"},"headline":"Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche","datePublished":"2022-05-15T10:00:00+00:00","dateModified":"2023-03-15T14:58:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/"},"wordCount":2164,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/REPORT_ZARATE_FENTO_296-Kopie.jpg","keywords":["bew\u00e4sserung","rebschnitt","Weinbergsarbeit","Weinlese","Winzer"],"articleSection":{"1":"Weinwissen"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/","name":"Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/REPORT_ZARATE_FENTO_296-Kopie.jpg","datePublished":"2022-05-15T10:00:00+00:00","dateModified":"2023-03-15T14:58:00+00:00","description":"Weinherstellung: Die Arbeit im Weinberg ist entscheidend f\u00fcr den Weingeschmack. Was von der Reberziehung bis zur Weinlese geschieht, lesen Sie hier:","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/REPORT_ZARATE_FENTO_296-Kopie.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/REPORT_ZARATE_FENTO_296-Kopie.jpg","width":1728,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/05\/weinherstellung-der-weg-vom-weinberg-in-die-weinflasche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Weinherstellung \u2013 Der Weg vom Weinberg in die Weinflasche"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/1961e2fa9870d64bea2fb8ce341edc01","name":"Janus Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/cropped-IMG_1664-96x96.jpg","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/cropped-IMG_1664-96x96.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/cropped-IMG_1664-96x96.jpg","caption":"Janus Fenske"},"description":"Wein und Essen sind Emotionen, welche gerne geteilt werden m\u00f6chten.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/janus-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/05\/REPORT_ZARATE_FENTO_296-Kopie.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-wTB","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/126455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=126455"}],"version-history":[{"count":2,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/126455\/revisions"}],"predecessor-version":[{"id":195912,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/126455\/revisions\/195912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/195910"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=126455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=126455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=126455"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=126455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}