{"id":128656,"date":"2022-09-24T11:00:00","date_gmt":"2022-09-24T09:00:00","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=128656"},"modified":"2023-03-15T13:56:30","modified_gmt":"2023-03-15T12:56:30","slug":"das-weinbaugebiet-pfalz","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/","title":{"rendered":"Das Weinbaugebiet Pfalz"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Die Geschichte von dem Weinbaugebiet Pfalz<\/h2>\n\n\n\n<p>\u201eZum Wohl. Die Pfalz.\u201c &#8211; die 3600 pf\u00e4lzischen Winzer verbinden in ihrem ber\u00fchmten Slogan geschickt Understatement und kerniges Selbstbewusstsein. Und das steht ihnen auch zu, denn aus der Region, die historisch gesehen vor allem f\u00fcr recht gew\u00f6hnlichen Landwein stand, hat sich in den vergangenen Jahrzehnten dank einer ambitionierten neuen Generation zu einem kleinen Eldorado gemausert, das auf internationalen Wettbewerben eine ernsthafte Konkurrenz f\u00fcr italienische und franz\u00f6sische Spitzenanbaugebiete darstellt. Vor k\u00fchlen Westwinden gesch\u00fctzt durch umgebende Berge, sicher vor Sp\u00e4tfrost und zu harten Niederschl\u00e4gen, ja allgemein verw\u00f6hnt durch sehr milde Temperaturen werden hier vor allem Weine erzeugt, die restzuckerarm, dabei dennoch sehr fruchtig sind &#8211; das kann man umso mehr nachvollziehen, wenn man sich die deutsch-franz\u00f6sische Grenze bei Wissembourg wegdenkt und den 80 Kilometer langen, recht schmalen Streifen, der das Gebiet Pfalz ist, als die n\u00f6rdliche Fortsetzung der Weinberge des Elsass betrachtet.<\/p>\n\n\n\n<p>Obwohl mit fast 24 000 Hektar das zweitgr\u00f6\u00dfte Weinbaugebiet Deutschlands, nimmt es doch nur f\u00fcnf Prozent der geografischen Pfalz ein. Auch unterteilt es sich, anders als manche viel kleinere Weinbaugebiete, die oft sehr viel ausdifferenzierter sind, lediglich in zwei Regionen: die Mittelhaardt und die S\u00fcdliche Weinstra\u00dfe. Qualitatives Zentrum des Pf\u00e4lzer Weinbaus ist erstere: unterhalb des Pf\u00e4lzer Waldes gedeihen hier in einer Handvoll Orten herrlich knackige Rieslinge. Kallstadt, Wachenheim, Ungstein und andere profitieren von den leichten B\u00f6den, welche die W\u00e4rme der 1800 Sonnenstunden j\u00e4hrlich l\u00e4nger speichern und die Rebst\u00f6cke tief hinab in sehr mineralhaltige Schichten wurzeln lassen. Der Lehmanteil in den B\u00f6den ist hier geringer als an der S\u00fcdlichen Weinstra\u00dfe, was die Weine weniger schwer, daf\u00fcr mineralischer werden l\u00e4sst: der Boden speichert das Wasser hier nicht so nachhaltig, sodass die Reben nicht dauerhaft nasse F\u00fc\u00dfe haben &#8211; daf\u00fcr ist aber auch der Ertrag geringer.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_6.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_6.jpg\" alt=\"\" class=\"wp-image-128717\"\/><\/a><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>Der gelungene Spagat zwischen Tradition und Moderne ist vielleicht das Geheimnis der Pfalz. Das mit bis zu 700 000 Besuchern gr\u00f6\u00dfte Weinfest der Welt, der D\u00fcrkheimer Wurstmarkt, lockt jeden September mit dem Klimpern der Dubbegl\u00e4ser, in denen das pf\u00e4lzische Lebenselixier, die Rieslingschorle, schimmert. Seit \u00fcber 600 Jahren findet er statt, damals entstanden, als Bauern und Winzer Pilger mit Wegzehrung versorgten. Seit 1934 ist nicht nur der Markt, sondern der ganze Ort um eine im wahrsten Sinne des Wortes gro\u00dfe Attraktion reicher: das D\u00fcrkheimer Riesenfass l\u00e4uft mit sagenhaften 1,7 Millionen Litern Fassungsverm\u00f6gen dem vorigen Rekordhalter im Heidelberger Schloss bei Weitem den Rang ab. Anders als in diesem wurde in der D\u00fcrkheimer Version niemals wirklich Wein gelagert, daf\u00fcr finden 430 G\u00e4ste Platz in der heimeligen Holzkonstruktion.<\/p>\n\n\n\n<p>Die Pf\u00e4lzer sind streng auf Regionalit\u00e4t bedacht: heutzutage muss jeder Wurstmarkt-Stand mindestens einen Riesling im Angebot haben, und erst seit etwa 20 Jahren sind auch Rotweine zugelassen. Das k\u00f6nnen verl\u00e4ssliche Klassiker wie Dornfelder und Portugieser sein, geschmacklich interessant wird es aber besonders bei den Sp\u00e4tburgundern, die nach einer ordentlichen Reifezeit eine fast magische Kr\u00e4uterw\u00fcrze entfalten k\u00f6nnen. Aber auch f\u00fcr Deutschland untypische Rebsorten wie Cabernet oder Merlot k\u00f6nnen in den sehr warmen Sommern gut heranreifen und zu Weinen werden, die sich &#8211; wie fast alle Pf\u00e4lzer Weine &#8211; sowohl jung genie\u00dfen als auch jahrelang lagern lassen. Zu verdanken ist das oft experimentierfreudigen Jungwinzern, die sich Jahr f\u00fcr Jahr gegenseitig anstacheln, radikal Neues zu wagen &#8211; mit viel Ehrgeiz, aber ganz ohne Neid und Missgunst. Einen Riesling muss man nat\u00fcrlich immer im Portfolio haben und versucht dabei, die Restzuckerschraube stets noch ein bisschen weiter Richtung Null zu drehen. Aber auch aus Wei\u00dfburgundern und Muskatellern l\u00e4sst sich Enormes herausarbeiten &#8211; wobei nicht die typische bombige Fruchtf\u00fclle dieser Rebsorten im Vordergrund steht, sondern sehr detailverliebt an immer mehr Reduktion gearbeitet wird. Ihr j\u00fcngstes Lieblingsspielzeug ist der Chardonnay, erst seit etwa 30 Jahren Im Lande, aber die Pf\u00e4lzer haben schon verstanden, dass zu intensives Toasting-Aroma vom Fass ihm eher schadet als n\u00fctzt. So rustikal die Jungs bei der Arbeit im \u201eWengert\u201c, im Weinberg, oder als derbe Lieder singende \u201eKerweburschen\u201c zu den sehr z\u00fcnftig begangenen Kirchweihfesten daherkommen, so behutsam puristisch sind sie in der Arbeit danach. Viele Betriebe arbeiten mittlerweile biodynamisch und wollen Eingriffe am Rebstock wie am Most so gering wie m\u00f6glich halten. Und diese Feinheit passt sowohl in die Deidesheimer Edelrestaurants wie zu Leberkn\u00f6del und Sauerkraut nach einer Wanderung durch den Pf\u00e4lzer Wald.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_3.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_3.jpg\" alt=\"\" class=\"wp-image-128719\"\/><\/a><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>Die Zeiten, in denen man Pf\u00e4lzer Wein mit minderwertigem Moselwein verschnitt, um die S\u00e4ure in letzterem zu mildern, sind lange vorbei, ebenso die geschmackliche Epoche der recht erdigen, eher s\u00fc\u00dflichen Weine. Ein st\u00e4hlerner Charakter mit einem zuverl\u00e4ssig tragenden S\u00e4ureger\u00fcst ist das Gebot der Stunde, und orientierte man sich da anfangs noch am Rheingau, hat man nun schon l\u00e4nger zu einem v\u00f6llig eigenen Stil gefunden. Gerade an der Mittelhaardt war man schon sehr fr\u00fch auf diesem Trip, denn w\u00e4hrend besonders in der S\u00fcdpfalz der Landwein noch bis lange in die Nachkriegszeit allgemein \u00fcblich war, setzte man hier schon seit den 1830ern auf Qualit\u00e4tswein. Zu verdanken ist das vor allem Andreas Jordan. Als er 1848 starb, ohne vorher sein Erbe geregelt zu haben, kam es zur sogenannten Jordanschen Teilung, welche die Geburtsstunde von drei der wohl ber\u00fchmtesten Pf\u00e4lzer Weing\u00fcter ist: Bassermann-Jordan, von Winning und Reichsrat von Buhl. Alle im malerischen Deidesheim beheimatet, haben ihre Lagen aber auch in umliegenden Gemeinden, etwa in Forst, auf dessen gerade einmal 3,6 Quadratkilometern Fl\u00e4che 180 Hektar dem Wein vorbehalten sind. Um viele Lagennamen wie das Forster Ungeheuer ranken sich wilde Legenden, die von den Einheimischen gern mit einem Augenzwinkern an staunende Touristen aus aller Welt weitergegeben werden.<\/p>\n\n\n\n<p>Wie viele andere pf\u00e4lzische Ortschaften ist Forst ein Stra\u00dfendorf, mitten hindurch f\u00fchrte fr\u00fcher also nur ein einziger Weg. Ein Erfolgsmodell, das mittlerweile von anderen Gebieten kopiert wurde, hat auch in diesen st\u00e4dtebaulichen Gegebenheiten seinen Ursprung: die Deutsche Weinstra\u00dfe, die Werbeidee schlechthin. Wie alle guten Einf\u00e4lle aus der Not geboren: die Besatzung des Rheinlandes nach dem Ersten Weltkrieg durch Frankreich brachte es mit sich, dass der Pf\u00e4lzer Wein nur eingeschr\u00e4nkt in den freien Teil des Reiches ausgef\u00fchrt werden durfte. Der Export nach Frankreich war aber ebenso unm\u00f6glich, weil man dort von deutschem Wein schlicht nichts wissen wollte. Hinzu kam, dass der Ertrag im Jahr 1934 weit \u00fcber dem der Vorjahre lag, was die Preise noch weiter dr\u00fcckte. Nachdem die Idee zu einer Weinstra\u00dfe schon einige Jahre kursiert hatten, griff Gauleiter B\u00fcrckel sie 1935 angesichts der finanziellen Not der Winzer auf und beschloss sehr pragmatisch, einfach diejenige Strecke zur Weinstra\u00dfe zu machen, die in S\u00fcd-Nord-Richtung durch die meisten Weinorte f\u00fchrte. Die Er\u00f6ffnung wurde zwar sehr pomp\u00f6s begangen, mit kilometerlangem Autokorso und weihevollen Reden, das bekannte Deutsche Weintor in Schweigen war jedoch nur notd\u00fcrftig aus Holz zusammengezimmert, das in Gr\u00fcnstadt gar aus Pappmach\u00e9 in Form gekleistert worden &#8211; das ist heute freilich ganz anders, gerade das Haus der Deutschen Weinstra\u00dfe in Bockenheim kann sich sehen lassen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_1.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_1.jpg\" alt=\"\" class=\"wp-image-128714\"\/><\/a><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>Die vielen Rebst\u00f6cke, die sich heute an den H\u00e4usern am Rande der Weinstra\u00dfe emporranken, stammen oft noch aus ebenjener Anfangszeit und bieten zusammen mit den Feigenstr\u00e4uchern, Mandelb\u00e4umen und Zitruspflanzen, ja sogar Kiwis und Bananenstauden eine tr\u00e4umerische, fast unwirkliche Riviera-Atmosph\u00e4re. Das markante gelb-schwarze Quadrat mit der stilisierten Weintraube am Wegesrand ist im wahrsten Sinne des Wortes zum Aush\u00e4ngeschild der Region geworden, so sehr, dass sich der ehemalige Landkreis Landau-Bad Bergzabern im Zuge der Gebietsreform kurzerhand in S\u00fcdliche Weinstra\u00dfe umbenannte und seitdem mit seinem \u201eS\u00dcW\u201c auf jeder Autobahn als Tourismus-Botschafter fungiert.<\/p>\n\n\n\n<p>Nicht an der Weinstra\u00dfe, ja nicht einmal im Weinbaugebiet lag Pirmasens, der Wohnort Ruth Bachrodts. Ein weiterer Marketing-Coup war n\u00e4mlich schon ein paar Jahr fr\u00fcher gelandet worden: die K\u00fcr der ersten Weink\u00f6nigin. Diese war bis Anfang der 50er Jahre in Personalunion pf\u00e4lzische und gesamtdeutsche Regentin, denn erst ab dann wurde das Konzept auch von anderen Weinbaugebieten adaptiert. Ist der Status der Weink\u00f6nigin heute mit vielerlei Repr\u00e4sentationspflichten auch im Ausland verbunden und der Anspruch an Bildung und Pers\u00f6nlichkeit der Kandidatinnen dementsprechend hoch, gen\u00fcgte es damals, schlicht und einfach die H\u00fcbscheste zu sein und dann \u00fcber die Weinfeste zu tingeln, etwa in Landau und Neustadt, mit jeweils knapp \u00fcber 2000 Hektar auf dem Stadtgebiet so viel Anbaufl\u00e4che wie die H\u00e4lfte der Nahe oder fast viermal das gesamte Gebiet Ahr.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_dietrich.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_dietrich.jpg\" alt=\"\" class=\"wp-image-128716\"\/><\/a><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>Dem gleichen Zweck wie die Weink\u00f6nigin geht, wenn auch auf ganz andere Weise, die Weinbruderschaft der Pfalz nach. Die etwa 1000 Mitglieder organisieren sich nach Art mittelalterlicher Ritterorden und haben sich die Pflege allen mit dem Wein in Zusammenhang stehenden Brauchtums auf die Fahnen geschrieben. Die allermeisten Mitglieder sind seit jeher keine Winzer, sondern Journalisten, Schriftsteller oder bildende K\u00fcnstler. Vielleicht ist es auch ihnen zu verdanken, dass es kaum eine Region in Deutschland gibt, in der Weinkultur und allt\u00e4gliche Lebensart so sehr miteinander verschr\u00e4nkt sind. Ber\u00fchmtestes Mitglied und gleichzeitig wohl bekanntester Genuss-Botschafter der Pfalz war Bundeskanzler Helmut Kohl, der gern zu Wein und Saumagen zu sich nach Hause in Oggersheim einlud und einmal den \u201eAngriff\u201c eines politischen Gegners, der ihm ein Glas Wein \u00fcber den Kopf gesch\u00fcttet hatte, lapidar kommentierte: \u201eNur schade, dass es kein Pf\u00e4lzer Wein war.\u201c Auch, wenn viele der jungen Talente auf den Weing\u00fctern Kohl gar nicht mehr bewusst als Kanzler erlebt haben d\u00fcrften &#8211; in puncto Selbstbewusstsein stehen sie ihm in nichts nach, ebenso wenig im Hinblick auf (aromatische) Kompromisslosigkeit. Den Mut zu den entsprechenden Resultaten sollte man als Weintrinker keinesfalls vermissen lassen! Text: Dario Sellmeier<\/p>\n\n\n\n\n\n<h3 class=\"wp-block-heading\">Jetzt Newsletter abonnieren und keinen Blog Beitrag mehr verpassen:<\/h3>\n\n\n<div class=\"wp-block-jetpack-subscriptions__supports-newline wp-block-jetpack-subscriptions\">\n\t\t<div>\n\t\t\t<div>\n\t\t\t\t<div>\n\t\t\t\t\t<p >\n\t\t\t\t\t\t<a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?post_type=post&#038;p=128656\" style=\"font-size: 16px;padding: 15px 23px 15px 23px;margin: 0; margin-left: 10px;border-radius: 0px;border-width: 1px; background-color: #113AF5; color: #FFFFFF; text-decoration: none; white-space: nowrap; margin-left: 0\">Anmelden<\/a>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-7e5fce0a wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-color has-background wp-element-button\" href=\"https:\/\/www.weine-feinkost.de\/shop\/\" style=\"border-radius:2px;color:#fffffa;background-color:#a52f2f\" target=\"_blank\" rel=\"noreferrer noopener\">Zum Shop<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-text-color wp-element-button\" href=\"https:\/\/www.weine-feinkost.de\/shop\/newsletter\" style=\"border-radius:2px;color:#a83535\" target=\"_blank\" rel=\"noreferrer noopener\">Weine&amp;Feinkost Newsletter<\/a><\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-social-links aligncenter has-large-icon-size is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-instagram  wp-block-social-link\"><a href=\"https:\/\/www.instagram.com\/weine_und_feinkost\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Weine&amp;Feinkost Instagram<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-facebook  wp-block-social-link\"><a href=\"https:\/\/www.facebook.com\/WeineFeinkostChristianFenske\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Weine&amp;Feinkost Facebook<\/span><\/a><\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Geschichte von dem Weinbaugebiet Pfalz \u201eZum Wohl. Die Pfalz.\u201c &#8211; die 3600 pf\u00e4lzischen Winzer verbinden in ihrem ber\u00fchmten Slogan geschickt Understatement und kerniges Selbstbewusstsein. Und das steht ihnen auch zu, denn aus der Region, die historisch gesehen vor allem f\u00fcr recht gew\u00f6hnlichen Landwein stand, hat sich in den vergangenen Jahrzehnten dank einer ambitionierten neuen &#8230; <a title=\"Das Weinbaugebiet Pfalz\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/\" aria-label=\"Mehr dazu unter Das Weinbaugebiet Pfalz\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":170798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3316,1],"tags":[1294,3059,919,3032,123,290,2680,3060,2785,2675],"post_folder":[],"class_list":["post-128656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anbaugebiete","category-weinwissen","tag-anbaugebiet","tag-dornfelder","tag-gewuerztraminer","tag-grauburgunder","tag-pfalz","tag-riesling","tag-spaetburgunder","tag-st-laurent","tag-weinregion","tag-weissburgunder"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das Weinbaugebiet Pfalz - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das Weinbaugebiet Pfalz - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Die Geschichte von dem Weinbaugebiet Pfalz \u201eZum Wohl. Die Pfalz.\u201c &#8211; die 3600 pf\u00e4lzischen Winzer verbinden in ihrem ber\u00fchmten Slogan geschickt Understatement und kerniges Selbstbewusstsein. Und das steht ihnen auch zu, denn aus der Region, die historisch gesehen vor allem f\u00fcr recht gew\u00f6hnlichen Landwein stand, hat sich in den vergangenen Jahrzehnten dank einer ambitionierten neuen ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-24T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-15T12:56:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/FAVOREAT-Stephan-_-Georg-Schwedhelm-178-Kopie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Das Weinbaugebiet Pfalz\",\"datePublished\":\"2022-09-24T09:00:00+00:00\",\"dateModified\":\"2023-03-15T12:56:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/\"},\"wordCount\":1648,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/pfalz_1.jpg\",\"keywords\":[\"Anbaugebiet\",\"Dornfelder\",\"Gew\u00fcrztraminer\",\"Grauburgunder\",\"Pfalz\",\"Riesling\",\"Sp\u00e4tburgunder\",\"St. Laurent\",\"Weinregion\",\"Wei\u00dfburgunder\"],\"articleSection\":[\"Anbaugebiete\",\"Weinwissen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/\",\"name\":\"Das Weinbaugebiet Pfalz - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/pfalz_1.jpg\",\"datePublished\":\"2022-09-24T09:00:00+00:00\",\"dateModified\":\"2023-03-15T12:56:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/pfalz_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/pfalz_1.jpg\",\"width\":480,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/09\\\/das-weinbaugebiet-pfalz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das Weinbaugebiet Pfalz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das Weinbaugebiet Pfalz - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/","og_locale":"de_DE","og_type":"article","og_title":"Das Weinbaugebiet Pfalz - Unterwegs mit Weine &amp; Feinkost","og_description":"Die Geschichte von dem Weinbaugebiet Pfalz \u201eZum Wohl. Die Pfalz.\u201c &#8211; die 3600 pf\u00e4lzischen Winzer verbinden in ihrem ber\u00fchmten Slogan geschickt Understatement und kerniges Selbstbewusstsein. Und das steht ihnen auch zu, denn aus der Region, die historisch gesehen vor allem f\u00fcr recht gew\u00f6hnlichen Landwein stand, hat sich in den vergangenen Jahrzehnten dank einer ambitionierten neuen ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2022-09-24T09:00:00+00:00","article_modified_time":"2023-03-15T12:56:30+00:00","og_image":[{"width":2000,"height":1334,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/FAVOREAT-Stephan-_-Georg-Schwedhelm-178-Kopie.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Das Weinbaugebiet Pfalz","datePublished":"2022-09-24T09:00:00+00:00","dateModified":"2023-03-15T12:56:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/"},"wordCount":1648,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_1.jpg","keywords":["Anbaugebiet","Dornfelder","Gew\u00fcrztraminer","Grauburgunder","Pfalz","Riesling","Sp\u00e4tburgunder","St. Laurent","Weinregion","Wei\u00dfburgunder"],"articleSection":["Anbaugebiete","Weinwissen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/","name":"Das Weinbaugebiet Pfalz - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_1.jpg","datePublished":"2022-09-24T09:00:00+00:00","dateModified":"2023-03-15T12:56:30+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_1.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_1.jpg","width":480,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/09\/das-weinbaugebiet-pfalz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Das Weinbaugebiet Pfalz"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/09\/pfalz_1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-xt6","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/128656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=128656"}],"version-history":[{"count":2,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/128656\/revisions"}],"predecessor-version":[{"id":195890,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/128656\/revisions\/195890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/170798"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=128656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=128656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=128656"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=128656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}