{"id":129458,"date":"2022-11-28T17:00:00","date_gmt":"2022-11-28T16:00:00","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=129458"},"modified":"2023-03-19T12:06:54","modified_gmt":"2023-03-19T11:06:54","slug":"wirtshaeuser-in-der-wachau","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/","title":{"rendered":"Wirtsh\u00e4user in der Wachau"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ein Hoch auf die Gast- und Wirtsh\u00e4user der Wachau<\/h2>\n\n\n\n<p class=\"has-drop-cap\">Laut Definition handelt es sich bei einem Wirtshaus um eine Gastwirtschaft in der man Mahlzeiten und alkoholische Getr\u00e4nke erh\u00e4lt. Diese befinden sich meistens in l\u00e4ndlichen Gebieten und sind vom Standard her einfach bis rustikal. Diese Wirtsh\u00e4user standen fr\u00fcher f\u00fcr eine ehrliche und selbst zubereitete K\u00fcche, und dort wurden lokale und f\u00fcr den Landstrich typische Gerichte serviert. In Nord und Mittel Deutschland sind die klassischen Wirtsh\u00e4user leider fast ausgestorben und lediglich in S\u00fcd Deutschland l\u00e4sst sich dieser gastronomische Brauchtum noch h\u00e4ufiger antreffen.<\/p>\n\n\n\n<p>In der Schweiz und in \u00d6sterreich dagegen treffen die suchenden G\u00e4ste diese Kultur noch wesentlich h\u00e4ufiger an. Gerade in touristischen Gebieten kann ehrlich und schmackhaft gegessen werden. Keine Tiefk\u00fchlkost, kein D\u00f6ner weit und breit, keine Pizza und mit ein wenig Gl\u00fcck wird vor Ort sogar noch der Fisch geangelt, das Wild geschossen und das Gem\u00fcse aus dem eigenen Garten angebaut. Anbei ein paar Beispiele dieser tollen regionalen Kultur Institutionen rund um die \u00d6sterreichische Weinregion Wachau an der Donau.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gasthaus Jell &#8211; Krems an der Donau<\/h2>\n\n\n\n<p class=\"has-drop-cap\">Da wo noch ger\u00f6stetes oder gebackenes Hirn stolz aus der K\u00fcche serviert wird, scheinen die gastronomischen Zeiten einfach stehen geblieben zu sein. Schon in der f\u00fcnften Generation wird im Gasthaus Jell in Krems an der Donau der klassischen Speisen gefr\u00f6nt. Der Gr\u00fcndervater Josef Jell kam bereits im Jahr 1897 zusammen mit seiner Frau Maria Anna an die Donau. Beide arbeiteten vorher im Salzburger Hotel \u00d6sterreichischer Hof, dem heutigen Hotel Sacher, bis sie sich dazu entschlossen, das Gasthaus zu erwerben. Er als gelernter Portier und sie als gelernte K\u00f6chin legten so die Grundsteine f\u00fcr diese seit Jahrzehnten feste und beliebte kulinarische Instanz in Krems.<\/p>\n\n\n\n<p>Auch heute scheint es so, als ob sich die Zeiten nicht ver\u00e4ndert h\u00e4tten. Beliebte Gerichte aus der kaiserlich- k\u00f6niglichen Monarchie werden im Gasthaus Jell in einem rustikalen und musealen Ambiente gekonnt auf die Tische platziert. Kaiser Franz Joseph und Sissi w\u00e4ren hier sicherlich ohne Reue und mit jeder Menge Freude Stammg\u00e4ste gewesen. 45 von 365 Punkten<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthaus_Jell_Krems_an_der_Donau_Oesterreich_3-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129479\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129479\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthaus_Jell_Krems_an_der_Donau_Oesterreich_3-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthaus_Jell_Krems_an_der_Donau_Oesterreich_3-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthaus_Jell_Krems_an_der_Donau_Oesterreich_1-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129477\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129477\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthaus_Jell_Krems_an_der_Donau_Oesterreich_1-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthaus_Jell_Krems_an_der_Donau_Oesterreich_1-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthaus_Jell_Krems_an_der_Donau_Oesterreich_2-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129478\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129478\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthaus_Jell_Krems_an_der_Donau_Oesterreich_2-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthaus_Jell_Krems_an_der_Donau_Oesterreich_2-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p><strong>Gasthaus Jell<\/strong>, Hoher Markt 8, 3500 Krems an der Donau, \u00d6sterreich, Telefon: +43 2732 82345, <a href=\"https:\/\/www.amon-jell.at\/\">https:\/\/www.amon-jell.at\/<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Heinzle &#8211; Wei\u00dfenkirchen in der Wachau<\/h2>\n\n\n\n<p class=\"has-drop-cap\">Das Restaurant Heinzle liegt direkt an der Donau im malerischen Wachauer Weinort Weissenkirchen. Die Spezialit\u00e4ten sind hier ger\u00e4ucherte, gekochte, ged\u00fcnstete, gebratene und gebeizte lokale Fische. Ob Forelle und Huchen aus dem Trausental oder Hecht und Karpfen aus den Teichwirtschaften des Waldviertels, hier kommt das auf den Tisch, was frisch und lecker schmeckt.<\/p>\n\n\n\n<p>Auch Wild und regionale Fleischspeisen oder Gem\u00fcse, teils aus dem eigenen Garten, m\u00fcssen nicht vom Tellerrand gesto\u00dfen werden. Chichi und Fastfood wird man hier nicht finden, ehrliche Hausmannskost, wie sie fr\u00fcher einfach zum Alltag geh\u00f6rte, dagegen mit jedem servierten Gang. Hier geht nicht nur bei gutem Wetter auf der Terrasse die gastronomische Sonne auf, auch im Inneren des Gasthauses wird ungek\u00fcnstelt ein ehrliches und leckeres Handwerk zelebriert. 25 von 365 Punkten<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:51.60988%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_1.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_1.jpg?strip=info&#038;w=512&#038;ssl=1 512w\" alt=\"\" data-height=\"640\" data-id=\"129471\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129471\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_1.jpg\" data-width=\"512\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_1.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:48.39012%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2025\/11\/Heinzle_Weissenkirchen_in_der_Wachau_5-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2025\/11\/Heinzle_Weissenkirchen_in_der_Wachau_5-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129475\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129475\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2025\/11\/Heinzle_Weissenkirchen_in_der_Wachau_5-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2025\/11\/Heinzle_Weissenkirchen_in_der_Wachau_5-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:47.01163%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_4.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_4.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_4.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"129474\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129474\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_4.jpg\" data-width=\"640\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_4.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:26.49419%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_3-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_3-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129473\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129473\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_3-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_3-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:26.49419%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_2-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_2-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129472\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129472\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_2-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Heinzle_Weissenkirchen_in_der_Wachau_2-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p><strong>Heinzle<\/strong>, Wei\u00dfenkirchen in der Wachau 280, 3610 Wei\u00dfenkirchen in der Wachau, \u00d6sterreich, Telefon: +43 2715 2231, <a href=\"https:\/\/www.heinzle.at\/\">https:\/\/www.heinzle.at\/<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gasthof Teufl &#8211; Purgstall an der Erlauf<\/h2>\n\n\n\n<p class=\"has-drop-cap\">Der Gasthof Teufl in Purgstall an der Erlauf liegt direkt im Ortszentrum gegen\u00fcber der sp\u00e4tgotischen Pfarrkirche. Im Teufl, welcher von der gleichnamigen Familie betrieben wird, scheinen die Zeiten stehen geblieben zu sein. Die Speisekarte ist klein, die Qualit\u00e4t daf\u00fcr umso gr\u00f6\u00dfer. Hier l\u00e4sst es sich aushalten und dem Leitspruch der Familie Teufl \u201eWir arbeiten mit noch mehr Regionalit\u00e4t, Identit\u00e4t und Qualit\u00e4t in Gedanken, Worten und Werken. Amen.\u201c, ist eigentlich nicht mehr viel hinzuzuf\u00fcgen. Nur das sich dieses Wirtshaus doch noch bitte sehr, sehr lange seinen Charme, seine Lokalit\u00e4t und seine leckeren, ungeschminkten Speisen bewahren wird. 30 von 365 Punkten<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:26.49419%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_3-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_3-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129470\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129470\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_3-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_3-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:47.01163%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_1.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_1.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_1.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"129468\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129468\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_1.jpg\" data-width=\"640\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_1.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:26.49419%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_2-rotated.jpg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_2-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129469\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129469\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_2-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Gasthof_Teufl_Purgstall_an_der_Erlauf_Oesterreich_2-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p><strong>Gasthof Teufl<\/strong>, Kirchenstra\u00dfe 9, 3251 Purgstall an der Erlauf, \u00d6sterreich, Telefon: 07489 232210, <a href=\"https:\/\/gasthof-teufl.at\/\">https:\/\/gasthof-teufl.at\/<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hofmeisterei Hirtzberger &#8211; Wei\u00dfenkirchen in der Wachau &#8211; \u00d6sterreich<\/h2>\n\n\n\n<p class=\"has-drop-cap\">Die Hofmeisterei Hirtzberger in dem kleinen \u00d6rtchen W\u00f6sendorf, kurz vor dem bekannten Weinort Wei\u00dfenkirchen in der Wachau liegend, ist streng genommen gar kein klassisches Wirtshaus, und dennoch hat es den selben Charme, die besondere Gem\u00fctlichkeit und dieses rustikale und nette Ambiente, sodass die G\u00e4ste sich hier wie daheim oder wie in einem Gasthaus mit solider, hausgemachter K\u00fcche f\u00fchlen.<\/p>\n\n\n\n<p>Das tolle fr\u00fchgotische Geb\u00e4ude wurde liebevoll von der Eigent\u00fcmer Familie Hirtzberger renoviert, um dann von den beiden P\u00e4chtern Erwin Windhaber als K\u00fcchenchef und Hartmuth Rameder als Restaurant- und Weinleiter im Jahr 2014 er\u00f6ffnet zu werden. Neben einer Speisekarte mit Klassikern der so ber\u00fchmten \u00f6sterreichischen K\u00fcche stehen hier den G\u00e4sten noch diverse Men\u00fcs zur Auswahl. In der Hofmeisterei Hirtzberger kann sich so jeder seine Wunschg\u00e4nge je nach Hunger, Lust und Laune zusammen stellen. Das ist locker, das ist ehrlich und das schmeckt zum Finger abschlecken gut.<\/p>\n\n\n\n<p>Die Weinkarte gleicht dabei einer Bibel und ist von vielen edlen Wachauer Tropfen gepr\u00e4gt. Besonders die Jahrgangstiefe der Weine der Familie Hirtzberger ist dabei einzigartig. Geh\u00f6ren deren Weine doch ohne Zweifel zu den besten der ganzen Wachau. Aber auch Liebhaber anderer gro\u00dfartiger Wei\u00df-, Rotweine und Champagner werden nur bei dem Anblick dieser Weinkarte ins Schw\u00e4rmen geraten.<\/p>\n\n\n\n<p>Also f\u00fchlt man sich dann irgendwie doch wie in einem Wirtshaus, und das ist an dieser Stelle als ganz gro\u00dfes Lob zu verstehen. 120 von 365 Punkten<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:25.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_1-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129493\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129493\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_1-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_1-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:25.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_3-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129495\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129495\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_3-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_3-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:25.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_4-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129496\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129496\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_4-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_4-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:25.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_5-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129497\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129497\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_5-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_5-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_6-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129498\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129498\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_6-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_6-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_7-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129499\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129499\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_7-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_7-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:37.15595%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_8.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_8.jpg?strip=info&#038;w=640&#038;ssl=1 640w\" alt=\"\" data-height=\"480\" data-id=\"129500\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129500\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_8.jpg\" data-width=\"640\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_8.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:20.94802%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_9-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129501\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129501\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_9-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_9-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:20.94802%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_10-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129502\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129502\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_10-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_10-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:20.94802%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_12-rotated.jpg?strip=info&#038;w=480&#038;ssl=1 480w\" alt=\"\" data-height=\"640\" data-id=\"129503\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=129503\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_12-rotated.jpg\" data-width=\"480\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_12-rotated.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p>Hofmeisterei Hirtzberger, W\u00f6sendorf 74, 3610 Wei\u00dfenkirchen in der Wachau, \u00d6sterreich, <a href=\"https:\/\/www.hofmeisterei.com\/\">https:\/\/www.hofmeisterei.com\/<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Jetzt Newsletter abonnieren und keinen Blog Beitrag mehr verpassen:<\/h3>\n\n\n<div class=\"wp-block-jetpack-subscriptions__supports-newline wp-block-jetpack-subscriptions\">\n\t\t<div>\n\t\t\t<div>\n\t\t\t\t<div>\n\t\t\t\t\t<p >\n\t\t\t\t\t\t<a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?post_type=post&#038;p=129458\" style=\"font-size: 16px;padding: 15px 23px 15px 23px;margin: 0; margin-left: 10px;border-radius: 0px;border-width: 1px; background-color: #113AF5; color: #FFFFFF; text-decoration: none; white-space: nowrap; margin-left: 0\">Anmelden<\/a>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-7e5fce0a wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-color has-background wp-element-button\" href=\"https:\/\/www.weine-feinkost.de\/shop\/\" style=\"border-radius:2px;color:#fffffa;background-color:#a52f2f\" target=\"_blank\" rel=\"noreferrer noopener\">Zum Shop<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-text-color wp-element-button\" href=\"https:\/\/www.weine-feinkost.de\/shop\/newsletter\" style=\"border-radius:2px;color:#a83535\" target=\"_blank\" rel=\"noreferrer noopener\">Weine&amp;Feinkost Newsletter<\/a><\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-social-links aligncenter has-large-icon-size is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-instagram  wp-block-social-link\"><a href=\"https:\/\/www.instagram.com\/weine_und_feinkost\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Weine&amp;Feinkost Instagram<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-facebook  wp-block-social-link\"><a href=\"https:\/\/www.facebook.com\/WeineFeinkostChristianFenske\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Weine&amp;Feinkost Facebook<\/span><\/a><\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Hoch auf die Gast- und Wirtsh\u00e4user der Wachau Laut Definition handelt es sich bei einem Wirtshaus um eine Gastwirtschaft in der man Mahlzeiten und alkoholische Getr\u00e4nke erh\u00e4lt. Diese befinden sich meistens in l\u00e4ndlichen Gebieten und sind vom Standard her einfach bis rustikal. Diese Wirtsh\u00e4user standen fr\u00fcher f\u00fcr eine ehrliche und selbst zubereitete K\u00fcche, und &#8230; <a title=\"Wirtsh\u00e4user in der Wachau\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/\" aria-label=\"Mehr dazu unter Wirtsh\u00e4user in der Wachau\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":171058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[33,13],"tags":[3120,3121,3122,3123,3124,3125,3126,560,3127,3128],"post_folder":[],"class_list":["post-129458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-oesterreich-restaurants","category-restaurants","tag-donau","tag-gasthaus-jell","tag-gasthof-teufl","tag-heinzle","tag-hofmeisterei-hirtzberger","tag-krems-an-der-donau","tag-purgstall-an-der-erlauf","tag-wachau","tag-weissenkirchen-in-der-wachau","tag-wirtshaus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wirtsh\u00e4user in der Wachau - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wirtsh\u00e4user in der Wachau - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Ein Hoch auf die Gast- und Wirtsh\u00e4user der Wachau Laut Definition handelt es sich bei einem Wirtshaus um eine Gastwirtschaft in der man Mahlzeiten und alkoholische Getr\u00e4nke erh\u00e4lt. Diese befinden sich meistens in l\u00e4ndlichen Gebieten und sind vom Standard her einfach bis rustikal. Diese Wirtsh\u00e4user standen fr\u00fcher f\u00fcr eine ehrliche und selbst zubereitete K\u00fcche, und ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-28T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-19T11:06:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_2-rotated.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Wirtsh\u00e4user in der Wachau\",\"datePublished\":\"2022-11-28T16:00:00+00:00\",\"dateModified\":\"2023-03-19T11:06:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/\"},\"wordCount\":949,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_2-rotated.jpg\",\"keywords\":[\"Donau\",\"Gasthaus Jell\",\"Gasthof Teufl\",\"Heinzle\",\"Hofmeisterei Hirtzberger\",\"Krems an der Donau\",\"Purgstall an der Erlauf\",\"Wachau\",\"Wei\u00dfenkirchen in der Wachau\",\"Wirtshaus\"],\"articleSection\":[\"\u00d6sterreich\",\"Restaurants\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/\",\"name\":\"Wirtsh\u00e4user in der Wachau - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_2-rotated.jpg\",\"datePublished\":\"2022-11-28T16:00:00+00:00\",\"dateModified\":\"2023-03-19T11:06:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_2-rotated.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_2-rotated.jpg\",\"width\":480,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2022\\\/11\\\/wirtshaeuser-in-der-wachau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wirtsh\u00e4user in der Wachau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wirtsh\u00e4user in der Wachau - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/","og_locale":"de_DE","og_type":"article","og_title":"Wirtsh\u00e4user in der Wachau - Unterwegs mit Weine &amp; Feinkost","og_description":"Ein Hoch auf die Gast- und Wirtsh\u00e4user der Wachau Laut Definition handelt es sich bei einem Wirtshaus um eine Gastwirtschaft in der man Mahlzeiten und alkoholische Getr\u00e4nke erh\u00e4lt. Diese befinden sich meistens in l\u00e4ndlichen Gebieten und sind vom Standard her einfach bis rustikal. Diese Wirtsh\u00e4user standen fr\u00fcher f\u00fcr eine ehrliche und selbst zubereitete K\u00fcche, und ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2022-11-28T16:00:00+00:00","article_modified_time":"2023-03-19T11:06:54+00:00","og_image":[{"width":480,"height":640,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_2-rotated.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Wirtsh\u00e4user in der Wachau","datePublished":"2022-11-28T16:00:00+00:00","dateModified":"2023-03-19T11:06:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/"},"wordCount":949,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_2-rotated.jpg","keywords":["Donau","Gasthaus Jell","Gasthof Teufl","Heinzle","Hofmeisterei Hirtzberger","Krems an der Donau","Purgstall an der Erlauf","Wachau","Wei\u00dfenkirchen in der Wachau","Wirtshaus"],"articleSection":["\u00d6sterreich","Restaurants"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/","name":"Wirtsh\u00e4user in der Wachau - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_2-rotated.jpg","datePublished":"2022-11-28T16:00:00+00:00","dateModified":"2023-03-19T11:06:54+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_2-rotated.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_2-rotated.jpg","width":480,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2022\/11\/wirtshaeuser-in-der-wachau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Wirtsh\u00e4user in der Wachau"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/08\/Hofmeisterei_Hirtzberger_Weissenkirchen_in_der_Wachau_Oesterreich_2-rotated.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-xG2","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/129458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=129458"}],"version-history":[{"count":1,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/129458\/revisions"}],"predecessor-version":[{"id":196259,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/129458\/revisions\/196259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/171058"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=129458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=129458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=129458"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=129458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}