{"id":14903,"date":"2012-10-09T10:15:06","date_gmt":"2012-10-09T08:15:06","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=14903"},"modified":"2012-10-09T10:15:06","modified_gmt":"2012-10-09T08:15:06","slug":"harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/","title":{"rendered":"Harlan Estate The Maiden 2005 &#8211; Napa Valley &#8211; Kalifornien \u2013 USA"},"content":{"rendered":"<p align=\"LEFT\"><span style=\"color: #000000;\"><span style=\"font-family: Helvetica,sans-serif;\"><span style=\"font-size: small;\">Der Duft dieses Rotweins vereint alle Attribute f\u00fcr die man \u00dcbersee Weine so hasst oder aber auch liebt: verschwenderische Noten von roter Gr\u00fctze mit frischer Vanillesauce, eingekochte schwarze Johannisbeeren und starke Kokosnuss Noten. Dabei stehen die roten Fruchtattribute \u00fcber dem Eichenholzfassbrand. Im Mund dann ein Feuerwerk an Kraft, Frucht, reifen Gerbstoffen und feinster L\u00e4nge, welche auch noch in einer reifen S\u00e4ure mundet. Bei diesem Wein wird der enorme Extrakt durch seine Vielschichtigkeit und Frische geb\u00fcndelt, aber auch durch Graphitaromen in den K\u00f6rper getragen. Ein Wein, der wie eine ganze Mahlzeit daher kommt, der aber nicht satt macht, sondern regelrecht nach dem n\u00e4chsten Gang schreit. Ein Rubenswein f\u00fcr Fortgeschrittene!<br \/>\n<\/span><\/span><\/span><\/p>\n<p style=\"text-align: center;\" align=\"LEFT\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/09\/wein_feinkost_wuppertal_harlan_estate_maiden.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-152384\" title=\"wein_feinkost_wuppertal_harlan_estate_maiden\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/09\/wein_feinkost_wuppertal_harlan_estate_maiden-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Duft dieses Rotweins vereint alle Attribute f\u00fcr die man \u00dcbersee Weine so hasst oder aber auch liebt: verschwenderische Noten von roter Gr\u00fctze mit frischer Vanillesauce, eingekochte schwarze Johannisbeeren und starke Kokosnuss Noten. Dabei stehen die roten Fruchtattribute \u00fcber dem Eichenholzfassbrand. Im Mund dann ein Feuerwerk an Kraft, Frucht, reifen Gerbstoffen und feinster L\u00e4nge, welche &#8230; <a title=\"Harlan Estate The Maiden 2005 &#8211; Napa Valley &#8211; Kalifornien \u2013 USA\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/\" aria-label=\"Mehr dazu unter Harlan Estate The Maiden 2005 &#8211; Napa Valley &#8211; Kalifornien \u2013 USA\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":152384,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[],"post_folder":[],"class_list":["post-14903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Harlan Estate The Maiden 2005 - Napa Valley - Kalifornien \u2013 USA - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Harlan Estate The Maiden 2005 - Napa Valley - Kalifornien \u2013 USA - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Der Duft dieses Rotweins vereint alle Attribute f\u00fcr die man \u00dcbersee Weine so hasst oder aber auch liebt: verschwenderische Noten von roter Gr\u00fctze mit frischer Vanillesauce, eingekochte schwarze Johannisbeeren und starke Kokosnuss Noten. Dabei stehen die roten Fruchtattribute \u00fcber dem Eichenholzfassbrand. Im Mund dann ein Feuerwerk an Kraft, Frucht, reifen Gerbstoffen und feinster L\u00e4nge, welche ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-09T08:15:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/09\/wein_feinkost_wuppertal_harlan_estate_maiden-768x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/10\\\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/10\\\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Harlan Estate The Maiden 2005 &#8211; Napa Valley &#8211; Kalifornien \u2013 USA\",\"datePublished\":\"2012-10-09T08:15:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/10\\\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\\\/\"},\"wordCount\":126,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/10\\\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/wein_feinkost_wuppertal_harlan_estate_maiden.jpg\",\"articleSection\":[\"Weine\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/10\\\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/10\\\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\\\/\",\"name\":\"Harlan Estate The Maiden 2005 - Napa Valley - Kalifornien \u2013 USA - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/10\\\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/10\\\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/wein_feinkost_wuppertal_harlan_estate_maiden.jpg\",\"datePublished\":\"2012-10-09T08:15:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/10\\\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/10\\\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/10\\\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/wein_feinkost_wuppertal_harlan_estate_maiden.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/wein_feinkost_wuppertal_harlan_estate_maiden.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2012\\\/10\\\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Harlan Estate The Maiden 2005 &#8211; Napa Valley &#8211; Kalifornien \u2013 USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Harlan Estate The Maiden 2005 - Napa Valley - Kalifornien \u2013 USA - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/","og_locale":"de_DE","og_type":"article","og_title":"Harlan Estate The Maiden 2005 - Napa Valley - Kalifornien \u2013 USA - Unterwegs mit Weine &amp; Feinkost","og_description":"Der Duft dieses Rotweins vereint alle Attribute f\u00fcr die man \u00dcbersee Weine so hasst oder aber auch liebt: verschwenderische Noten von roter Gr\u00fctze mit frischer Vanillesauce, eingekochte schwarze Johannisbeeren und starke Kokosnuss Noten. Dabei stehen die roten Fruchtattribute \u00fcber dem Eichenholzfassbrand. Im Mund dann ein Feuerwerk an Kraft, Frucht, reifen Gerbstoffen und feinster L\u00e4nge, welche ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2012-10-09T08:15:06+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/09\/wein_feinkost_wuppertal_harlan_estate_maiden-768x1024.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Harlan Estate The Maiden 2005 &#8211; Napa Valley &#8211; Kalifornien \u2013 USA","datePublished":"2012-10-09T08:15:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/"},"wordCount":126,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/09\/wein_feinkost_wuppertal_harlan_estate_maiden.jpg","articleSection":["Weine"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/","name":"Harlan Estate The Maiden 2005 - Napa Valley - Kalifornien \u2013 USA - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/09\/wein_feinkost_wuppertal_harlan_estate_maiden.jpg","datePublished":"2012-10-09T08:15:06+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/09\/wein_feinkost_wuppertal_harlan_estate_maiden.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/09\/wein_feinkost_wuppertal_harlan_estate_maiden.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2012\/10\/harlan-estate-the-maiden-2005-napa-valley-kalifornien-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Harlan Estate The Maiden 2005 &#8211; Napa Valley &#8211; Kalifornien \u2013 USA"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2012\/09\/wein_feinkost_wuppertal_harlan_estate_maiden.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-3Sn","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/14903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=14903"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/14903\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/152384"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=14903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=14903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=14903"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=14903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}