{"id":199564,"date":"2023-06-01T17:00:00","date_gmt":"2023-06-01T15:00:00","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=199564"},"modified":"2023-06-07T06:24:20","modified_gmt":"2023-06-07T04:24:20","slug":"jade-gross-rioja-spanien","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/","title":{"rendered":"Jade Gross &#8211; Rioja  &#8211; Spanien"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Wer eine Ausbildung zur Menschenrechtsanw\u00e4ltin absolviert, um dann in die K\u00fcchenwelt einzutauchen und nach dem dort erreichten Ziel als Chefk\u00f6chin im weltbekannten Restaurant Mugaritz die Kochl\u00f6ffel zu werfen, und dann eine Karriere als Winzerin startet, kann als durchaus spannende Pers\u00f6nlichkeit beschrieben werden. Hier ist von keiner geringeren als von der selbstbewussten, jungen und talentierten Jade Gross die Rede; ihres Zeichen Chinesische-Amerikanerin, aufgewachsen in Hong Kong, gelebt unter anderem in Metropolen wie New York, Sao Paulo, London, Paris, Girona und Donostia-San Sebasti\u00e1n und nun in dem Rioja Winzer Dorf San Vicente de la Sonsierra gelandet.<\/p>\n\n\n\n<p>Und hier hat kein geringerer als der Winzer Abel Mendoza Jade Gross unter seine Fittiche genommen. Diese ruhige, sympathische und erfahrene Winzer Pers\u00f6nlichkeit hat Jade Gross in die Welt der unterschiedlichen Einzellagen und diversen Anbaumethoden nebst Ausbautechniken eingeweiht. Bescheiden wie Jade ist, wei\u00df sie nat\u00fcrlich, dass es viele Jahrzehnte dauern wird, bis sie alle Geheimnisse \u00fcber den Weinbau entl\u00fcften wird, aber sie hinterfragt schon jetzt alle Prozesse, versucht sich in neuen Arbeitsschritten und wagt f\u00fcr die Weine der Anbauregion Rioja gar Ungeheuerliches, indem sie hier in dieser altehrw\u00fcrdigen und traditionellen spanischen Weinregion mehr oder weniger als erste Winzerin \u00fcberhaupt Naturweine anbaut.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:30.63864%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_5-1200x900.jpeg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_5-1200x900.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_5-1200x900.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_5-1200x900.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_5-1200x900.jpeg?strip=info&#038;w=1280&#038;ssl=1 1280w\" alt=\"\" data-height=\"960\" data-id=\"199571\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=199571#main\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_5-1200x900.jpeg\" data-width=\"1280\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_5-1200x900.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:17.11545%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_3.jpeg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_3.jpeg?strip=info&#038;w=476&#038;ssl=1 476w\" alt=\"\" data-height=\"640\" data-id=\"199572\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=199572#main\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_3.jpeg\" data-width=\"476\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_3.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:27.77154%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_7.jpeg\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_7.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_7.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_7.jpeg?strip=info&#038;w=1160&#038;ssl=1 1160w\" alt=\"\" data-height=\"960\" data-id=\"199570\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=199570#main\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_7.jpeg\" data-width=\"1160\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_7.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:24.47436%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_6.jpeg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_6.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_6.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_6.jpeg?strip=info&#038;w=1022&#038;ssl=1 1022w\" alt=\"\" data-height=\"960\" data-id=\"199569\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=199569#main\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_6.jpeg\" data-width=\"1022\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_6.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p>Alle Weine stammen aus einer Einzellage, eine mehrmalige Selektion im Weinberg ist die Grundvoraussetzung ihrer Arbeit, vor der Abf\u00fcllung erfolgt weder eine Sch\u00f6nung noch eine Filtration der Weine und auch eine zus\u00e4tzliche Schwefelung ihrer feinen Naturweine lehnt Jade entschieden ab. Seit ihrem ersten Jahrgang aus dem Jahr 2019 hat Jade Gross nun so bezaubernde vinophile Tropfen wie den Chiguita blanco, den Jabalina rosado, den Piano piano tinto, den Peace, Love &amp; Garnacha oder Harrobia tinto in Kleinstauflagen auf den Markt gebracht. F\u00fcr das Design und die Etiketten hat sie den Graphiker und Designer Javier Aramburu aus Donostia-San Sebasti\u00e1n gewinnen k\u00f6nnen. Welch eine Kombination des guten Geschmacks und der individuellen Herangehensweise an das Produkt Wein und seinem faszinierenden Terroir.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:60.00080%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_2.jpeg\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_2.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_2.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_2.jpeg?strip=info&#038;w=960&#038;ssl=1 960w\" alt=\"\" data-height=\"960\" data-id=\"199573\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=199573#main\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_2.jpeg\" data-width=\"960\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_2.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:39.99920%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_1-682x1024.jpeg\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_1-682x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_1-682x1024.jpeg?strip=info&#038;w=853&#038;ssl=1 853w\" alt=\"\" data-height=\"1280\" data-id=\"199574\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=199574#main\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_1-682x1024.jpeg\" data-width=\"853\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_1-682x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p><strong>Und hier geht es zu den Weinen vom Weingut Jade Gross -> <\/strong><a href=\"https:\/\/www.weine-feinkost.de\/shop\/Jade-Gross\/\">https:\/\/www.weine-feinkost.de\/shop\/Jade-Gross\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer eine Ausbildung zur Menschenrechtsanw\u00e4ltin absolviert, um dann in die K\u00fcchenwelt einzutauchen und nach dem dort erreichten Ziel als Chefk\u00f6chin im weltbekannten Restaurant Mugaritz die Kochl\u00f6ffel zu werfen, und dann eine Karriere als Winzerin startet, kann als durchaus spannende Pers\u00f6nlichkeit beschrieben werden. Hier ist von keiner geringeren als von der selbstbewussten, jungen und talentierten Jade &#8230; <a title=\"Jade Gross &#8211; Rioja  &#8211; Spanien\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/\" aria-label=\"Mehr dazu unter Jade Gross &#8211; Rioja  &#8211; Spanien\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":199568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[16],"tags":[3389,313,3390,829,79,1738],"post_folder":[],"class_list":["post-199564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weingueter","tag-jade-gross","tag-rioja","tag-rosewein","tag-rotwein","tag-spanien","tag-weisswein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jade Gross - Rioja - Spanien - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jade Gross - Rioja - Spanien - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Wer eine Ausbildung zur Menschenrechtsanw\u00e4ltin absolviert, um dann in die K\u00fcchenwelt einzutauchen und nach dem dort erreichten Ziel als Chefk\u00f6chin im weltbekannten Restaurant Mugaritz die Kochl\u00f6ffel zu werfen, und dann eine Karriere als Winzerin startet, kann als durchaus spannende Pers\u00f6nlichkeit beschrieben werden. Hier ist von keiner geringeren als von der selbstbewussten, jungen und talentierten Jade ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-01T15:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-07T04:24:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Jade Gross &#8211; Rioja &#8211; Spanien\",\"datePublished\":\"2023-06-01T15:00:00+00:00\",\"dateModified\":\"2023-06-07T04:24:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Jade_Gross_Rioja_Spanien_4.jpeg\",\"keywords\":[\"Jade Gross\",\"Rioja\",\"Rosewein\",\"Rotwein\",\"Spanien\",\"Wei\u00dfwein\"],\"articleSection\":[\"Weing\u00fcter\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/\",\"name\":\"Jade Gross - Rioja - Spanien - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Jade_Gross_Rioja_Spanien_4.jpeg\",\"datePublished\":\"2023-06-01T15:00:00+00:00\",\"dateModified\":\"2023-06-07T04:24:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Jade_Gross_Rioja_Spanien_4.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Jade_Gross_Rioja_Spanien_4.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/06\\\/jade-gross-rioja-spanien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jade Gross &#8211; Rioja &#8211; Spanien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jade Gross - Rioja - Spanien - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/","og_locale":"de_DE","og_type":"article","og_title":"Jade Gross - Rioja - Spanien - Unterwegs mit Weine &amp; Feinkost","og_description":"Wer eine Ausbildung zur Menschenrechtsanw\u00e4ltin absolviert, um dann in die K\u00fcchenwelt einzutauchen und nach dem dort erreichten Ziel als Chefk\u00f6chin im weltbekannten Restaurant Mugaritz die Kochl\u00f6ffel zu werfen, und dann eine Karriere als Winzerin startet, kann als durchaus spannende Pers\u00f6nlichkeit beschrieben werden. Hier ist von keiner geringeren als von der selbstbewussten, jungen und talentierten Jade ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2023-06-01T15:00:00+00:00","article_modified_time":"2023-06-07T04:24:20+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_4.jpeg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Jade Gross &#8211; Rioja &#8211; Spanien","datePublished":"2023-06-01T15:00:00+00:00","dateModified":"2023-06-07T04:24:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_4.jpeg","keywords":["Jade Gross","Rioja","Rosewein","Rotwein","Spanien","Wei\u00dfwein"],"articleSection":["Weing\u00fcter"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/","name":"Jade Gross - Rioja - Spanien - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_4.jpeg","datePublished":"2023-06-01T15:00:00+00:00","dateModified":"2023-06-07T04:24:20+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_4.jpeg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_4.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/06\/jade-gross-rioja-spanien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Jade Gross &#8211; Rioja &#8211; Spanien"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/05\/Jade_Gross_Rioja_Spanien_4.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-PUM","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/199564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=199564"}],"version-history":[{"count":4,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/199564\/revisions"}],"predecessor-version":[{"id":199911,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/199564\/revisions\/199911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/199568"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=199564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=199564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=199564"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=199564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}