{"id":200806,"date":"2023-07-23T14:30:00","date_gmt":"2023-07-23T12:30:00","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=200806"},"modified":"2023-07-23T14:22:36","modified_gmt":"2023-07-23T12:22:36","slug":"salatherz-anchovis-walnuss-kaese-tapa","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/","title":{"rendered":"Salatherz Anchovis Walnuss K\u00e4se Tapa"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">K\u00f6stliche Tapa mit K\u00e4secreme und Anchovis &#8211; Mediterraner Genuss zum Verlieben!<\/h2>\n\n\n\n<p class=\"has-drop-cap\">Diese k\u00f6stliche Tapa wird aus einer Vielzahl bester Zutaten zubereitet, die perfekt miteinander harmonieren. F\u00fcr die Zubereitung ben\u00f6tigst du ein frisches Salatherz, eine hochwertige Anchovis, cremigen Frischk\u00e4se,  Blauschimmelk\u00e4se, knackige Waln\u00fcsse, Wei\u00dfweinessig, hochwertiges Extra Virgin Oliven\u00f6l sowie eine Prise Salz und Pfeffer f\u00fcr die perfekte W\u00fcrze.<\/p>\n\n\n\n<p>Beginnen wir mit der Zubereitung der herzhaften K\u00e4secreme. Hierf\u00fcr vermischen wir den Frischk\u00e4se und den Blauschimmelk\u00e4se im Verh\u00e4ltnis von 2\/3 zu 1\/3 in einer Sch\u00fcssel. Die Mischung wird dann mit zersto\u00dfenen Waln\u00fcssen verfeinert, die dem Ganzen einen nussigen Geschmack verleihen.<\/p>\n\n\n\n<p>Um das Aroma der K\u00e4secreme zu intensivieren, geben wir einen gro\u00dfz\u00fcgigen Schuss Wei\u00dfweinessig hinzu, der eine herrliche S\u00e4urenote beisteuert. Hochwertiges Extra Virgin Oliven\u00f6l rundet die Masse ab. Je nach pers\u00f6nlichem Geschmack wird die K\u00e4secreme dann leicht mit Salz und Pfeffer gew\u00fcrzt, um alle Aromen perfekt auszubalancieren.<\/p>\n\n\n\n<p>Nun geht es ans Anrichten! Wir nehmen ein frisches Salatblatt und verteilen gro\u00dfz\u00fcgig unsere aromatische K\u00e4secreme darauf. Dann kr\u00f6nen wir sie mit der Anchovis, die mit ihrem leicht salzigen Charakter perfekt mit der Creme harmoniert. Und schon ist die Tapa fertig!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_1-768x1024.jpg\" alt=\"\" class=\"wp-image-200808\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_1-768x1024.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_1-225x300.jpg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_1.jpg 960w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\">  <\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_2-768x1024.jpg\" alt=\"\" class=\"wp-image-200809\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_2-768x1024.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_2-225x300.jpg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_2.jpg 960w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\"> <\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_4-768x1024.jpg\" alt=\"\" class=\"wp-image-200811\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_4-768x1024.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_4-225x300.jpg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_4.jpg 960w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\"> <\/figcaption><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>K\u00f6stliche Tapa mit K\u00e4secreme und Anchovis &#8211; Mediterraner Genuss zum Verlieben! Diese k\u00f6stliche Tapa wird aus einer Vielzahl bester Zutaten zubereitet, die perfekt miteinander harmonieren. F\u00fcr die Zubereitung ben\u00f6tigst du ein frisches Salatherz, eine hochwertige Anchovis, cremigen Frischk\u00e4se, Blauschimmelk\u00e4se, knackige Waln\u00fcsse, Wei\u00dfweinessig, hochwertiges Extra Virgin Oliven\u00f6l sowie eine Prise Salz und Pfeffer f\u00fcr die perfekte &#8230; <a title=\"Salatherz Anchovis Walnuss K\u00e4se Tapa\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/\" aria-label=\"Mehr dazu unter Salatherz Anchovis Walnuss K\u00e4se Tapa\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":200812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[17,65],"tags":[383,1268,227,3447,160,1116],"post_folder":[],"class_list":["post-200806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezepte","category-tapa","tag-anchovis","tag-kaese","tag-pintxo","tag-salatherz","tag-tapa","tag-walnuss"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salatherz Anchovis Walnuss K\u00e4se Tapa - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salatherz Anchovis Walnuss K\u00e4se Tapa - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"K\u00f6stliche Tapa mit K\u00e4secreme und Anchovis &#8211; Mediterraner Genuss zum Verlieben! Diese k\u00f6stliche Tapa wird aus einer Vielzahl bester Zutaten zubereitet, die perfekt miteinander harmonieren. F\u00fcr die Zubereitung ben\u00f6tigst du ein frisches Salatherz, eine hochwertige Anchovis, cremigen Frischk\u00e4se, Blauschimmelk\u00e4se, knackige Waln\u00fcsse, Wei\u00dfweinessig, hochwertiges Extra Virgin Oliven\u00f6l sowie eine Prise Salz und Pfeffer f\u00fcr die perfekte ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-23T12:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Salatherz Anchovis Walnuss K\u00e4se Tapa\",\"datePublished\":\"2023-07-23T12:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/\"},\"wordCount\":220,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_5.jpg\",\"keywords\":[\"Anchovis\",\"K\u00e4se\",\"Pintxo\",\"Salatherz\",\"Tapa\",\"Walnuss\"],\"articleSection\":[\"Rezepte\",\"Viva la TAPA\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/\",\"name\":\"Salatherz Anchovis Walnuss K\u00e4se Tapa - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_5.jpg\",\"datePublished\":\"2023-07-23T12:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_5.jpg\",\"width\":960,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/07\\\/salatherz-anchovis-walnuss-kaese-tapa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salatherz Anchovis Walnuss K\u00e4se Tapa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salatherz Anchovis Walnuss K\u00e4se Tapa - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/","og_locale":"de_DE","og_type":"article","og_title":"Salatherz Anchovis Walnuss K\u00e4se Tapa - Unterwegs mit Weine &amp; Feinkost","og_description":"K\u00f6stliche Tapa mit K\u00e4secreme und Anchovis &#8211; Mediterraner Genuss zum Verlieben! Diese k\u00f6stliche Tapa wird aus einer Vielzahl bester Zutaten zubereitet, die perfekt miteinander harmonieren. F\u00fcr die Zubereitung ben\u00f6tigst du ein frisches Salatherz, eine hochwertige Anchovis, cremigen Frischk\u00e4se, Blauschimmelk\u00e4se, knackige Waln\u00fcsse, Wei\u00dfweinessig, hochwertiges Extra Virgin Oliven\u00f6l sowie eine Prise Salz und Pfeffer f\u00fcr die perfekte ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2023-07-23T12:30:00+00:00","og_image":[{"width":960,"height":1280,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_5.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Salatherz Anchovis Walnuss K\u00e4se Tapa","datePublished":"2023-07-23T12:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/"},"wordCount":220,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_5.jpg","keywords":["Anchovis","K\u00e4se","Pintxo","Salatherz","Tapa","Walnuss"],"articleSection":["Rezepte","Viva la TAPA"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/","name":"Salatherz Anchovis Walnuss K\u00e4se Tapa - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_5.jpg","datePublished":"2023-07-23T12:30:00+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_5.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_5.jpg","width":960,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/07\/salatherz-anchovis-walnuss-kaese-tapa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Salatherz Anchovis Walnuss K\u00e4se Tapa"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/07\/Salatherz_Anchovis_Walnuss_Kaese_Tapa_5.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-QeO","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/200806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=200806"}],"version-history":[{"count":3,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/200806\/revisions"}],"predecessor-version":[{"id":200817,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/200806\/revisions\/200817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/200812"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=200806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=200806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=200806"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=200806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}