{"id":201922,"date":"2023-10-22T17:00:00","date_gmt":"2023-10-22T15:00:00","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=201922"},"modified":"2024-04-17T15:43:22","modified_gmt":"2024-04-17T13:43:22","slug":"das-weinland-portugal","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/","title":{"rendered":"Das Weinland Portugal"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Portugals Weinvielfalt: Eine Reise durch Zeit, Tradition und einzigartige Aromen<\/h2>\n\n\n\n<p>Hier sprechen die Statistiken f\u00fcr sich: zwar liegt Portugal mit einer Gesamtrebfl\u00e4che von 195 000 Hektar nur auf Platz neun der Weltrangliste &#8211; was sich allerdings schnell relativiert, wenn man das in Bezug zur ziemlich geringen Gr\u00f6\u00dfe des nach wie vor landschaftlich urt\u00fcmlichen, agrarisch gepr\u00e4gten Landes setzt. Und mit \u00fcber 60 Litern pro Kopf trinken die Portugiesen j\u00e4hrlich so viel Wein wie kein anderes Volk auf der Welt. Das ist kein Wunder, denn zu der verbreiteten Ausgeh-Kultur und der \u00e4u\u00dferst vielf\u00e4ltigen K\u00fcche passt ein guter Tropfen immer. Ob zum portugiesischen Nationalgericht, dem Bacalhau genannten getrockneten und eingesalzenen Kabeljau, oder anderen K\u00fcstengerichten wie gegrillten Sardinen, Taschenkrebsen oder Muscheleint\u00f6pfen aus dem traditionellen Cataplana-Kochtopf &#8211; ein spritziger Wei\u00dfwein aus dem Norden des Landes passt immer. Gehaltvoll-trockene Rotweine, etwa von den gebirgigen Granitb\u00f6den D\u00e3os im Landesinneren, harmonieren hingegen perfekt mit dem omnipr\u00e4senten Rindersteak, aber auch mit dem ehemaligen Arme-Leute-Essen Feijoadas, einem deftigen Bohneneintopf mit Einlage aus Schweineohren, -schwanz und -f\u00fc\u00dfen. Da in der Landesk\u00fcche, au\u00dfer mit dem allseits beliebten Koriander und hin und wieder mit der scharfen Chilischote Piri Piri nicht allzu ausgiebig gew\u00fcrzt wird, sind charakterstarke Speisebegleiter umso wichtiger.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/capa-tras-Kopie-1200x900.jpg\" alt=\"\" class=\"wp-image-201927\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/capa-tras-Kopie-1200x900.jpg 1200w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/capa-tras-Kopie-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/capa-tras-Kopie-768x576.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/capa-tras-Kopie.jpg 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>Wie die meisten Mittelmeer-Anrainerstaaten profitierte das Land zuerst vom Know-how der Ph\u00f6nizier und Griechen, sp\u00e4ter auch der R\u00f6mer, die sich in K\u00fcstenn\u00e4he ansiedelten und im Hinterland die ersten Reben zogen. In ihrer Mythologie malten sich die R\u00f6mer gar eine Abstammung der einheimischen Lusitanier vom Sohn des Weingottes Bacchus aus. So selbstverst\u00e4ndlich der Weinbau allerdings in den Hochkulturen der Antike verankert war, so radikal wurde er bek\u00e4mpft, als ab dem 8. Jahrhundert die muslimischen Mauren von Nordafrika her auf die Iberische Halbinsel vordrangen. Weinberge wurden zwar nicht vollst\u00e4ndig vernichtet, sondern oft f\u00fcr den Anbau von Rosinen weiterbetrieben, das reichhaltige Wissen um Kellertechnik allerdings versank vorerst im Dunkel der Geschichte. Erst einige Jahrhunderte sp\u00e4ter, nach der R\u00fcckeroberung durch christliche Herrscher, bem\u00fchten sich M\u00f6nchsorden wie die Zisterzienser um eine Renaissance. Diese Entwicklung, die sich parallel auch in anderen Teilen Europas wie etwa dem Burgund oder dem Rheingau vollzog, erf\u00fcllte zun\u00e4chst eher praktische Anspr\u00fcche: man bedurfte des Weines zur Feier des Messopfers. Schnell wurden aber weltliche Herren, eher die geistige als die geistliche Wirkung sch\u00e4tzend, auf den neuen Wirtschaftszweig aufmerksam und f\u00f6rderten ihn nach Kr\u00e4ften &#8211; nicht nur f\u00fcr den eigenen Genuss, sondern auch als beliebtes Exportgut, das den Aufstieg des kleinen Portugals zur einflussreichen Seefahrernation wahrscheinlich erst erm\u00f6glichte. Den gr\u00f6\u00dften Sprung dorthin wagte man Anfang des 14. Jahrhunderts ausgerechnet unter einem K\u00f6nig mit dem Namen Dionysius.<\/p>\n\n\n\n<p>Als kluge Strategen machen sich die Portugiesen in der Geschichte ein ums andere Mal Streitereien ihrer Nachbarn zunutze: so etwa, als England mal wieder im Clinch mit Frankreich liegt und dessen Weine mit astronomischen Einfuhrz\u00f6llen belegt. Hier beginnt die Erfolgsstory der wohl bekanntesten portugiesischen Weine &#8211; die eigentlich gar keine Weine im klassischen Sinne sind, sondern Lik\u00f6re, oder, wie die nach ihnen verr\u00fcckten Engl\u00e4nder sie nannten, \u201efortified\u201c, also verst\u00e4rkte Weine. Ebendies mussten sie aber auch sein, um den langen Transport zu \u00fcberstehen, ohne ungenie\u00dfbar zu werden. Die M\u00f6nche f\u00fcgten dem Most also Neutralalkohol hinzu &#8211; dessen Herstellung sie ironischerweise von den muslimischen Invasoren \u00fcbernommen hatten, die damit Duftstoffe anfertigten. Ein Nebeneffekt der Aufspritung war allerdings, dass dadurch die G\u00e4rung des Mostes abrupt gestoppt wurde &#8211; und der bisher noch unvergorene Zucker erhalten blieb, was den Wein zwangsl\u00e4ufig s\u00fc\u00df machte. Eine Region, die sich schon sehr bald als optimal f\u00fcr die Herstellung des edlen Tropfens erwies, war das durch seine Windungen und Steilh\u00e4nge ein wenig an die Mosel erinnernde Douro-Tal im Nordosten Portugals, heute UNESCO-Welterbe. Mit kleinen Booten, den Rabelos, brachte man die F\u00e4sser schlie\u00dflich den Fluss hinab in die Hafenstadt Porto &#8211; daher auch der Name. Hier gr\u00fcndeten im Laufe der Zeit vor allem Engl\u00e4nder, aber auch Niederl\u00e4nder und Deutsche Handelsniederlassungen, die einen direkten Transport in ihre Heimatl\u00e4nder organisierten. Alle diese Portweine waren damals \u201etawny\u201c, also haupts\u00e4chlich im Fass gereift, wo sie oxidierten und nussige Aromen annahmen. Heutzutage haben sich auch \u201eruby\u201c-Ports etabliert, die gr\u00f6\u00dftenteils in der Flasche reifen und sich aufgrund der langsameren Alterung ein fruchtiges Bukett erhalten. Durch den hohen Zuckergehalt und Alkohol um die 20 Volumenprozent ist Portwein lange lagerf\u00e4hig, was die mit einem Jahrgang versehenen Vintage-Editionen zu raren Sammlerobjekten macht. Hin und wieder tauchen sogar mal Flaschen aus der Zeit um 1756 auf, als der umtriebige Ministerpr\u00e4sident Marqu\u00eas de Pombal das Gebiet mit Grenzsteinen abstecken lie\u00df und damit eine der ersten gesch\u00fctzten Herkunftsregionen der Welt begr\u00fcndete.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/2-dia024-Kopie-1200x800.jpg\" alt=\"\" class=\"wp-image-201928\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/2-dia024-Kopie-1200x800.jpg 1200w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/2-dia024-Kopie-300x200.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/2-dia024-Kopie-768x512.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/2-dia024-Kopie.jpg 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>Zu dieser Zeit, im 18. und 19. Jahrhundert, spielen \u201eklassische\u201c Weine mit regul\u00e4rem Alkoholgehalt f\u00fcr das Renommee Portugals so gut wie keine Rolle. Diese konsumierte man haupts\u00e4chlich im Inland, was allerdings ebenso wie der Export erst mit dem Mehltau, dann mit der Reblauskatastrophe ein j\u00e4hes Ende fand: fast der gesamte wertvolle Bestand wurde vernichtet. Einzig im Gebiet Colares in der N\u00e4he der Stadt Sintra finden sich noch wurzelechte Rebst\u00f6cke der seltenen Sorte Ramisco: auf den tiefen Sandb\u00f6den konnten sich die Rebl\u00e4use nicht fortbewegen. Fast 50 Jahre dauerte es, bis einige mutige Winzergenossenschaften &#8211; die heute in der Organisation des portugiesischen Weinbaus noch immer eine gro\u00dfe Rolle spielen &#8211; die Initiative ergriffen und mit dem fl\u00e4chendeckenden Wiederaufbau begannen. Unter der anschlie\u00dfenden autokratischen Regierung Salazars hatte der Weinbau allerdings keinen guten Stand: der Zugang zu internationalen Absatzm\u00e4rkten fehlte, die Branche wurde nicht gef\u00f6rdert und befand sich technisch auf einem hoffnungslos veralteten Stand. Das Resultat waren herbe, sehr alkoholreiche Rotweine ohne jede Finesse. Doch diese lange Durststrecke, die erst mit der Aufnahme in die EU Mitte der 80er endete, barg auch einige Vorteile f\u00fcr das Land: anders als in vielen anderen Weinbaunationen importierte man nicht massenhaft franz\u00f6sische Reben und zerst\u00f6rte damit eine historisch gewachsene Weinkultur. Statt also auf Merlot, Sauvignon Blanc, Chardonnay und Co. zu setzen, blieben \u00fcber 250 autochthone Rebsorten erhalten &#8211; die sogenannten \u201eCastas\u201c, deren Namen selbst weintechnisch Bewanderten oft nur ein Achselzucken entlocken. Einige von ihnen werden im ganzen Land angebaut, andere hingegen finden sich nur punktuell auf kleinen Fl\u00e4chen, wo eine einzigartige Kombination aus Bodenbeschaffenheit und Mikroklima die perfekte \u00f6kologische Nische f\u00fcr sie bereith\u00e4lt. Zu den Platzhirschen aufseiten der roten Trauben z\u00e4hlt auf jeden Fall die Touriga Nacional &#8211; mit der tiefdunklen Farbe, dem hohen Alkoholgehalt, der gewaltigen Tanninstruktur und dem vollmundigen, harzig-w\u00fcrzigen Geschmack quasi eine iberische Traube schlechthin. Ein gro\u00dfer Teil geht in die Portwein-Produktion, wenn aber Rotweine aus ihr gekeltert werden, ist das Potential f\u00fcr Spitzenerzeugnisse mit jahrzehntelanger Lagerf\u00e4higkeit hoch. Wie bei vielen \u201ealten Sorten\u201c bleibt der Ertrag eher gering, daf\u00fcr ist allerdings die Resistenz gegen Krankheiten, Sch\u00e4dlinge und Umwelteinfl\u00fcsse relativ hoch &#8211; zunutze macht sich das seit 2021 das franz\u00f6sische Bordeaux, wo die Touriga Nacional dank ihrer Hitzetoleranz neu zugelassen wurde. Eine weitere wichtige Rolle spielt der Tempranillo, den man hier eher unter den Namen Tinta Roriz oder Aragonez kennt. Er gilt als vergleichsweise feinduftig mild und ist die meistverbreitete Rebe im Land &#8211; allerdings mit gerade einmal 17 000 Hektar, was als Beleg daf\u00fcr gelten kann, wie ungeheuer vielf\u00e4ltig das portugiesische Trauben-Portfolio ist. Als besondere Spezialit\u00e4t gilt der Baga, eine robuste Rebe, die sich in ihrer Jugend aufgrund aggressiver S\u00e4ure und bitter-pelziger Tannine oft als nahezu untrinkbar erweist, nach langj\u00e4hriger Flaschenreife aber wunderbar elegante Weine mit einem delikaten Pflaumen- oder Cassis-Aroma und w\u00fcrzig-tabakigen Noten hervorbringt.<\/p>\n\n\n\n<p>Das Land verf\u00fcgt allerdings nicht nur \u00fcber begehrte Rebensch\u00e4tze, sondern auch \u00fcber das global gr\u00f6\u00dfte Vorkommen einer anderen Pflanze, die f\u00fcr die Weinwelt (noch) von zentraler Bedeutung ist: die Korkeiche. Fast ein Drittel der weltweiten Best\u00e4nde finden sich hier auf 750 000 Hektar, jeder zweite Korken stammt aus Portugal. Im Alter von 12 bis 15 Jahren werden die B\u00e4ume zum ersten Mal entrindet, was sich dann im Durchschnitt alle zehn Jahre wiederholt, um ihnen genug Zeit zu geben, die drei bis vier Zentimeter dicke Borke erneut zu bilden. Da sie bereits abgestorben ist, nimmt der Baum keinerlei Schaden und kann in seiner Lebensspanne bis zu 200 Kilo Ertrag liefern. Der sich immer fl\u00e4chendeckender durchsetzende Trend hin zu Schraubverschl\u00fcssen oder anderen maschinell erzeugten L\u00f6sungen allerdings gef\u00e4hrdet inzwischen nicht nur die Baumbest\u00e4nde selbst, sondern auch die hohe Artenvielfalt, die durch sie gew\u00e4hrleistet wird: gegen die immer h\u00e4ufiger auftretenden Waldbr\u00e4nde sind sie dank ihrer dicken Rinde immun und stellen so faktisch eine optimale Fauna in Zeiten des Klimawandels dar.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/Quinta-do-Mouro-26-Kopie-2-1200x800.jpg\" alt=\"\" class=\"wp-image-201929\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/Quinta-do-Mouro-26-Kopie-2-1200x800.jpg 1200w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/Quinta-do-Mouro-26-Kopie-2-300x200.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/Quinta-do-Mouro-26-Kopie-2-768x512.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/Quinta-do-Mouro-26-Kopie-2.jpg 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>Besonders pr\u00e4sent sind die knorrigen Zeitgenossen mit ihrer ausladenden Krone, unter denen sich umherstreifende Schweine oft an den herabfallenden Eicheln m\u00e4sten, im S\u00fcden des Landes, wo der Weinbau nicht ganz so ausgepr\u00e4gt ist. Ansonsten verteilen sich die 14 Weinregionen recht gleichm\u00e4\u00dfig \u00fcber die gesamte Fl\u00e4che. Die bekanntesten sind das Douro-Tal, dessen Schieferb\u00f6den komplexe Rotweine hervorbringen, und Alentejo, wo die lehmigen Untergr\u00fcnde dem Rebensaft Frucht und F\u00fclle verleihen. Beide sind eher kontinental gepr\u00e4gt und deutlich mehr der Hitze ausgesetzt als jene Regionen in K\u00fcstenn\u00e4he, wo Atlantik oder Mittelmeer f\u00fcr viele Niederschl\u00e4ge und eine sanfte Regulation der Temperaturen sorgen. Ein Beispiel ist das Gebiet Rios do Minho, wo auf kargen Granitb\u00f6den der portugiesische Wein schlechthin, der Vinho Verde, produziert wird, der f\u00fcr viele Portugiesen geradezu den Charakter eines Erfrischungsgetr\u00e4nks hat. F\u00fcr den \u201egr\u00fcnen Wein\u201c liest man noch nicht voll ausgereifte Trauben, was sich im Endprodukt durch den geringen Alkoholgehalt und das leichte Moussieren bemerkbar macht, das bei der zweiten G\u00e4rung entsteht, wenn die enthaltene Apfels\u00e4ure abgebaut und in Kohlens\u00e4ure umgewandelt wird. Wie bei den meisten portugiesischen Weinen handelt es sich beim Vinho Verde, von dem es \u00fcbrigens auch eine rote, sehr gerbstoffreiche Variante gibt, um eine Cuv\u00e9e aus verschiedenen Rebsorten. Den gr\u00f6\u00dften Anteil daran hat der bekannte Alvarinho. Obwohl der Name und die Legende besagen, dass es sich bei ihm um einen einen vom Rhein stammenden, mit dem Riesling verwandten Wei\u00dfwein handelt, ist die Traube h\u00f6chstwahrscheinlich heimischen Ursprungs &#8211; auch wenn der Vergleich zum Riesling aufgrund der S\u00e4urebetontheit und zitrisch unterlegten Gr\u00fcnfruchtigkeit durchaus naheliegend ist. Seine Hitzetoleranz ist vergleichsweise hoch, sodass auch er mittlerweile in Bordeaux angebaut werden darf, allerdings gehen die portugiesischen Winzer gern auf Nummer sicher und ziehen die Reben bevorzugt auf Pergolen, wo sie einerseits vor direkter Sonneneinstrahlung gesch\u00fctzt sind und andererseits genug Freiraum haben, um die hohe Luftfeuchtigkeit verdunsten zu k\u00f6nnen und nicht zu faulen. Als Verschnittpartner eignen sich besonders die alkohol- und k\u00f6rperreiche Trajadura und der Loureiro mit seinem hocharomatischen Bukett. Andere vielversprechende wei\u00dfe Reben sind etwa der im ganzen Land verbreitete Bical, der mit seinem feinen Spiel aus barocker Aromenf\u00fclle und rassiger S\u00e4ure hohes Reifepotential besitzt und auch gern f\u00fcr die Schaumweinproduktion genutzt wird. Oder der meistangebaute Wei\u00dfe, der Fern\u00e3o Pires &#8211; dank seiner Ausgewogenheit zwischen S\u00e4ure und Frucht bei recht hohem Alkoholgehalt und &#8211; je nach Boden &#8211; hohem Mostgewicht ein echter Allrounder, der als stiller Verschnittpartner ebenso eine gute Figur macht wie als Grundlage f\u00fcr feine Schaum- und S\u00fc\u00dfweine. Keineswegs vergessen sollte man, dass auch au\u00dferhalb des Festlandes Weinbau betrieben wird: auf den im Atlantik gelegenen Azoren und Madeira. Auf ersteren gedeihen die Reben, besonders der wei\u00dfe Verdelho, auf tiefschwarzen, als perfekter W\u00e4rmespeicher fungierenden Vulkanb\u00f6den in direkter N\u00e4he zum Ozean, was ihnen eine expressive, salzig-mineralische und s\u00e4urebetonte Aromatik verleiht. Madeiraweine hingegen werden auf \u00e4hnliche Weise hergestellt wie Portwein &#8211; mit einem Unterschied: f\u00fcr seine Entwicklung spielt Hitze eine gro\u00dfe Rolle. Nachdem Matrosen eher zuf\u00e4llig bemerkt hatten, dass der Wein auf einer Schiffsreise durch die Tropen geschmacklich stark profitiert hatte, wurde er in der Folge ganz gezielt in \u00dcberseeprovinzen wie Macau oder Angola und wieder zur\u00fcck geschippert. Obwohl es ihn vom trockenen Sercial \u00fcber den feinherben Boal bis zum s\u00fc\u00dfen Malvasia in etlichen Stilrichtungen gibt, wird er heutzutage eher selten pur genossen &#8211; daf\u00fcr sch\u00e4tzt man ihn aber als Zutat der gehobenen K\u00fcche, etwa in der ber\u00fchmten Madeirasauce. Text: Dario Sellmeier<\/p>\n\n\n\n<p>Anders als viele andere europ\u00e4ische Weinbaunationen, die in den vergangenen 20 bis 30 Jahren stagnierten oder sogar an Rebfl\u00e4che verloren, ging es f\u00fcr Portugal steil bergauf. Das h\u00e4ngt auch damit zusammen, dass der Klimawandel f\u00fcr das Land eher Segen als Fluch ist und das fr\u00fcher von Jahr zu Jahr stark schwankende Qualit\u00e4tsniveau durch die nun durchgehend hei\u00dfen Sommer auf ein konstant hohes Level gehoben wurde. Hinzu kommt der hohe Bestand an sogenannten \u201eVinhas Velhas\u201c, uralter, teils vor \u00fcber 100 Jahren gepflanzter Rebst\u00f6cke, die sich im ganzen Land finden und eine zwar geringe, daf\u00fcr aber geschmacklich unvergleichliche Ausbeute liefern. Man darf sich von den billigen, rests\u00fc\u00dfen und \u00fcberschwefelten Vinho Verdes und den massenhaft produzierten Ros\u00e9s in auff\u00e4lligen Bocksbeutelflaschen also nicht t\u00e4uschen lassen &#8211; Portugal ist viel mehr als das. Von frischen Jungweinen, den \u201eVerdes\u201c, \u00fcber gehaltvolle, tanninbetonte \u201eMaduros\u201c bis hin zu den mindestens zehn Jahre gereiften, vielschichtigen \u201eGarrafeiras\u201c findet sich hier f\u00fcr jeden Gaumen etwas. Zudem gelten die Weine angesichts ihrer durchweg soliden bis au\u00dfergew\u00f6hnlichen Qualit\u00e4t im internationalen Vergleich nach wie vor als sehr g\u00fcnstig. Die nach alter Sitte im gemischten Satz gekelterten Rotweine vom Douro sind dabei ebenso spannende Entdeckungen wie die zu Unrecht immer etwas im Schatten von Port und Madeira stehenden S\u00fc\u00dfweine von Set\u00fabal oder die experimentierfreudige junge Weinszene am Tejo, wo man sich seit einiger Zeit dem Assemblieren alter, heimischer Reben mit den international gel\u00e4ufigen franz\u00f6sischen verschrieben hat. Einen Versuch ist die ungeheuer abwechslungsreiche Weinkultur Portugals, diese sympathische Synthese aus stolzem Traditionsbewusstsein und optimistischer Zukunftsorientierung mit einem Schuss iberischer Verwegenheit, definitiv wert!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Portugals Weinvielfalt: Eine Reise durch Zeit, Tradition und einzigartige Aromen Hier sprechen die Statistiken f\u00fcr sich: zwar liegt Portugal mit einer Gesamtrebfl\u00e4che von 195 000 Hektar nur auf Platz neun der Weltrangliste &#8211; was sich allerdings schnell relativiert, wenn man das in Bezug zur ziemlich geringen Gr\u00f6\u00dfe des nach wie vor landschaftlich urt\u00fcmlichen, agrarisch gepr\u00e4gten &#8230; <a title=\"Das Weinland Portugal\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/\" aria-label=\"Mehr dazu unter Das Weinland Portugal\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":201926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[1709,1661,863,3567,3565,850,3566,3570,3569],"post_folder":[],"class_list":["post-201922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weinwissen","tag-bairrada","tag-dao","tag-douro","tag-historischerebsorten","tag-korkeiche-weinregionenportugals","tag-portugal","tag-portugiesischerwein","tag-portwein","tag-weinkultur"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das Weinland Portugal - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das Weinland Portugal - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Portugals Weinvielfalt: Eine Reise durch Zeit, Tradition und einzigartige Aromen Hier sprechen die Statistiken f\u00fcr sich: zwar liegt Portugal mit einer Gesamtrebfl\u00e4che von 195 000 Hektar nur auf Platz neun der Weltrangliste &#8211; was sich allerdings schnell relativiert, wenn man das in Bezug zur ziemlich geringen Gr\u00f6\u00dfe des nach wie vor landschaftlich urt\u00fcmlichen, agrarisch gepr\u00e4gten ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-22T15:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-17T13:43:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/niepoort_napoles_terrasse-Kopie-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1059\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Das Weinland Portugal\",\"datePublished\":\"2023-10-22T15:00:00+00:00\",\"dateModified\":\"2024-04-17T13:43:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/\"},\"wordCount\":2351,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/niepoort_napoles_terrasse-Kopie-2.jpg\",\"keywords\":[\"Bairrada\",\"Dao\",\"Douro\",\"HistorischeRebsorten\",\"Korkeiche WeinregionenPortugals\",\"Portugal\",\"PortugiesischerWein\",\"Portwein\",\"Weinkultur\"],\"articleSection\":[\"Weinwissen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/\",\"name\":\"Das Weinland Portugal - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/niepoort_napoles_terrasse-Kopie-2.jpg\",\"datePublished\":\"2023-10-22T15:00:00+00:00\",\"dateModified\":\"2024-04-17T13:43:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/niepoort_napoles_terrasse-Kopie-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/niepoort_napoles_terrasse-Kopie-2.jpg\",\"width\":2500,\"height\":1059},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2023\\\/10\\\/das-weinland-portugal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das Weinland Portugal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das Weinland Portugal - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/","og_locale":"de_DE","og_type":"article","og_title":"Das Weinland Portugal - Unterwegs mit Weine &amp; Feinkost","og_description":"Portugals Weinvielfalt: Eine Reise durch Zeit, Tradition und einzigartige Aromen Hier sprechen die Statistiken f\u00fcr sich: zwar liegt Portugal mit einer Gesamtrebfl\u00e4che von 195 000 Hektar nur auf Platz neun der Weltrangliste &#8211; was sich allerdings schnell relativiert, wenn man das in Bezug zur ziemlich geringen Gr\u00f6\u00dfe des nach wie vor landschaftlich urt\u00fcmlichen, agrarisch gepr\u00e4gten ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2023-10-22T15:00:00+00:00","article_modified_time":"2024-04-17T13:43:22+00:00","og_image":[{"width":2500,"height":1059,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/niepoort_napoles_terrasse-Kopie-2.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Das Weinland Portugal","datePublished":"2023-10-22T15:00:00+00:00","dateModified":"2024-04-17T13:43:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/"},"wordCount":2351,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/niepoort_napoles_terrasse-Kopie-2.jpg","keywords":["Bairrada","Dao","Douro","HistorischeRebsorten","Korkeiche WeinregionenPortugals","Portugal","PortugiesischerWein","Portwein","Weinkultur"],"articleSection":["Weinwissen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/","name":"Das Weinland Portugal - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/niepoort_napoles_terrasse-Kopie-2.jpg","datePublished":"2023-10-22T15:00:00+00:00","dateModified":"2024-04-17T13:43:22+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/niepoort_napoles_terrasse-Kopie-2.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/niepoort_napoles_terrasse-Kopie-2.jpg","width":2500,"height":1059},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2023\/10\/das-weinland-portugal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Das Weinland Portugal"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/10\/niepoort_napoles_terrasse-Kopie-2.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-QwO","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/201922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=201922"}],"version-history":[{"count":4,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/201922\/revisions"}],"predecessor-version":[{"id":204485,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/201922\/revisions\/204485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/201926"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=201922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=201922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=201922"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=201922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}