{"id":205319,"date":"2024-07-11T17:00:00","date_gmt":"2024-07-11T15:00:00","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=205319"},"modified":"2024-07-10T17:41:21","modified_gmt":"2024-07-10T15:41:21","slug":"herbert-zillinger-weinviertel-oesterreich","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/","title":{"rendered":"Herbert Zillinger &#8211; Weinviertel -\u00d6sterreich"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Das Weingut Zillinger: Naturbelassene Weine ohne Kompromisse aus dem Weinviertel<\/h2>\n\n\n\n<p class=\"has-drop-cap\">Das Weingut Zillinger liegt in Ebenthal im Weinviertel, einem kleinen Dorf im Wiener Becken. Herbert Zillinger f\u00fchrt zusammen mit seiner Frau Carmen das etwa 16 Hektar gro\u00dfe Weingut. Ihre klare Mission lautet: Keine Kompromisse! Hier bekommt man naturbelassenen Wein ins Glas. Die Weine sind Unikate mit Profil, Struktur und Alleinstellungsmerkmal.<\/p>\n\n\n\n<p>Seit 2016 werden alle Weinberge biodynamisch bewirtschaftet. Als Hauptrebsorte nimmt Gr\u00fcner Veltliner den gr\u00f6\u00dften Teil der Rebfl\u00e4chen ein, aber auch Sauvignon Blanc, Zweigelt, Wei\u00dfburgunder und Chardonnay sind im Rebsortenportfolio und in einigen Cuv\u00e9es zu finden. Die B\u00f6den bestehen aus kalkhaltigem L\u00f6ss, der sich aus folgenden Silikaten bildet: Quarz, Feldspat, Glimmer und Tonmineralien.<\/p>\n\n\n\n<p>Das Klima im Weinviertel ist pannonisch gepr\u00e4gt, was bedeutet, dass es thermisch kontinental und hygrisch eher ozeanisch ist. Die durchschnittliche Jahrestemperatur liegt bei 9 bis 10 \u00b0C, die Sonnenscheindauer betr\u00e4gt bis zu 1.900 Stunden pro Jahr und der j\u00e4hrliche Niederschlag liegt zwischen 400 und 600 mm. Diese Bedingungen bilden die Basis f\u00fcr frische Weine, die vom Weingut Zillinger auch manchmal etwas \u201efunky\u201c daherkommen.<\/p>\n\n\n\n<p>Zu den Weinen im Online-Shop -> <a href=\"https:\/\/www.weine-feinkost.de\/shop\/Weingut-Herbert-Zillinger\/\"><strong>Weingut Herbert Zillinger<\/strong><\/a><\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:62.37154%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_3_oesterreich_-811x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_3_oesterreich_-811x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_3_oesterreich_-811x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_3_oesterreich_-811x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_3_oesterreich_-811x1024.jpg?strip=info&#038;w=1521&#038;ssl=1 1521w\" alt=\"\" data-height=\"1920\" data-id=\"205321\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=205321#main\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_3_oesterreich_-811x1024.jpg\" data-width=\"1521\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_3_oesterreich_-811x1024.jpg?ssl=1\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Bild\u00a01 von 4 im Vollbildmodus \u00f6ffnen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:37.62846%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_1-1200x900.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_1-1200x900.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_1-1200x900.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_1-1200x900.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_1-1200x900.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_1-1200x900.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"1440\" data-id=\"205322\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=205322#main\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_1-1200x900.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_1-1200x900.jpg?ssl=1\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Bild\u00a02 von 4 im Vollbildmodus \u00f6ffnen\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_4-1200x799.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_4-1200x799.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_4-1200x799.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_4-1200x799.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_4-1200x799.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_4-1200x799.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"1279\" data-id=\"205324\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=205324#main\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_4-1200x799.jpeg\" data-width=\"1920\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_4-1200x799.jpeg?ssl=1\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Bild\u00a03 von 4 im Vollbildmodus \u00f6ffnen\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_5-1200x800.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_5-1200x800.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_5-1200x800.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_5-1200x800.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_5-1200x800.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_5-1200x800.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"1280\" data-id=\"205325\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=205325#main\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_5-1200x800.jpg\" data-width=\"1920\" src=\"https:\/\/i1.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_5-1200x800.jpg?ssl=1\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Bild\u00a04 von 4 im Vollbildmodus \u00f6ffnen\"\/><\/figure><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p> <\/p>\n\n\n\n<p><strong>Wein-Plus Kollektion des Jahres 2023\/24:<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"107\" height=\"107\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Kollektion_of_the_year_2023_2024_wein_plus.png\" alt=\"\" class=\"wp-image-205328\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Kollektion_of_the_year_2023_2024_wein_plus.png 107w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Kollektion_of_the_year_2023_2024_wein_plus-65x65.png 65w\" sizes=\"auto, (max-width: 107px) 100vw, 107px\" \/><\/figure>\n<\/div>\n\n\n<p>&#8222;<em>Herbert Zillinger produziert schon lange Weine, die sowohl was den Charakter, als auch die Qualit\u00e4t an sich angeht, mit dem Mainstream im Weinviertel wenig bis gar nichts zu tun haben. Doch zuletzt muss er nochmal an einigen Stellschrauben gedreht haben. Die aktuelle Serie ist so profund, wie wir es selbst bei einem Meister wie ihm bislang nicht erlebt haben. Die Weine verbinden Kraft und Substanz mit Feinheiten, Leben und\u00a0innerer Ruhe, sie besitzen eine Tiefe und Komplexit\u00e4t, die man nicht nur im Gebiet selten findet. Doch nicht nur auf dem \u201cklassischen\u201d Terrain\u00a0k\u00f6nnen Zillinger nur wenige das Wasser reichen: Mit seinem 16 \u201cRadikal\u201d zeigt er ein wildes, extrem vielschichtiges, ungest\u00fcmes Meisterwerk, einen der besten Weine dieser Art \u00fcberhaupt.&#8220; Text: Wein-Plus.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Weingut Zillinger: Naturbelassene Weine ohne Kompromisse aus dem Weinviertel Das Weingut Zillinger liegt in Ebenthal im Weinviertel, einem kleinen Dorf im Wiener Becken. Herbert Zillinger f\u00fchrt zusammen mit seiner Frau Carmen das etwa 16 Hektar gro\u00dfe Weingut. Ihre klare Mission lautet: Keine Kompromisse! Hier bekommt man naturbelassenen Wein ins Glas. Die Weine sind Unikate &#8230; <a title=\"Herbert Zillinger &#8211; Weinviertel -\u00d6sterreich\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/\" aria-label=\"Mehr dazu unter Herbert Zillinger &#8211; Weinviertel -\u00d6sterreich\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":205323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3316,16],"tags":[9118,9103,9119,9108,2541,9101,632,7880,9099,9111,9120,9121,9112,557,9100,9116,9117,9109,9104,9114,9106,9110,235,9107,9115,9113,9105,9098,726,2675,9102,3163],"post_folder":[],"class_list":["post-205319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anbaugebiete","category-weingueter","tag-1-900-sonnenstunden","tag-16-hektar","tag-400-600-mm-niederschlag","tag-alleinstellungsmerkmal","tag-biodynamisch","tag-carmen-zillinger","tag-chardonnay","tag-cuvees","tag-ebenthal","tag-feldspat","tag-frische-weine","tag-funky-weine","tag-glimmer","tag-gruener-veltliner","tag-herbert-zillinger","tag-hygrisch-ozeanisch","tag-jahrestemperatur-9-10-c","tag-kalkhaltiger-loess","tag-naturbelassener-wein","tag-pannonisches-klima","tag-profil","tag-quarz","tag-sauvignon-blanc","tag-struktur","tag-thermisch-kontinental","tag-tonmineralien","tag-unikate","tag-weingut-zillinger","tag-weinviertel","tag-weissburgunder","tag-wiener-becken","tag-zweigelt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Herbert Zillinger - Weinviertel -\u00d6sterreich - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Herbert Zillinger - Weinviertel -\u00d6sterreich - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Das Weingut Zillinger: Naturbelassene Weine ohne Kompromisse aus dem Weinviertel Das Weingut Zillinger liegt in Ebenthal im Weinviertel, einem kleinen Dorf im Wiener Becken. Herbert Zillinger f\u00fchrt zusammen mit seiner Frau Carmen das etwa 16 Hektar gro\u00dfe Weingut. Ihre klare Mission lautet: Keine Kompromisse! Hier bekommt man naturbelassenen Wein ins Glas. Die Weine sind Unikate ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-11T15:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Herbert Zillinger &#8211; Weinviertel -\u00d6sterreich\",\"datePublished\":\"2024-07-11T15:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/\"},\"wordCount\":323,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Herbert_zillinger_weinviertel_oesterreich_2.jpg\",\"keywords\":[\"1.900 Sonnenstunden\",\"16 Hektar\",\"400-600 mm Niederschlag\",\"Alleinstellungsmerkmal\",\"biodynamisch\",\"Carmen Zillinger\",\"Chardonnay\",\"Cuv\u00e9es\",\"Ebenthal\",\"Feldspat\",\"frische Weine\",\"funky Weine\",\"Glimmer\",\"Gr\u00fcner Veltliner\",\"Herbert Zillinger\",\"hygrisch ozeanisch\",\"Jahrestemperatur 9-10 \u00b0C\",\"kalkhaltiger L\u00f6ss\",\"naturbelassener Wein\",\"pannonisches Klima\",\"Profil\",\"Quarz\",\"Sauvignon Blanc\",\"Struktur\",\"thermisch kontinental\",\"Tonmineralien\",\"Unikate\",\"Weingut Zillinger\",\"Weinviertel\",\"Wei\u00dfburgunder\",\"Wiener Becken\",\"Zweigelt\"],\"articleSection\":[\"Anbaugebiete\",\"Weing\u00fcter\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/\",\"name\":\"Herbert Zillinger - Weinviertel -\u00d6sterreich - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Herbert_zillinger_weinviertel_oesterreich_2.jpg\",\"datePublished\":\"2024-07-11T15:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Herbert_zillinger_weinviertel_oesterreich_2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Herbert_zillinger_weinviertel_oesterreich_2.jpg\",\"width\":1920,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2024\\\/07\\\/herbert-zillinger-weinviertel-oesterreich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Herbert Zillinger &#8211; Weinviertel -\u00d6sterreich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Herbert Zillinger - Weinviertel -\u00d6sterreich - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/","og_locale":"de_DE","og_type":"article","og_title":"Herbert Zillinger - Weinviertel -\u00d6sterreich - Unterwegs mit Weine &amp; Feinkost","og_description":"Das Weingut Zillinger: Naturbelassene Weine ohne Kompromisse aus dem Weinviertel Das Weingut Zillinger liegt in Ebenthal im Weinviertel, einem kleinen Dorf im Wiener Becken. Herbert Zillinger f\u00fchrt zusammen mit seiner Frau Carmen das etwa 16 Hektar gro\u00dfe Weingut. Ihre klare Mission lautet: Keine Kompromisse! Hier bekommt man naturbelassenen Wein ins Glas. Die Weine sind Unikate ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2024-07-11T15:00:00+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_2.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Herbert Zillinger &#8211; Weinviertel -\u00d6sterreich","datePublished":"2024-07-11T15:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/"},"wordCount":323,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_2.jpg","keywords":["1.900 Sonnenstunden","16 Hektar","400-600 mm Niederschlag","Alleinstellungsmerkmal","biodynamisch","Carmen Zillinger","Chardonnay","Cuv\u00e9es","Ebenthal","Feldspat","frische Weine","funky Weine","Glimmer","Gr\u00fcner Veltliner","Herbert Zillinger","hygrisch ozeanisch","Jahrestemperatur 9-10 \u00b0C","kalkhaltiger L\u00f6ss","naturbelassener Wein","pannonisches Klima","Profil","Quarz","Sauvignon Blanc","Struktur","thermisch kontinental","Tonmineralien","Unikate","Weingut Zillinger","Weinviertel","Wei\u00dfburgunder","Wiener Becken","Zweigelt"],"articleSection":["Anbaugebiete","Weing\u00fcter"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/","name":"Herbert Zillinger - Weinviertel -\u00d6sterreich - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_2.jpg","datePublished":"2024-07-11T15:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_2.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_2.jpg","width":1920,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2024\/07\/herbert-zillinger-weinviertel-oesterreich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Herbert Zillinger &#8211; Weinviertel -\u00d6sterreich"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2024\/07\/Herbert_zillinger_weinviertel_oesterreich_2.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-RpB","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/205319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=205319"}],"version-history":[{"count":4,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/205319\/revisions"}],"predecessor-version":[{"id":205335,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/205319\/revisions\/205335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/205323"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=205319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=205319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=205319"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=205319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}