{"id":23101,"date":"2014-03-19T14:35:40","date_gmt":"2014-03-19T13:35:40","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=23101"},"modified":"2014-03-19T14:35:40","modified_gmt":"2014-03-19T13:35:40","slug":"lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/","title":{"rendered":"Lebensmitteleinzelhandel verkauft mehr deutschen Wein"},"content":{"rendered":"<div><strong>18.03.14\u00a0 &#8211; Regionale Produkte gefragt:<\/strong> <span style=\"color: #000000;\">Der klassische Lebensmitteleinzelhandel (unter 5.000 m\u00b2) wird als Einkaufsst\u00e4tte f\u00fcr Wein beliebter. Der Absatz bei den sogenannten Vollsortimentern wuchs im Vergleich zum Vorjahr um f\u00fcnf Prozent und der Umsatz um acht Prozent. Dies gab das Deutsche Weininstitut (DWI) auf der Basis des GfK-Haushaltspanels im Vorfeld der internationalen Wein\u00admesse ProWein bekannt.<\/span><\/div>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Diese Steigerung ist in erster Linie auf Zuw\u00e4chse von heimischen Weinen zur\u00fcckzuf\u00fchren, die in diesem Vertriebskanal in Menge und Wert um 15 Prozent zulegten. \u201eWir stellen fest, dass immer mehr Filialen der Einzelhandelsketten versuchen, sich \u00fcber ein gutes Weinsortiment zu profilieren. Dabei folgen sie auch dem allgemeinen Einkaufstrend, verst\u00e4rkt auf heimische und regionale Produkte zur\u00fcckzugreifen\u201c, erl\u00e4utert DWI-Gesch\u00e4ftsf\u00fchrerin Monika Reule. \u201eDer Einkauf von deutschen Weinen hat sich dadurch ein St\u00fcck weit vom Fachhandel und Direktbezug vom Erzeuger zum Lebensmitteleinzelhandel verlagert\u201c, so Reule.<\/span><\/p>\n<p><span style=\"color: #000000;\">Zusammen mit den gro\u00dfen SB-Warenh\u00e4usern (\u00fcber 5.000 m\u00b2) und den Discountern wurden 2013 im gesamten Lebensmittelhandel 74 Prozent aller Weine von den Verbrauchern bezogen. Dabei haben die Discounter einen unver\u00e4nderten Marktanteil von 48 Prozent.<\/span><\/p>\n<p><span style=\"color: #000000;\">Der Durchschnittspreis f\u00fcr einen Liter Wein im gesamten Lebensmittelhandel belief sich im vergangenen Jahr \u00fcber alle Herk\u00fcnfte gesehen auf 2,84 \u20ac, was im Vergleich zu 2012 einem Plus von zw\u00f6lf Cent beziehungsweise 4,4 Prozent entspricht.<\/span> Quelle: <a href=\"http:\/\/www.deutscheweine.de\/icc\/Internet-DE\/nav\/eb8\/eb8708fd-e785-7401-be59-267b48205846&amp;uCon=bd3206f3-d344-d441-5915-f034044755db&amp;uTem=d5304ee7-4f03-d212-517b-6624c41ed8b2&amp;currentpage=1\">www.deutscheweine.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>18.03.14\u00a0 &#8211; Regionale Produkte gefragt: Der klassische Lebensmitteleinzelhandel (unter 5.000 m\u00b2) wird als Einkaufsst\u00e4tte f\u00fcr Wein beliebter. Der Absatz bei den sogenannten Vollsortimentern wuchs im Vergleich zum Vorjahr um f\u00fcnf Prozent und der Umsatz um acht Prozent. Dies gab das Deutsche Weininstitut (DWI) auf der Basis des GfK-Haushaltspanels im Vorfeld der internationalen Wein\u00admesse ProWein bekannt. &#8230; <a title=\"Lebensmitteleinzelhandel verkauft mehr deutschen Wein\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/\" aria-label=\"Mehr dazu unter Lebensmitteleinzelhandel verkauft mehr deutschen Wein\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":154767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[66],"tags":[],"post_folder":[],"class_list":["post-23101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuigkeiten-aus-der-welt-des-weines"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lebensmitteleinzelhandel verkauft mehr deutschen Wein - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lebensmitteleinzelhandel verkauft mehr deutschen Wein - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"18.03.14\u00a0 &#8211; Regionale Produkte gefragt: Der klassische Lebensmitteleinzelhandel (unter 5.000 m\u00b2) wird als Einkaufsst\u00e4tte f\u00fcr Wein beliebter. Der Absatz bei den sogenannten Vollsortimentern wuchs im Vergleich zum Vorjahr um f\u00fcnf Prozent und der Umsatz um acht Prozent. Dies gab das Deutsche Weininstitut (DWI) auf der Basis des GfK-Haushaltspanels im Vorfeld der internationalen Wein\u00admesse ProWein bekannt. ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-19T13:35:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Lebensmitteleinzelhandel verkauft mehr deutschen Wein\",\"datePublished\":\"2014-03-19T13:35:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/\"},\"wordCount\":223,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/planet_breit-640x270.jpg\",\"articleSection\":[\"Wein News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/\",\"name\":\"Lebensmitteleinzelhandel verkauft mehr deutschen Wein - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/planet_breit-640x270.jpg\",\"datePublished\":\"2014-03-19T13:35:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/planet_breit-640x270.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/planet_breit-640x270.jpg\",\"width\":640,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/03\\\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lebensmitteleinzelhandel verkauft mehr deutschen Wein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lebensmitteleinzelhandel verkauft mehr deutschen Wein - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/","og_locale":"de_DE","og_type":"article","og_title":"Lebensmitteleinzelhandel verkauft mehr deutschen Wein - Unterwegs mit Weine &amp; Feinkost","og_description":"18.03.14\u00a0 &#8211; Regionale Produkte gefragt: Der klassische Lebensmitteleinzelhandel (unter 5.000 m\u00b2) wird als Einkaufsst\u00e4tte f\u00fcr Wein beliebter. Der Absatz bei den sogenannten Vollsortimentern wuchs im Vergleich zum Vorjahr um f\u00fcnf Prozent und der Umsatz um acht Prozent. Dies gab das Deutsche Weininstitut (DWI) auf der Basis des GfK-Haushaltspanels im Vorfeld der internationalen Wein\u00admesse ProWein bekannt. ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2014-03-19T13:35:40+00:00","og_image":[{"width":640,"height":270,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Lebensmitteleinzelhandel verkauft mehr deutschen Wein","datePublished":"2014-03-19T13:35:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/"},"wordCount":223,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg","articleSection":["Wein News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/","name":"Lebensmitteleinzelhandel verkauft mehr deutschen Wein - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg","datePublished":"2014-03-19T13:35:40+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg","width":640,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/03\/lebensmitteleinzelhandel-verkauft-mehr-deutschen-wein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Lebensmitteleinzelhandel verkauft mehr deutschen Wein"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-60B","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/23101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=23101"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/23101\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/154767"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=23101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=23101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=23101"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=23101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}