{"id":23709,"date":"2014-05-14T21:20:47","date_gmt":"2014-05-14T19:20:47","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=23709"},"modified":"2014-05-14T21:20:47","modified_gmt":"2014-05-14T19:20:47","slug":"letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/","title":{"rendered":"Letzte Werbekampagne von Ex-Weinminister Klaus Gonzalez eingel\u00e4utet."},"content":{"rendered":"<p>Mit einer aufsehenerregenden Werbekampagne hat Ex-Weinminister Klaus Gonzalez den Endspurt f\u00fcr die Europawahl eingeleitet. Fachleute und Medienvertreter r\u00e4umen ihm zwar keine gro\u00dfen Chancen mehr ein, doch Kenner der Branche sind davon \u00fcberzeugt, dass der Politiker die Wahl einfach ausschlafen wird. Dieses Erfolgsgeheimnis hat ihm schon sehr h\u00e4ufig in den brenzligsten Lebenssituationen geholfen.<\/p>\n<p><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Intelligenz_trinkt.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-141815\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Intelligenz_trinkt-300x160.png\" alt=\"Intelligenz_trinkt\" width=\"450\" height=\"240\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Intelligenz_trinkt-300x160.png 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Intelligenz_trinkt-768x410.png 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Intelligenz_trinkt.png 800w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit einer aufsehenerregenden Werbekampagne hat Ex-Weinminister Klaus Gonzalez den Endspurt f\u00fcr die Europawahl eingeleitet. Fachleute und Medienvertreter r\u00e4umen ihm zwar keine gro\u00dfen Chancen mehr ein, doch Kenner der Branche sind davon \u00fcberzeugt, dass der Politiker die Wahl einfach ausschlafen wird. Dieses Erfolgsgeheimnis hat ihm schon sehr h\u00e4ufig in den brenzligsten Lebenssituationen geholfen.<\/p>\n","protected":false},"author":7,"featured_media":155630,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[],"post_folder":[],"class_list":["post-23709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weinminister"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Letzte Werbekampagne von Ex-Weinminister Klaus Gonzalez eingel\u00e4utet. - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Letzte Werbekampagne von Ex-Weinminister Klaus Gonzalez eingel\u00e4utet. - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Mit einer aufsehenerregenden Werbekampagne hat Ex-Weinminister Klaus Gonzalez den Endspurt f\u00fcr die Europawahl eingeleitet. Fachleute und Medienvertreter r\u00e4umen ihm zwar keine gro\u00dfen Chancen mehr ein, doch Kenner der Branche sind davon \u00fcberzeugt, dass der Politiker die Wahl einfach ausschlafen wird. Dieses Erfolgsgeheimnis hat ihm schon sehr h\u00e4ufig in den brenzligsten Lebenssituationen geholfen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-14T19:20:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Intelligenz_trinkt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Letzte Werbekampagne von Ex-Weinminister Klaus Gonzalez eingel\u00e4utet.\",\"datePublished\":\"2014-05-14T19:20:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/\"},\"wordCount\":64,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/Intelligenz_trinkt.jpg\",\"articleSection\":[\"Weinminister (Satire)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/\",\"name\":\"Letzte Werbekampagne von Ex-Weinminister Klaus Gonzalez eingel\u00e4utet. - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/Intelligenz_trinkt.jpg\",\"datePublished\":\"2014-05-14T19:20:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/Intelligenz_trinkt.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/Intelligenz_trinkt.jpg\",\"width\":670,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/05\\\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Letzte Werbekampagne von Ex-Weinminister Klaus Gonzalez eingel\u00e4utet.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Letzte Werbekampagne von Ex-Weinminister Klaus Gonzalez eingel\u00e4utet. - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/","og_locale":"de_DE","og_type":"article","og_title":"Letzte Werbekampagne von Ex-Weinminister Klaus Gonzalez eingel\u00e4utet. - Unterwegs mit Weine &amp; Feinkost","og_description":"Mit einer aufsehenerregenden Werbekampagne hat Ex-Weinminister Klaus Gonzalez den Endspurt f\u00fcr die Europawahl eingeleitet. Fachleute und Medienvertreter r\u00e4umen ihm zwar keine gro\u00dfen Chancen mehr ein, doch Kenner der Branche sind davon \u00fcberzeugt, dass der Politiker die Wahl einfach ausschlafen wird. Dieses Erfolgsgeheimnis hat ihm schon sehr h\u00e4ufig in den brenzligsten Lebenssituationen geholfen.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2014-05-14T19:20:47+00:00","og_image":[{"width":670,"height":270,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Intelligenz_trinkt.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Letzte Werbekampagne von Ex-Weinminister Klaus Gonzalez eingel\u00e4utet.","datePublished":"2014-05-14T19:20:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/"},"wordCount":64,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Intelligenz_trinkt.jpg","articleSection":["Weinminister (Satire)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/","name":"Letzte Werbekampagne von Ex-Weinminister Klaus Gonzalez eingel\u00e4utet. - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Intelligenz_trinkt.jpg","datePublished":"2014-05-14T19:20:47+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Intelligenz_trinkt.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Intelligenz_trinkt.jpg","width":670,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/05\/letzte-werbekampagne-von-ex-weinminister-klaus-gonzalez-eingelaeutet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Letzte Werbekampagne von Ex-Weinminister Klaus Gonzalez eingel\u00e4utet."}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Intelligenz_trinkt.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-6ap","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/23709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=23709"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/23709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/155630"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=23709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=23709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=23709"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=23709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}