{"id":23929,"date":"2014-09-26T14:42:35","date_gmt":"2014-09-26T12:42:35","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=23929"},"modified":"2014-09-26T14:42:35","modified_gmt":"2014-09-26T12:42:35","slug":"europa-weinminister-praesentiert-neue-geschaeftsideen","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/","title":{"rendered":"Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen."},"content":{"rendered":"<p>Nachdem Europa Weinminister Klaus Gonzalez wieder volle Fahrt in der Politik aufgenommen hat, bet\u00e4tigt er sich auch wieder mehr privatwirtschaftlich, um seine hohen Lebenshaltungskosten decken zu k\u00f6nnen. Sein Lottogewinn scheint in Saus und Braus auf den Kopf gehauen worden zu sein, und neue Gesch\u00e4ftsideen werden von ihm mit allen Verbindungen und Seilschaften nachhaltig nach vorne getrieben. In der Pipeline sind ein europaweit fl\u00e4chendeckendes Lampen- Franchise- Konzept und ein surreales Antik- Theater, welches in D\u00f6rfern bis zu 50 Einwohnern als Wanderb\u00fchne zum Einsatz kommen soll. \u201eDie Kohle muss wieder rein \u2013 egal wie\u201c, so wird der Minister in den Medien zitiert.<\/p>\n<p><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-155775\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_4-225x300.jpg\" alt=\"Europa_Weinminister_geschaetsideen_4\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_4-225x300.jpg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_4.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_1.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-155772\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_1-225x300.jpeg\" alt=\"Europa_Weinminister_geschaetsideen_1\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_1-225x300.jpeg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_1.jpeg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-155773\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_2-225x300.jpeg\" alt=\"Europa_Weinminister_geschaetsideen_2\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_2-225x300.jpeg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_2.jpeg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_3.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-155774\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_3-225x300.jpeg\" alt=\"Europa_Weinminister_geschaetsideen_3\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_3-225x300.jpeg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_3.jpeg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachdem Europa Weinminister Klaus Gonzalez wieder volle Fahrt in der Politik aufgenommen hat, bet\u00e4tigt er sich auch wieder mehr privatwirtschaftlich, um seine hohen Lebenshaltungskosten decken zu k\u00f6nnen. Sein Lottogewinn scheint in Saus und Braus auf den Kopf gehauen worden zu sein, und neue Gesch\u00e4ftsideen werden von ihm mit allen Verbindungen und Seilschaften nachhaltig nach vorne &#8230; <a title=\"Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen.\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/\" aria-label=\"Mehr dazu unter Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen.\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":155776,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[],"post_folder":[],"class_list":["post-23929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weinminister"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen. - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen. - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Nachdem Europa Weinminister Klaus Gonzalez wieder volle Fahrt in der Politik aufgenommen hat, bet\u00e4tigt er sich auch wieder mehr privatwirtschaftlich, um seine hohen Lebenshaltungskosten decken zu k\u00f6nnen. Sein Lottogewinn scheint in Saus und Braus auf den Kopf gehauen worden zu sein, und neue Gesch\u00e4ftsideen werden von ihm mit allen Verbindungen und Seilschaften nachhaltig nach vorne ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-26T12:42:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_41.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen.\",\"datePublished\":\"2014-09-26T12:42:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/\"},\"wordCount\":111,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/Europa_Weinminister_geschaetsideen_41.jpg\",\"articleSection\":[\"Weinminister (Satire)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/\",\"name\":\"Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen. - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/Europa_Weinminister_geschaetsideen_41.jpg\",\"datePublished\":\"2014-09-26T12:42:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/Europa_Weinminister_geschaetsideen_41.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/Europa_Weinminister_geschaetsideen_41.jpg\",\"width\":670,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/europa-weinminister-praesentiert-neue-geschaeftsideen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen. - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/","og_locale":"de_DE","og_type":"article","og_title":"Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen. - Unterwegs mit Weine &amp; Feinkost","og_description":"Nachdem Europa Weinminister Klaus Gonzalez wieder volle Fahrt in der Politik aufgenommen hat, bet\u00e4tigt er sich auch wieder mehr privatwirtschaftlich, um seine hohen Lebenshaltungskosten decken zu k\u00f6nnen. Sein Lottogewinn scheint in Saus und Braus auf den Kopf gehauen worden zu sein, und neue Gesch\u00e4ftsideen werden von ihm mit allen Verbindungen und Seilschaften nachhaltig nach vorne ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2014-09-26T12:42:35+00:00","og_image":[{"width":670,"height":270,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_41.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen.","datePublished":"2014-09-26T12:42:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/"},"wordCount":111,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_41.jpg","articleSection":["Weinminister (Satire)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/","name":"Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen. - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_41.jpg","datePublished":"2014-09-26T12:42:35+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_41.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_41.jpg","width":670,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/europa-weinminister-praesentiert-neue-geschaeftsideen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Europa Weinminister pr\u00e4sentiert neue Gesch\u00e4ftsideen."}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/05\/Europa_Weinminister_geschaetsideen_41.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-6dX","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/23929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=23929"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/23929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/155776"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=23929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=23929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=23929"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=23929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}