{"id":24505,"date":"2014-09-20T19:47:29","date_gmt":"2014-09-20T17:47:29","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=24505"},"modified":"2014-09-20T19:47:29","modified_gmt":"2014-09-20T17:47:29","slug":"baskischer-kochclub-zarautz","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/","title":{"rendered":"Baskischer Kochclub in Zarautz."},"content":{"rendered":"<p>Ein Abend in einem baskischen Kochclub ist f\u00fcr Nicht- Mitglieder sicherlich immer etwas Besonderes. An diesem Freitag Abend gab es einfache, aber dennoch \u00fcberragende Gerichte. Das Geheimnis sind schlicht und einfach die Zutaten, und diese wurden meisterhaft in Szene gesetzt. Der Tomaten-Zwiebelsalat mit gutem Oliven\u00f6l schmeckte wie von einem anderen Stern; der Bonito-Tomaten-Paprika-Zwiebel-Salat stand dem in nichts nach und die gegrillte Ventresca geh\u00f6rte in dieser Art und Weise schlicht zu der besten meines Lebens. Was aber mal wieder noch mehr beeindruckte als das sehr, sehr gute Mahl, war die Freundlichkeit und der Zusammenhalt der hier anwesenden Menschen. Hier wird diskutiert, lamentiert, gelacht, erkl\u00e4rt und zugeh\u00f6rt. Kochen und Essen verbindet und l\u00e4sst Menschen durch ein gemeinsames Interesse an ein und demselben Ereignis zusammen r\u00fccken. Man erf\u00e4hrt Zuspruch f\u00fcr das Produzierte, somit Best\u00e4tigung f\u00fcr sein Wirken, in einer nat\u00fcrlichen Umgebung. Man erf\u00e4hrt Neues, kann sich austauschen, aber auch einmal Luft ablassen. Ein Gemeinsinn, der f\u00fcr K\u00f6rper, Geist und Seele nur Gutes bereit h\u00e4lt und der einen selber stark \u00fcber die neue, immer egoistischer werdende Gesellschaft mit all ihrem sch\u00f6n verpackten, sinnentleerten Fast Food nachgr\u00fcbeln l\u00e4sst.<\/p>\n<p><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_5.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156057\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_5-300x225.jpeg\" alt=\"baskischer_kochclub_zarautz_5\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_5-300x225.jpeg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_5-600x450.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_5.jpeg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_1.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-156053 size-medium\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_1-e1405965746877-225x300.jpeg\" alt=\"baskischer_kochclub_zarautz_1\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_1-e1405965746877-225x300.jpeg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_1-e1405965746877.jpeg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>Tomaten-Zwiebel Salat.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156054\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_2-300x225.jpeg\" alt=\"baskischer_kochclub_zarautz_2\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_2-300x225.jpeg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_2-600x450.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_2.jpeg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Gegrillte Paprika aus Gernika.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_10.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156062\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_10-300x225.jpg\" alt=\"baskischer_kochclub_zarautz_10\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_10-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_10-600x450.jpg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_10.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Bonito Salat.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_3.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156055\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_3-300x225.jpeg\" alt=\"baskischer_kochclub_zarautz_3\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_3-300x225.jpeg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_3-600x450.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_3.jpeg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ventresca Thunfisch Salat.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_4.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156056\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_4-300x225.jpeg\" alt=\"baskischer_kochclub_zarautz_4\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_4-300x225.jpeg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_4-600x450.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_4.jpeg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Landr\u00fchrei mit Steinpilzen.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_6.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156058\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_6-300x225.jpeg\" alt=\"baskischer_kochclub_zarautz_6\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_6-300x225.jpeg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_6-600x450.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_6.jpeg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ventresca auf dem Grill.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_7.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156059\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_7-300x225.jpeg\" alt=\"baskischer_kochclub_zarautz_7\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_7-300x225.jpeg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_7-600x450.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_7.jpeg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ventresca.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_8.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156060\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_8-300x225.jpeg\" alt=\"baskischer_kochclub_zarautz_8\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_8-300x225.jpeg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_8-600x450.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_8.jpeg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Bonito.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_9.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156061\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_9-300x225.jpeg\" alt=\"baskischer_kochclub_zarautz_9\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_9-300x225.jpeg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_9-600x450.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_9.jpeg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Zum Abschluss gibt es immer einen Gin Tonic (mit Spezial Limette aus Getaria!)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Abend in einem baskischen Kochclub ist f\u00fcr Nicht- Mitglieder sicherlich immer etwas Besonderes. An diesem Freitag Abend gab es einfache, aber dennoch \u00fcberragende Gerichte. Das Geheimnis sind schlicht und einfach die Zutaten, und diese wurden meisterhaft in Szene gesetzt. Der Tomaten-Zwiebelsalat mit gutem Oliven\u00f6l schmeckte wie von einem anderen Stern; der Bonito-Tomaten-Paprika-Zwiebel-Salat stand dem &#8230; <a title=\"Baskischer Kochclub in Zarautz.\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/\" aria-label=\"Mehr dazu unter Baskischer Kochclub in Zarautz.\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":156058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[63],"tags":[],"post_folder":[],"class_list":["post-24505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baskischer Kochclub in Zarautz. - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Besuch in einem baskischen Kochclub in Zarautz: 100 % Kommunikation und Genuss.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baskischer Kochclub in Zarautz. - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Besuch in einem baskischen Kochclub in Zarautz: 100 % Kommunikation und Genuss.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-20T17:47:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_6.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Baskischer Kochclub in Zarautz.\",\"datePublished\":\"2014-09-20T17:47:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/\"},\"wordCount\":240,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/baskischer_kochclub_zarautz_6.jpeg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/\",\"name\":\"Baskischer Kochclub in Zarautz. - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/baskischer_kochclub_zarautz_6.jpeg\",\"datePublished\":\"2014-09-20T17:47:29+00:00\",\"description\":\"Besuch in einem baskischen Kochclub in Zarautz: 100 % Kommunikation und Genuss.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/baskischer_kochclub_zarautz_6.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/baskischer_kochclub_zarautz_6.jpeg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/09\\\/baskischer-kochclub-zarautz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baskischer Kochclub in Zarautz.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baskischer Kochclub in Zarautz. - Unterwegs mit Weine &amp; Feinkost","description":"Besuch in einem baskischen Kochclub in Zarautz: 100 % Kommunikation und Genuss.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/","og_locale":"de_DE","og_type":"article","og_title":"Baskischer Kochclub in Zarautz. - Unterwegs mit Weine &amp; Feinkost","og_description":"Besuch in einem baskischen Kochclub in Zarautz: 100 % Kommunikation und Genuss.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2014-09-20T17:47:29+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_6.jpeg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Baskischer Kochclub in Zarautz.","datePublished":"2014-09-20T17:47:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/"},"wordCount":240,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_6.jpeg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/","name":"Baskischer Kochclub in Zarautz. - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_6.jpeg","datePublished":"2014-09-20T17:47:29+00:00","description":"Besuch in einem baskischen Kochclub in Zarautz: 100 % Kommunikation und Genuss.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_6.jpeg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_6.jpeg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/09\/baskischer-kochclub-zarautz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Baskischer Kochclub in Zarautz."}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/baskischer_kochclub_zarautz_6.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-6nf","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/24505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=24505"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/24505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/156058"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=24505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=24505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=24505"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=24505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}