{"id":24857,"date":"2014-08-12T19:14:49","date_gmt":"2014-08-12T17:14:49","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=24857"},"modified":"2014-08-12T19:14:49","modified_gmt":"2014-08-12T17:14:49","slug":"spanische-quiche-mit-thunfisch-und-oliven","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/","title":{"rendered":"Spanische Quiche mit Thunfisch und Oliven"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-141948\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_1-300x225.jpg\" alt=\"quiche_spanisch_1\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_1-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_1-1200x900.jpg 1200w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_1-768x576.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_1.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Zutaten: f\u00fcr den Teig: 125 g weiche Butter, 1 Eigelb, 250 g Mehl und etwas Wasser. F\u00fcr den Belag: 200 g\u00a0 besten Thunfisch aus der Dose (ohne \u00d6l), 150 g gr\u00fcne Oliven. Ausserdem 4 Eier, 200 g Sahne und Parmesan nach belieben.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-141949\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_5-300x225.jpg\" alt=\"quiche_spanisch_5\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_5-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_5-1200x900.jpg 1200w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_5-768x576.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_5.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Aus den Teigzutaten einen Teig mischen und in eine mehlierte Tarte- oder Backform geben.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-141950\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_2-300x225.jpg\" alt=\"quiche_spanisch_2\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_2-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_2-1200x900.jpg 1200w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_2-768x576.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_2.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Die Oliven grob zerkleinern.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-141951\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_3-300x225.jpg\" alt=\"quiche_spanisch_3\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_3-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_3-1200x900.jpg 1200w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_3-768x576.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_3.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Thunfisch, Sahne und Eier hinzugeben.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-141952\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_4-300x225.jpg\" alt=\"quiche_spanisch_4\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_4-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_4-1200x900.jpg 1200w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_4-768x576.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_4.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Parmesan in die Masse reiben. Salzen und pfeffern. Nicht zu stark vermengen.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-141953\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_6-300x225.jpg\" alt=\"quiche_spanisch_6\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_6-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_6-1200x900.jpg 1200w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_6-768x576.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_6.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Masse auf den Teig geben.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-141954\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_7-300x225.jpg\" alt=\"quiche_spanisch_7\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_7-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_7-1200x900.jpg 1200w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_7-768x576.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_7.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Bei 180 \u00b0C\u00a0 30 bis 40 Minuten im Ofen backen.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-141955\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_8-300x225.jpg\" alt=\"quiche_spanisch_8\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_8-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_8-1200x900.jpg 1200w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_8-768x576.jpg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/quiche_spanisch_8.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Der passende Verdejo zu der Tarte\u00a0<strong> -&gt;<\/strong> <span style=\"color: #ff0000;\"><a href=\"https:\/\/www.weine-feinkost.de\/shop\/Monteabellon-Verdejo.html\"><span style=\"color: #ff0000;\">Monteabellon Verdejo<\/span><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten: f\u00fcr den Teig: 125 g weiche Butter, 1 Eigelb, 250 g Mehl und etwas Wasser. F\u00fcr den Belag: 200 g\u00a0 besten Thunfisch aus der Dose (ohne \u00d6l), 150 g gr\u00fcne Oliven. Ausserdem 4 Eier, 200 g Sahne und Parmesan nach belieben. Aus den Teigzutaten einen Teig mischen und in eine mehlierte Tarte- oder Backform &#8230; <a title=\"Spanische Quiche mit Thunfisch und Oliven\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/\" aria-label=\"Mehr dazu unter Spanische Quiche mit Thunfisch und Oliven\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":141947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[17,103],"tags":[116,117,118,119,84],"post_folder":[],"class_list":["post-24857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezepte","category-spanische-rezepte","tag-gruene-oliven","tag-kuchen","tag-ofen","tag-spanische-quiche","tag-thunfisch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spanische Quiche mit Thunfisch und Oliven - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Quiche mit typisch spanischen Zutaten wie gr\u00fcnen Oliven und Thunfisch. Hinzukommen eine Sahne- Ei Mischnung und ein M\u00fcrbeteig in einer Backform.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spanische Quiche mit Thunfisch und Oliven - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Quiche mit typisch spanischen Zutaten wie gr\u00fcnen Oliven und Thunfisch. Hinzukommen eine Sahne- Ei Mischnung und ein M\u00fcrbeteig in einer Backform.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-12T17:14:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Spanische Quiche mit Thunfisch und Oliven\",\"datePublished\":\"2014-08-12T17:14:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/\"},\"wordCount\":101,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/spanische_rezepte_1.jpg\",\"keywords\":[\"gr\u00fcne Oliven\",\"Kuchen\",\"Ofen\",\"Spanische Quiche\",\"Thunfisch\"],\"articleSection\":[\"Rezepte\",\"Spanische Spezialit\u00e4ten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/\",\"name\":\"Spanische Quiche mit Thunfisch und Oliven - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/spanische_rezepte_1.jpg\",\"datePublished\":\"2014-08-12T17:14:49+00:00\",\"description\":\"Quiche mit typisch spanischen Zutaten wie gr\u00fcnen Oliven und Thunfisch. Hinzukommen eine Sahne- Ei Mischnung und ein M\u00fcrbeteig in einer Backform.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/spanische_rezepte_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/spanische_rezepte_1.jpg\",\"width\":640,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/spanische-quiche-mit-thunfisch-und-oliven\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spanische Quiche mit Thunfisch und Oliven\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spanische Quiche mit Thunfisch und Oliven - Unterwegs mit Weine &amp; Feinkost","description":"Quiche mit typisch spanischen Zutaten wie gr\u00fcnen Oliven und Thunfisch. Hinzukommen eine Sahne- Ei Mischnung und ein M\u00fcrbeteig in einer Backform.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/","og_locale":"de_DE","og_type":"article","og_title":"Spanische Quiche mit Thunfisch und Oliven - Unterwegs mit Weine &amp; Feinkost","og_description":"Quiche mit typisch spanischen Zutaten wie gr\u00fcnen Oliven und Thunfisch. Hinzukommen eine Sahne- Ei Mischnung und ein M\u00fcrbeteig in einer Backform.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2014-08-12T17:14:49+00:00","og_image":[{"width":640,"height":270,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Spanische Quiche mit Thunfisch und Oliven","datePublished":"2014-08-12T17:14:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/"},"wordCount":101,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg","keywords":["gr\u00fcne Oliven","Kuchen","Ofen","Spanische Quiche","Thunfisch"],"articleSection":["Rezepte","Spanische Spezialit\u00e4ten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/","name":"Spanische Quiche mit Thunfisch und Oliven - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg","datePublished":"2014-08-12T17:14:49+00:00","description":"Quiche mit typisch spanischen Zutaten wie gr\u00fcnen Oliven und Thunfisch. Hinzukommen eine Sahne- Ei Mischnung und ein M\u00fcrbeteig in einer Backform.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg","width":640,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/spanische-quiche-mit-thunfisch-und-oliven\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Spanische Quiche mit Thunfisch und Oliven"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-6sV","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/24857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=24857"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/24857\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/141947"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=24857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=24857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=24857"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=24857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}