{"id":24942,"date":"2014-08-15T10:59:59","date_gmt":"2014-08-15T08:59:59","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=24942"},"modified":"2014-08-15T10:59:59","modified_gmt":"2014-08-15T08:59:59","slug":"erste-trauben-des-jahres-geerntet","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/","title":{"rendered":"Erste Trauben des Jahres geerntet"},"content":{"rendered":"<p><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/van_volxem_ernte.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-141973\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/08\/van_volxem_ernte-300x199.jpeg\" alt=\"van_volxem_ernte\" width=\"300\" height=\"199\" \/><\/a><\/p>\n<p><span style=\"color: #333333;\">Am <strong>8. August 2014<\/strong> wurden bereits <strong>die ersten Trauben<\/strong> des Jahres f\u00fcr den Federwei\u00dfen von der fr\u00fchreifen Rebsorte Solaris im rheinhessischen Westhofen <strong>gelesen<\/strong>. Eine au\u00dfergew\u00f6hnlich fr\u00fche Rebbl\u00fcte, die bereits Ende Mai\/Anfang Juni einsetzte, lie\u00df in diesem Jahr schon einen fr\u00fchzeitigen Start in die Weinlese erwarten.<\/span><\/p>\n<p><span style=\"color: #333333;\">Denn die Trauben brauchen nach der Bl\u00fcte etwa 90 bis 100 Tage bis zur Lesereife. Dieser fr\u00fche Lesetermin reiht sich damit in die bis dato fr\u00fchesten Lesestarttermine aus den Jahren 2007 und 2011 ein. Normalerweise beginnt die Federwei\u00dfenlese erst ab Mitte August, im vergangenen Jahr war es sogar erst der 28. dieses Monats.<\/span><\/p>\n<p><span style=\"color: #333333;\">Derzeit pr\u00e4sentieren sich hierzulande in allen Anbaugebieten die Rebanlagen und Trauben in hervorragendem Zustand, so dass optimistisch auf die Hauptlese geblickt werden kann. Wenn die Witterung in den n\u00e4chsten entscheidenden Wochen mitspielt, ist aufgrund eines Entwicklungsvorsprungs der Rebenvegetation von gut 10 bis 14 Tagen und einer guten Wasserversorgung der B\u00f6den mit einer qualitativ und quantitativ guten Ernte zu rechnen. Nach derzeitigem Vegetationsstand wird davon ausgegangen, dass die Traubenlese f\u00fcr die Weinbereitung in der ersten September-Dekade startet.<\/span> Quelle: <a href=\"http:\/\/www.deutscheweine.de\/icc\/Internet-DE\/nav\/eb8\/eb8708fd-e785-7401-be59-267b48205846&amp;uCon=8c120792-93e3-b741-f0ee-13636f135e25&amp;uTem=d5304ee7-4f03-d212-517b-6624c41ed8b2&amp;currentpage=1\">Deutsches Weininstitut.<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 8. August 2014 wurden bereits die ersten Trauben des Jahres f\u00fcr den Federwei\u00dfen von der fr\u00fchreifen Rebsorte Solaris im rheinhessischen Westhofen gelesen. Eine au\u00dfergew\u00f6hnlich fr\u00fche Rebbl\u00fcte, die bereits Ende Mai\/Anfang Juni einsetzte, lie\u00df in diesem Jahr schon einen fr\u00fchzeitigen Start in die Weinlese erwarten. Denn die Trauben brauchen nach der Bl\u00fcte etwa 90 bis &#8230; <a title=\"Erste Trauben des Jahres geerntet\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/\" aria-label=\"Mehr dazu unter Erste Trauben des Jahres geerntet\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":154767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[66],"tags":[131,120,132],"post_folder":[],"class_list":["post-24942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuigkeiten-aus-der-welt-des-weines","tag-131","tag-deutschland","tag-weinernte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erste Trauben des Jahres geerntet - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Am 08.08.2014 wurden in Rheinhessen die ersten Trauben des Jahres der Rebsorte Solaris gelesen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erste Trauben des Jahres geerntet - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Am 08.08.2014 wurden in Rheinhessen die ersten Trauben des Jahres der Rebsorte Solaris gelesen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-15T08:59:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Erste Trauben des Jahres geerntet\",\"datePublished\":\"2014-08-15T08:59:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/\"},\"wordCount\":191,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/planet_breit-640x270.jpg\",\"keywords\":[\"2014\",\"Deutschland\",\"Weinernte\"],\"articleSection\":[\"Wein News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/\",\"name\":\"Erste Trauben des Jahres geerntet - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/planet_breit-640x270.jpg\",\"datePublished\":\"2014-08-15T08:59:59+00:00\",\"description\":\"Am 08.08.2014 wurden in Rheinhessen die ersten Trauben des Jahres der Rebsorte Solaris gelesen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/planet_breit-640x270.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/planet_breit-640x270.jpg\",\"width\":640,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/08\\\/erste-trauben-des-jahres-geerntet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erste Trauben des Jahres geerntet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erste Trauben des Jahres geerntet - Unterwegs mit Weine &amp; Feinkost","description":"Am 08.08.2014 wurden in Rheinhessen die ersten Trauben des Jahres der Rebsorte Solaris gelesen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/","og_locale":"de_DE","og_type":"article","og_title":"Erste Trauben des Jahres geerntet - Unterwegs mit Weine &amp; Feinkost","og_description":"Am 08.08.2014 wurden in Rheinhessen die ersten Trauben des Jahres der Rebsorte Solaris gelesen.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2014-08-15T08:59:59+00:00","og_image":[{"width":640,"height":270,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Erste Trauben des Jahres geerntet","datePublished":"2014-08-15T08:59:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/"},"wordCount":191,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg","keywords":["2014","Deutschland","Weinernte"],"articleSection":["Wein News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/","name":"Erste Trauben des Jahres geerntet - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg","datePublished":"2014-08-15T08:59:59+00:00","description":"Am 08.08.2014 wurden in Rheinhessen die ersten Trauben des Jahres der Rebsorte Solaris gelesen.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg","width":640,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/08\/erste-trauben-des-jahres-geerntet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Erste Trauben des Jahres geerntet"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2013\/11\/planet_breit-640x270.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-6ui","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/24942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=24942"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/24942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/154767"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=24942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=24942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=24942"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=24942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}