{"id":25287,"date":"2014-12-14T12:35:19","date_gmt":"2014-12-14T11:35:19","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=25287"},"modified":"2014-12-14T12:35:19","modified_gmt":"2014-12-14T11:35:19","slug":"rezept-ma","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/","title":{"rendered":"Potaje de Bacalao"},"content":{"rendered":"<p>Dieses Rezept hat Ana in Barcelona zubereitet. Es war sehr lecker und s\u00e4ttigend. Im Grunde auch preiswert und gut f\u00fcr den Herbst. Sie hat es von ihrer Mutter \u00fcbernommen.<\/p>\n<p>Historia<\/p>\n<p>Bevor der Mensch die Lebensmittelk\u00fchlung erfand war er angewiesen auf die Konservierung von Lebensmittel durch das Salz.<br \/>\nSo wurden der Kabeljau und die Sardine die beliebtesten Fische zum Lufttrocknen mit Hilfe des Meeressalzes.<\/p>\n<p><strong>Potaje de Bacalao<\/strong><\/p>\n<p>Ingredientes f\u00fcr 4 Personen<\/p>\n<p>2 Kartoffeln, in W\u00fcrfel geschnitten<br \/>\n150 g Paella Reis<br \/>\n600 ml Wasser<br \/>\n300 g luftgetrockneter Stockfisch (2 Stunden vorher w\u00e4ssern zum Entsalzen)<br \/>\n4 Knoblauchzehen klein gehackt<br \/>\nPetersilie gehackt, 1 Lorbeerblatt<br \/>\nOliven\u00f6l<br \/>\n3 Eier<br \/>\nDieses Gericht wird zum Schluss vorsichtig mit Salz und Pfeffer abgeschmeckt. Je nachdem wie der Fisch entsalzt wurde, ben\u00f6tigt man wenig oder gar kein Salz!!<\/p>\n<p>Zubereitung<\/p>\n<p>Das Oliven\u00f6l in einen Kochtopf geben, hei\u00df werden lassen und die Kartoffeln, den Knoblauch, den Stockfisch in kleine St\u00fccke und das Lorbeerblatt darin d\u00fcnsten, dann Reis dazu geben und mitd\u00fcnsten. Jetzt das Wasser zugeben und kochen lassen bis der Reis gar ist. Wenn n\u00f6tig mehr hei\u00dfes Wasser dazugeben bevor zum Schluss die Eier darin pochiert werden.<br \/>\nFertig und sofort servieren mit Petersilie bestreuen und einen mittelschweren Rosado dazu trinken.<br \/>\n.<\/p>\n<p><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_1.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156481\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_1-225x300.jpeg\" alt=\"bacalao_1\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_1-225x300.jpeg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_1-768x1024.jpeg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_1-600x800.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_1.jpeg 810w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156482\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_2-225x300.jpeg\" alt=\"bacalao_2\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_2-225x300.jpeg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_2-768x1024.jpeg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_2-600x800.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_2.jpeg 810w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_3.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156483\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_3-225x300.jpeg\" alt=\"bacalao_3\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_3-225x300.jpeg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_3-768x1024.jpeg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_3-600x800.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_3.jpeg 810w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_4.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156484\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_4-225x300.jpeg\" alt=\"bacalao_4\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_4-225x300.jpeg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_4-768x1024.jpeg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_4-600x800.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_4.jpeg 810w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_5.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156485\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_5-225x300.jpeg\" alt=\"bacalao_5\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_5-225x300.jpeg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_5-768x1024.jpeg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_5-600x800.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_5.jpeg 810w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_6.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156486\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_6-225x300.jpeg\" alt=\"bacalao_6\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_6-225x300.jpeg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_6-768x1024.jpeg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_6-600x800.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_6.jpeg 810w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_7.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-156487\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_7-225x300.jpeg\" alt=\"bacalao_7\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_7-225x300.jpeg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_7-768x1024.jpeg 768w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_7-600x800.jpeg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/12\/bacalao_7.jpeg 810w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><strong>Weintipp<\/strong>: <strong><span style=\"color: #ff0000;\">-&gt;<\/span> <a href=\"https:\/\/www.weine-feinkost.de\/shop\/Ochoa-Calendas-rosado.html\">Ochoa Calendas rosado<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieses Rezept hat Ana in Barcelona zubereitet. Es war sehr lecker und s\u00e4ttigend. Im Grunde auch preiswert und gut f\u00fcr den Herbst. Sie hat es von ihrer Mutter \u00fcbernommen. Historia Bevor der Mensch die Lebensmittelk\u00fchlung erfand war er angewiesen auf die Konservierung von Lebensmittel durch das Salz. So wurden der Kabeljau und die Sardine die &#8230; <a title=\"Potaje de Bacalao\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/\" aria-label=\"Mehr dazu unter Potaje de Bacalao\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":141947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[103],"tags":[259,260,261,262,263],"post_folder":[],"class_list":["post-25287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spanische-rezepte","tag-bacalao","tag-potaje","tag-reis","tag-spanisches-rezept","tag-stockfisch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Potaje de Bacalao - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Potaje Bacalao ist ein typisch spanisches Rezept mit Kartoffeln, Bacalao und Reis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Potaje de Bacalao - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Potaje Bacalao ist ein typisch spanisches Rezept mit Kartoffeln, Bacalao und Reis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-14T11:35:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Potaje de Bacalao\",\"datePublished\":\"2014-12-14T11:35:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/\"},\"wordCount\":212,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/spanische_rezepte_1.jpg\",\"keywords\":[\"Bacalao\",\"Potaje\",\"Reis\",\"spanisches Rezept\",\"Stockfisch\"],\"articleSection\":[\"Spanische Spezialit\u00e4ten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/\",\"name\":\"Potaje de Bacalao - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/spanische_rezepte_1.jpg\",\"datePublished\":\"2014-12-14T11:35:19+00:00\",\"description\":\"Potaje Bacalao ist ein typisch spanisches Rezept mit Kartoffeln, Bacalao und Reis.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/spanische_rezepte_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/spanische_rezepte_1.jpg\",\"width\":640,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2014\\\/12\\\/rezept-ma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Potaje de Bacalao\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Potaje de Bacalao - Unterwegs mit Weine &amp; Feinkost","description":"Potaje Bacalao ist ein typisch spanisches Rezept mit Kartoffeln, Bacalao und Reis.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/","og_locale":"de_DE","og_type":"article","og_title":"Potaje de Bacalao - Unterwegs mit Weine &amp; Feinkost","og_description":"Potaje Bacalao ist ein typisch spanisches Rezept mit Kartoffeln, Bacalao und Reis.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2014-12-14T11:35:19+00:00","og_image":[{"width":640,"height":270,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Potaje de Bacalao","datePublished":"2014-12-14T11:35:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/"},"wordCount":212,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg","keywords":["Bacalao","Potaje","Reis","spanisches Rezept","Stockfisch"],"articleSection":["Spanische Spezialit\u00e4ten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/","name":"Potaje de Bacalao - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg","datePublished":"2014-12-14T11:35:19+00:00","description":"Potaje Bacalao ist ein typisch spanisches Rezept mit Kartoffeln, Bacalao und Reis.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg","width":640,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2014\/12\/rezept-ma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Potaje de Bacalao"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/07\/spanische_rezepte_1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-6zR","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/25287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=25287"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/25287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/141947"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=25287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=25287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=25287"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=25287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}