{"id":30541,"date":"2016-02-05T18:48:27","date_gmt":"2016-02-05T17:48:27","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=30541"},"modified":"2016-02-05T18:48:27","modified_gmt":"2016-02-05T17:48:27","slug":"europa-weinminister-fuehrt-das-weinwaffen-recht-ein","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/","title":{"rendered":"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein"},"content":{"rendered":"<h2>Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein<\/h2>\n<p>Der Trend in den Vereinigten Staaten und auch in der Europ\u00e4ischen Union geht ganz klar zur Selbstverteidigung hin. Der private B\u00fcrger r\u00fcstet immer mehr auf und kauft Gewehre, Bomben, Granaten und Pistolen f\u00fcr den eigenen Schutz. Aus diesem politischen Dilemma hat Europa Weinminister nun Kapital geschlagen und das mit sofortiger Wirkung eintretende Weinwaffen-Recht eingef\u00fchrt. Hierbei ist es erlaubt, Weinflaschen in den Formaten 0,75, 1,50 und 3,00 Liter als Waffe zur Selbstverteidigung einzusetzten. Die sogenannten &#8222;Flaschen-Waffen&#8220; k\u00f6nnen ab sofort im lokalen Handel eingekauft werden. Sie zeichnen sich durch besonders dickwandiges Glas, eine flotte, gut in der Hand liegende Oberfl\u00e4che und ein tolles Etiketten aus, welches an einen Revolver erinnert. Jeder vollj\u00e4hrige EU- B\u00fcrger darf pro Jahr 120 Flaschen erwerben. Innerhalb der europ\u00e4ischen Grenzen d\u00fcrfen die &#8222;Flaschen-Waffen&#8220; auch frei \u00fcber die Grenzen transportiert werden und im innereurop\u00e4ischen Flugverkehr m\u00fcssen diese nur in durchsichtige Plastikh\u00fcllen verpackt werden und k\u00f6nnen ansonsten frei auf jede Reise mitgenommen werden.<\/p>\n<p>Laut dem Ministerium soll kein &#8222;Weinflaschen Trageschein&#8220; f\u00fcr das Eigentum und die Benutzung der Wein-Waffen erforderlich sein.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Europa-Weinminister_fuehrt_das_Weinwaffen_Recht_ein_1.jpg\" rel=\"attachment wp-att-30542\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-145187 size-medium\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Europa-Weinminister_fuehrt_das_Weinwaffen_Recht_ein_1-e1453312458195-225x300.jpg\" alt=\"Europa Weinminister_fuehrt_das_Weinwaffen_Recht_ein_1\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Europa-Weinminister_fuehrt_das_Weinwaffen_Recht_ein_1-e1453312458195-225x300.jpg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Europa-Weinminister_fuehrt_das_Weinwaffen_Recht_ein_1-e1453312458195.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>Die erten Prototypen der &#8222;Wein-Waffen&#8220; wurden inzwischen angefertigt und sind schon im \u00f6rtlichen Handeln in den Verkauf gelangt.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_2.jpg\" rel=\"attachment wp-att-30543\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-145178 size-medium\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_2-e1453312447786-225x300.jpg\" alt=\"Weinminister_fuehrt_das_Weinwaffen_Recht_ein_2\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_2-e1453312447786-225x300.jpg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_2-e1453312447786.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>Modisch schick und sicher &#8230;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_3.jpg\" rel=\"attachment wp-att-30544\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-145185 size-medium\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_3-e1453312471330-225x300.jpg\" alt=\"Weinminister_fuehrt_das_Weinwaffen_Recht_ein_3\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_3-e1453312471330-225x300.jpg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_3-e1453312471330.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>&#8230; und mit dem notwendigen Abschreckschutz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein Der Trend in den Vereinigten Staaten und auch in der Europ\u00e4ischen Union geht ganz klar zur Selbstverteidigung hin. Der private B\u00fcrger r\u00fcstet immer mehr auf und kauft Gewehre, Bomben, Granaten und Pistolen f\u00fcr den eigenen Schutz. Aus diesem politischen Dilemma hat Europa Weinminister nun Kapital geschlagen und das mit &#8230; <a title=\"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/\" aria-label=\"Mehr dazu unter Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":158771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[],"post_folder":[],"class_list":["post-30541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weinminister"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein und erlaubt Weinflaschen als Waffe einzusezten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein und erlaubt Weinflaschen als Waffe einzusezten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-05T17:48:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein\",\"datePublished\":\"2016-02-05T17:48:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/\"},\"wordCount\":223,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_4.jpg\",\"articleSection\":[\"Weinminister (Satire)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/\",\"name\":\"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_4.jpg\",\"datePublished\":\"2016-02-05T17:48:27+00:00\",\"description\":\"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein und erlaubt Weinflaschen als Waffe einzusezten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_4.jpg\",\"width\":600,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/02\\\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein - Unterwegs mit Weine &amp; Feinkost","description":"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein und erlaubt Weinflaschen als Waffe einzusezten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/","og_locale":"de_DE","og_type":"article","og_title":"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein - Unterwegs mit Weine &amp; Feinkost","og_description":"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein und erlaubt Weinflaschen als Waffe einzusezten.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2016-02-05T17:48:27+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_4.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein","datePublished":"2016-02-05T17:48:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/"},"wordCount":223,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_4.jpg","articleSection":["Weinminister (Satire)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/","name":"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_4.jpg","datePublished":"2016-02-05T17:48:27+00:00","description":"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein und erlaubt Weinflaschen als Waffe einzusezten.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_4.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_4.jpg","width":600,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/02\/europa-weinminister-fuehrt-das-weinwaffen-recht-ein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Europa Weinminister f\u00fchrt das Weinwaffen-Recht ein"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/01\/Weinminister_fuehrt_das_Weinwaffen_Recht_ein_4.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-7WB","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/30541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=30541"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/30541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/158771"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=30541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=30541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=30541"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=30541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}