{"id":31022,"date":"2016-03-04T18:54:25","date_gmt":"2016-03-04T17:54:25","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=31022"},"modified":"2016-03-04T18:54:25","modified_gmt":"2016-03-04T17:54:25","slug":"tatort-kochklub-kuechentisch","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/","title":{"rendered":"Tatort Kochklub K\u00fcchentisch"},"content":{"rendered":"<h2>Tatort Kochklub K\u00fcchentisch<\/h2>\n<p>Jakobsmuschel Tatar mit Gurke, jodisiertem (Austern) Hendricks, Sauerrahm, Kaviar, Gurke und Minze Granite.<\/p>\n<p>Ein schlechtes Skatblatt? Pech in der Liebe? Probleme mit dem Nachbarn? Gesundheitliche Unp\u00e4sslichkeiten? Sonstige Problem? All das wird mit dem ersten Bissen dieses Jakobsmuschel Tatars sofort vergessen gemacht! Die einzelnen Komponenten m\u00f6gen nicht zusammen passen und wirken einzelnd geschmeckt sogar streng, hart und abweisend; zusammen genommen, auf einen L\u00f6ffel geschoben und dann in den Mund gef\u00fchrt, wird allerdings sofort ein gro\u00dfer Speichelfluss in Gang gesetzt und alle K\u00f6rperteile schreien umgehend nach einer ordentlichen Portion Nachschub. Das Tatar von der Jakobsmuschel schmeckt klar, bekommt durch die jodisierte Auster noch einen extra Kick Meersalz an Geschmack dazu und gewinnt durch den Hendricks Gin mit Gurke an vegetalen, gr\u00fcnen Noten und durch den Alkohol auch ordentlich an L\u00e4nge und Volumen hinzu.<\/p>\n<p>Der Sauerrahm bringt noch die passende adstringierende St\u00e4rke in den Gang hinein, der Kaviar eine facettenreiche Eleganz und diese gute Zuchtware vom St\u00f6r zaubert dann auch noch einen umwerfenden Perlage Effekt in den Mund hinein; das Gurken\/Minz Gratin\u00e9e sorgt hingegen f\u00fcr die unwiderstehliche Frische bei jedem einzelnen Biss.<\/p>\n<p>Ein genialer Gang und ohne Frage war hier wieder einmal viel zu wenig auf dem Teller. Wo wir wieder bei den Lebensproblemen vom Anfang w\u00e4ren &#8230; aber da gibt es ja noch den passenden sehr vollmundigen, kr\u00e4ftigen, in der Oxidationsphase steckenden Chardonnay passend zum Gericht dazu. Mmmmh &#8230;<\/p>\n<h2><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/02\/tatort_kochklub_kuechentisch.jpg\" rel=\"attachment wp-att-31023\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-158968\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/02\/tatort_kochklub_kuechentisch-300x225.jpg\" alt=\"tatort_kochklub_kuechentisch\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/02\/tatort_kochklub_kuechentisch-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/02\/tatort_kochklub_kuechentisch-600x450.jpg 600w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/02\/tatort_kochklub_kuechentisch.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Tatort Kochklub K\u00fcchentisch Jakobsmuschel Tatar mit Gurke, jodisiertem (Austern) Hendricks, Sauerrahm, Kaviar, Gurke und Minze Granite. Ein schlechtes Skatblatt? Pech in der Liebe? Probleme mit dem Nachbarn? Gesundheitliche Unp\u00e4sslichkeiten? Sonstige Problem? All das wird mit dem ersten Bissen dieses Jakobsmuschel Tatars sofort vergessen gemacht! Die einzelnen Komponenten m\u00f6gen nicht zusammen passen und wirken einzelnd geschmeckt &#8230; <a title=\"Tatort Kochklub K\u00fcchentisch\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/\" aria-label=\"Mehr dazu unter Tatort Kochklub K\u00fcchentisch\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":158968,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[63],"tags":[],"post_folder":[],"class_list":["post-31022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tatort Kochklub K\u00fcchentisch - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Jakobsmuschel Tatar mit Gurke jodisiertem (Austern) Hendricks, Sauerrahm, Kaviar, Gurke und Minze Granite im Kochklub K\u00fcchentisch.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tatort Kochklub K\u00fcchentisch - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Jakobsmuschel Tatar mit Gurke jodisiertem (Austern) Hendricks, Sauerrahm, Kaviar, Gurke und Minze Granite im Kochklub K\u00fcchentisch.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-04T17:54:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/02\/tatort_kochklub_kuechentisch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Tatort Kochklub K\u00fcchentisch\",\"datePublished\":\"2016-03-04T17:54:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/\"},\"wordCount\":248,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/tatort_kochklub_kuechentisch.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/\",\"name\":\"Tatort Kochklub K\u00fcchentisch - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/tatort_kochklub_kuechentisch.jpg\",\"datePublished\":\"2016-03-04T17:54:25+00:00\",\"description\":\"Jakobsmuschel Tatar mit Gurke jodisiertem (Austern) Hendricks, Sauerrahm, Kaviar, Gurke und Minze Granite im Kochklub K\u00fcchentisch.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/tatort_kochklub_kuechentisch.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/tatort_kochklub_kuechentisch.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/03\\\/tatort-kochklub-kuechentisch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tatort Kochklub K\u00fcchentisch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tatort Kochklub K\u00fcchentisch - Unterwegs mit Weine &amp; Feinkost","description":"Jakobsmuschel Tatar mit Gurke jodisiertem (Austern) Hendricks, Sauerrahm, Kaviar, Gurke und Minze Granite im Kochklub K\u00fcchentisch.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/","og_locale":"de_DE","og_type":"article","og_title":"Tatort Kochklub K\u00fcchentisch - Unterwegs mit Weine &amp; Feinkost","og_description":"Jakobsmuschel Tatar mit Gurke jodisiertem (Austern) Hendricks, Sauerrahm, Kaviar, Gurke und Minze Granite im Kochklub K\u00fcchentisch.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2016-03-04T17:54:25+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/02\/tatort_kochklub_kuechentisch.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Tatort Kochklub K\u00fcchentisch","datePublished":"2016-03-04T17:54:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/"},"wordCount":248,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/02\/tatort_kochklub_kuechentisch.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/","name":"Tatort Kochklub K\u00fcchentisch - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/02\/tatort_kochklub_kuechentisch.jpg","datePublished":"2016-03-04T17:54:25+00:00","description":"Jakobsmuschel Tatar mit Gurke jodisiertem (Austern) Hendricks, Sauerrahm, Kaviar, Gurke und Minze Granite im Kochklub K\u00fcchentisch.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/02\/tatort_kochklub_kuechentisch.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/02\/tatort_kochklub_kuechentisch.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/03\/tatort-kochklub-kuechentisch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Tatort Kochklub K\u00fcchentisch"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/02\/tatort_kochklub_kuechentisch.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-84m","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/31022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=31022"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/31022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/158968"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=31022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=31022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=31022"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=31022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}