{"id":31384,"date":"2016-04-27T08:57:10","date_gmt":"2016-04-27T06:57:10","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=31384"},"modified":"2016-04-27T08:57:10","modified_gmt":"2016-04-27T06:57:10","slug":"31384-2","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/","title":{"rendered":"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe"},"content":{"rendered":"<h2><strong>Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe<\/strong><\/h2>\n<p><strong>Frage:<\/strong> Man munkelt, f\u00fcr nur ein Glas Wein m\u00e4\u00dfiger Qualit\u00e4t w\u00fcrden Sie ihre Familie verkaufen? Wie stehen Sie zu diesem Ger\u00fccht?<\/p>\n<p><strong>Antwort:<\/strong> <em>Hierbei handelt es sich wirklich nur um ein Ger\u00fccht, so etwas w\u00fcrde ich nur f\u00fcr eine wirklich gute Flasche Wein aus einem au\u00dfergew\u00f6hnlich guten Jahrgang machen.<\/em><\/p>\n<p><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_2.jpg\" rel=\"attachment wp-att-31386\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-159150\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_2-225x300.jpg\" alt=\"Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_2\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_2-225x300.jpg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_2.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p><strong>Frage:<\/strong> Sie sollen schon die besten und rarsten Tropfen dieser Erde probiert und vor allen Dingen getrunken haben. Was war f\u00fcr Sie der beste Rebensaft aller Zeiten?<\/p>\n<p><strong>Antwort:<\/strong> <em>Das ist eines der gro\u00dfen Probleme meines fortgeschrittenen Alters, ich wei\u00df es einfach nicht mehr. Es muss aber ein Rotwein gewesen sein. Ich bin ja ein Pinot-Boy!<\/em><\/p>\n<p><strong>Frage:<\/strong> An welchem Ort war es f\u00fcr Sie am schwersten an einen Tropfen Alkohol zu kommen?<\/p>\n<p><strong>Antwort:<\/strong> <em>Das war einmal in einer \u00f6ffentlichen Bed\u00fcrfnisanstalt auf einem Rastplatz in der Mongolei. Da bin ich fast verdurstet, wurde aber von einem japanischen Touristen und einem Schluck Sake aus dessen Flachmann dann doch noch gerettet.<\/em><\/p>\n<p><strong>Frage:<\/strong> Wie f\u00fchlen Sie sich ohne Genuss von Alkohol?<\/p>\n<p><strong>Antwort:<\/strong> <em>Nicht gut.<\/em><\/p>\n<p><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_1.jpg\" rel=\"attachment wp-att-31385\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-159149\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_1-225x300.jpg\" alt=\"Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_1\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_1-225x300.jpg 225w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_1.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p><strong>Frage:<\/strong> Hand aufs Herz. Welchen anderen Lastern fr\u00f6nen Sie noch?<\/p>\n<p><strong>Antwort:<\/strong> <em>Das Kartenspiel hat es mir noch angetan und ich kann einen leichten Hang zum Exhibitionismus nicht leugnen.<\/em><\/p>\n<p><strong>Frage:<\/strong> Wie sind Sie an ihr Verm\u00f6gen gekommen, um sich diese teuren Bouteillen leisten zu k\u00f6nnen?<\/p>\n<p><strong>Antwort:<\/strong> <em>Ich habe immer schon als profunder Witzbold und vor allen Dingen als Gasttrinker mein Geld verdient. Die Leute zahlen paradoxerweise sehr gerne daf\u00fcr, dass ich ihnen ihre Weinflaschen leer trinken darf.<\/em><\/p>\n<p><strong>Frage:<\/strong> Was sagt ihre Familie zu ihrem expressiven Lebensstil?<\/p>\n<p><strong>Antwort:<\/strong> <em>Bitte haben Sie Verst\u00e4ndnis daf\u00fcr, dass es sich hierbei um eine Privatsache handelt und ich auf diese Frage nicht antworten m\u00f6chte.<\/em><\/p>\n<p><strong>Frage:<\/strong> Haben Sie noch Zukunftspl\u00e4ne, W\u00fcnsche und Ziele?<\/p>\n<p><strong>Antwort:<\/strong> <em>Ja. Ich w\u00fcrde gerne den ultimativen Witz erfinden.<\/em><\/p>\n<p>Wir danken Ihnen f\u00fcr dieses Gespr\u00e4ch.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe Frage: Man munkelt, f\u00fcr nur ein Glas Wein m\u00e4\u00dfiger Qualit\u00e4t w\u00fcrden Sie ihre Familie verkaufen? Wie stehen Sie zu diesem Ger\u00fccht? Antwort: Hierbei handelt es sich wirklich nur um ein Ger\u00fccht, so etwas w\u00fcrde ich nur f\u00fcr eine wirklich gute Flasche Wein aus einem au\u00dfergew\u00f6hnlich guten Jahrgang machen. &#8230; <a title=\"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/\" aria-label=\"Mehr dazu unter Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":159152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[],"post_folder":[],"class_list":["post-31384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weinminister"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe \u00fcber alles Wichtig und Unwichtige im Leben dieses einzigartigen Menschen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe \u00fcber alles Wichtig und Unwichtige im Leben dieses einzigartigen Menschen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-27T06:57:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe\",\"datePublished\":\"2016-04-27T06:57:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/\"},\"wordCount\":338,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_4.jpg\",\"articleSection\":[\"Weinminister (Satire)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/\",\"name\":\"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_4.jpg\",\"datePublished\":\"2016-04-27T06:57:10+00:00\",\"description\":\"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe \u00fcber alles Wichtig und Unwichtige im Leben dieses einzigartigen Menschen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_4.jpg\",\"width\":640,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/04\\\/31384-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe - Unterwegs mit Weine &amp; Feinkost","description":"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe \u00fcber alles Wichtig und Unwichtige im Leben dieses einzigartigen Menschen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/","og_locale":"de_DE","og_type":"article","og_title":"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe - Unterwegs mit Weine &amp; Feinkost","og_description":"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe \u00fcber alles Wichtig und Unwichtige im Leben dieses einzigartigen Menschen.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2016-04-27T06:57:10+00:00","og_image":[{"width":480,"height":640,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2016\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_1.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe","datePublished":"2016-04-27T06:57:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/"},"wordCount":338,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_4.jpg","articleSection":["Weinminister (Satire)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/","name":"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_4.jpg","datePublished":"2016-04-27T06:57:10+00:00","description":"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe \u00fcber alles Wichtig und Unwichtige im Leben dieses einzigartigen Menschen.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_4.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_4.jpg","width":640,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/04\/31384-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Ein Interview mit dem einzig lebenden Wein-Weltkulturerbe"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/04\/Ein_Interview_mit_dem_einzig_lebenden_Wein-Weltkulturerbe_4.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-8ac","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/31384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=31384"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/31384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/159152"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=31384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=31384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=31384"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=31384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}