{"id":31444,"date":"2016-05-07T18:42:42","date_gmt":"2016-05-07T16:42:42","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=31444"},"modified":"2023-03-22T12:32:45","modified_gmt":"2023-03-22T11:32:45","slug":"culinaria-im-farmerkreuz-dorf-tirol-italien","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/","title":{"rendered":"Culinaria im Farmerkreuz &#8211; Dorf Tirol &#8211; Italien"},"content":{"rendered":"<h2>Culinaria im Farmerkreuz &#8211; Dorf Tirol &#8211; Italien<\/h2>\n<p>Auf 800 Meter \u00fcber dem Meeresspiegel liegt das Restaurant Culinaria im Farmerkreuz. Hier in dieser luftigen H\u00f6henlage mit traumhaftem Blick \u00fcber das Dorf Tirol und dem Meraner Talkessel, haben die Gebr\u00fcder Kofler einen besondern Ort f\u00fcr Genussfreudige geschaffen. Mittags wird hier eine pfiffige Bistro-K\u00fcche f\u00fcr Wanderer, Schutzsuchende oder gezielt Vorbeikommende freundlich und nett zelebriert und abends erwartet den Gast eine Gourmet-K\u00fcche mit allem drum und dran.<\/p>\n<p>Die hier mittags besuchte Bistro-K\u00fcche schmeckte in jedem Fall schon sehr gut. Frischer Spargel aus S\u00fcdtirol so wie er sein muss und auch die geschmorte Rinderschulter zerfiel schon vor Zartheit nach dem ersten Messerschnitt. Eine gute, intensive Jus dazu, und der handgemachte Gem\u00fcse Raviolo mundete kongenial zu diesem Schmorgericht.<\/p>\n<p>Wenn es hier mittags schon so gut schmeckt, wird es abends sicherlich noch eine Schippe besser sein &#8230;.<\/p>\n\n<p><strong><br \/>\nCulinaria im Farmerkreuz<\/strong><br \/>\nHaslachstra\u00dfe, 105<br \/>\n39019 Dorf Tirol<br \/>\nItalien<br \/>\nTelefon: +39 0473 923508<br \/>\n<a href=\"http:\/\/www.culinaria-im-farmerkreuz.it\/\">www.culinaria-im-farmerkreuz.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Culinaria im Farmerkreuz &#8211; Dorf Tirol &#8211; Italien Auf 800 Meter \u00fcber dem Meeresspiegel liegt das Restaurant Culinaria im Farmerkreuz. Hier in dieser luftigen H\u00f6henlage mit traumhaftem Blick \u00fcber das Dorf Tirol und dem Meraner Talkessel, haben die Gebr\u00fcder Kofler einen besondern Ort f\u00fcr Genussfreudige geschaffen. Mittags wird hier eine pfiffige Bistro-K\u00fcche f\u00fcr Wanderer, Schutzsuchende &#8230; <a title=\"Culinaria im Farmerkreuz &#8211; Dorf Tirol &#8211; Italien\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/\" aria-label=\"Mehr dazu unter Culinaria im Farmerkreuz &#8211; Dorf Tirol &#8211; Italien\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":159183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[34,13],"tags":[897,898,192,73],"post_folder":[],"class_list":["post-31444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italien-restaurants","category-restaurants","tag-culinaria-im-farmerkreuz","tag-dorf-tirol","tag-italien","tag-restaurant"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Culinaria im Farmerkreuz - Dorf Tirol - Italien - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Culinaria im Farmerkreuz: oben auf 800 Meter \u00fcber dem Meeresspiegel Kulinarik genie\u00dfen und die gro\u00dfartigen Panorama Aussichten wirken lassen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Culinaria im Farmerkreuz - Dorf Tirol - Italien - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Culinaria im Farmerkreuz: oben auf 800 Meter \u00fcber dem Meeresspiegel Kulinarik genie\u00dfen und die gro\u00dfartigen Panorama Aussichten wirken lassen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-07T16:42:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-22T11:32:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/04\/Culinaria_im_Farmerkreuz-_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Culinaria im Farmerkreuz &#8211; Dorf Tirol &#8211; Italien\",\"datePublished\":\"2016-05-07T16:42:42+00:00\",\"dateModified\":\"2023-03-22T11:32:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/\"},\"wordCount\":176,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Culinaria_im_Farmerkreuz-_1.jpg\",\"keywords\":[\"Culinaria im Farmerkreuz\",\"Dorf Tirol\",\"Italien\",\"Restaurant\"],\"articleSection\":[\"Italien\",\"Restaurants\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/\",\"name\":\"Culinaria im Farmerkreuz - Dorf Tirol - Italien - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Culinaria_im_Farmerkreuz-_1.jpg\",\"datePublished\":\"2016-05-07T16:42:42+00:00\",\"dateModified\":\"2023-03-22T11:32:45+00:00\",\"description\":\"Culinaria im Farmerkreuz: oben auf 800 Meter \u00fcber dem Meeresspiegel Kulinarik genie\u00dfen und die gro\u00dfartigen Panorama Aussichten wirken lassen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Culinaria_im_Farmerkreuz-_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Culinaria_im_Farmerkreuz-_1.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2016\\\/05\\\/culinaria-im-farmerkreuz-dorf-tirol-italien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinaria im Farmerkreuz &#8211; Dorf Tirol &#8211; Italien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Culinaria im Farmerkreuz - Dorf Tirol - Italien - Unterwegs mit Weine &amp; Feinkost","description":"Culinaria im Farmerkreuz: oben auf 800 Meter \u00fcber dem Meeresspiegel Kulinarik genie\u00dfen und die gro\u00dfartigen Panorama Aussichten wirken lassen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/","og_locale":"de_DE","og_type":"article","og_title":"Culinaria im Farmerkreuz - Dorf Tirol - Italien - Unterwegs mit Weine &amp; Feinkost","og_description":"Culinaria im Farmerkreuz: oben auf 800 Meter \u00fcber dem Meeresspiegel Kulinarik genie\u00dfen und die gro\u00dfartigen Panorama Aussichten wirken lassen.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2016-05-07T16:42:42+00:00","article_modified_time":"2023-03-22T11:32:45+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/04\/Culinaria_im_Farmerkreuz-_1.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Culinaria im Farmerkreuz &#8211; Dorf Tirol &#8211; Italien","datePublished":"2016-05-07T16:42:42+00:00","dateModified":"2023-03-22T11:32:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/"},"wordCount":176,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/04\/Culinaria_im_Farmerkreuz-_1.jpg","keywords":["Culinaria im Farmerkreuz","Dorf Tirol","Italien","Restaurant"],"articleSection":["Italien","Restaurants"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/","name":"Culinaria im Farmerkreuz - Dorf Tirol - Italien - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/04\/Culinaria_im_Farmerkreuz-_1.jpg","datePublished":"2016-05-07T16:42:42+00:00","dateModified":"2023-03-22T11:32:45+00:00","description":"Culinaria im Farmerkreuz: oben auf 800 Meter \u00fcber dem Meeresspiegel Kulinarik genie\u00dfen und die gro\u00dfartigen Panorama Aussichten wirken lassen.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/04\/Culinaria_im_Farmerkreuz-_1.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/04\/Culinaria_im_Farmerkreuz-_1.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2016\/05\/culinaria-im-farmerkreuz-dorf-tirol-italien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Culinaria im Farmerkreuz &#8211; Dorf Tirol &#8211; Italien"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/04\/Culinaria_im_Farmerkreuz-_1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-8ba","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/31444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=31444"}],"version-history":[{"count":1,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/31444\/revisions"}],"predecessor-version":[{"id":197508,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/31444\/revisions\/197508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/159183"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=31444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=31444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=31444"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=31444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}