{"id":33893,"date":"2017-03-05T08:54:01","date_gmt":"2017-03-05T07:54:01","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=33893"},"modified":"2023-03-21T20:45:29","modified_gmt":"2023-03-21T19:45:29","slug":"33893-2","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/","title":{"rendered":"Calderera Godello &#8211; Bierzo &#8211; Spanien"},"content":{"rendered":"<h2>Calderera Godello &#8211; Bierzo &#8211; Spanien<\/h2>\n<p>Diese Weinkooperation zwischen Dirk Niepoort aus dem portugiesischen Douro Tal und Ra\u00fal P\u00e9rez aus dem spanischen Kesselanbaugebiet Bierzo ist ein wahrer Paukenschlag. Der Calderera, auf deutsch \u201eder Kesselflicker\u201c, ist geruchstechnisch erst einmal ein richtiger Schlag in die sogenannte \u201eFresse\u201c: oxidativer Sherry Ton, verbrannte Mandeln und ein Brei undefinierbarer Aromen ergeben erst einmal \u00fcberhaupt keinen Sinn. Geschmacklich ist der Wein durch pr\u00e4sente Gerbstoffe, eine sehr knackige S\u00e4ure und extrem viel Extrakt gepr\u00e4gt. Der Nachhall ist schon beim ersten Schluck unheimlich lang, klar und faszinierend.<\/p>\n<p>Mit Luftkontakt z\u00e4hmt sich der beissende Geruch. Haseln\u00fcsse, Fenchel, frisch aufgebr\u00fchter weisser Tee, Lavendel und unreife Birne erobern nach und nach das Geruchsfeld. Diese Facetten pr\u00e4gen nach einer halben Stunde auch den faszinierenden Geschmack. Facettenreich und mit dem Trinkenden quasi t\u00e4nzerisch spielend fesselt der Calderera Schluck auf Schluck mehr. Die komplette Metamorphose hat der Wein nach einer guten Stunde durch gemacht. Vom h\u00e4sslichen Entlein zum stolzen Schwan. Dabei so urspr\u00fcnglich und wild, dass einem das Herz vor Freude rast, wenn man nur an diesen aus der Godello Traube vinifizierten Traumstoff denkt. Dieser Wei\u00dfwein sprengt alle bisher bekannten Qualit\u00e4ts-Dimensionen, die bisher aus Spanien bekannt waren. Ein doppelter Super Applaus an die Iberische Insel und geniale Zusammenarbeit der beiden Charakterk\u00f6pfe Dirk Niepoort und Ra\u00fal P\u00e9rez!<\/p>\n<p><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/01\/Niepoort_Raoul_Perez_Calderera_Godello_Bierzo_2-e1484555937372.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-160464\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/01\/Niepoort_Raoul_Perez_Calderera_Godello_Bierzo_2-e1484555937372.jpg\" alt=\"\" width=\"480\" height=\"640\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/01\/Niepoort_Raoul_Perez_Calderera_Godello_Bierzo_2-e1484555937372.jpg 480w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/01\/Niepoort_Raoul_Perez_Calderera_Godello_Bierzo_2-e1484555937372-225x300.jpg 225w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Calderera Godello &#8211; Bierzo &#8211; Spanien Diese Weinkooperation zwischen Dirk Niepoort aus dem portugiesischen Douro Tal und Ra\u00fal P\u00e9rez aus dem spanischen Kesselanbaugebiet Bierzo ist ein wahrer Paukenschlag. Der Calderera, auf deutsch \u201eder Kesselflicker\u201c, ist geruchstechnisch erst einmal ein richtiger Schlag in die sogenannte \u201eFresse\u201c: oxidativer Sherry Ton, verbrannte Mandeln und ein Brei undefinierbarer Aromen &#8230; <a title=\"Calderera Godello &#8211; Bierzo &#8211; Spanien\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/\" aria-label=\"Mehr dazu unter Calderera Godello &#8211; Bierzo &#8211; Spanien\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":144513,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20,18],"tags":[1135,1136,1137,1090,1138,79],"post_folder":[],"class_list":["post-33893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spanien","category-weine","tag-bierzo","tag-calderera","tag-dirk-niepoort","tag-godello","tag-raul-perez","tag-spanien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calderera Godello - Bierzo - Spanien - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Der Calderera Godello von Dirk Niepoort aus dem portugiesischen Douro Tal und Ra\u00fal P\u00e9rez aus Bierzo ist ohne Frage einfach nur ein genialer Wei\u00dfwein!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calderera Godello - Bierzo - Spanien - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Der Calderera Godello von Dirk Niepoort aus dem portugiesischen Douro Tal und Ra\u00fal P\u00e9rez aus Bierzo ist ohne Frage einfach nur ein genialer Wei\u00dfwein!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-05T07:54:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T19:45:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/02\/Brots_de_Vi_Girona_Spanien_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Calderera Godello &#8211; Bierzo &#8211; Spanien\",\"datePublished\":\"2017-03-05T07:54:01+00:00\",\"dateModified\":\"2023-03-21T19:45:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/\"},\"wordCount\":235,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/Brots_de_Vi_Girona_Spanien_4.jpg\",\"keywords\":[\"Bierzo\",\"Calderera\",\"Dirk Niepoort\",\"Godello\",\"Ra\u00fal P\u00e9rez\",\"Spanien\"],\"articleSection\":[\"Spanien\",\"Weine\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/\",\"name\":\"Calderera Godello - Bierzo - Spanien - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/Brots_de_Vi_Girona_Spanien_4.jpg\",\"datePublished\":\"2017-03-05T07:54:01+00:00\",\"dateModified\":\"2023-03-21T19:45:29+00:00\",\"description\":\"Der Calderera Godello von Dirk Niepoort aus dem portugiesischen Douro Tal und Ra\u00fal P\u00e9rez aus Bierzo ist ohne Frage einfach nur ein genialer Wei\u00dfwein!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/Brots_de_Vi_Girona_Spanien_4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/Brots_de_Vi_Girona_Spanien_4.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/03\\\/33893-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calderera Godello &#8211; Bierzo &#8211; Spanien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calderera Godello - Bierzo - Spanien - Unterwegs mit Weine &amp; Feinkost","description":"Der Calderera Godello von Dirk Niepoort aus dem portugiesischen Douro Tal und Ra\u00fal P\u00e9rez aus Bierzo ist ohne Frage einfach nur ein genialer Wei\u00dfwein!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/","og_locale":"de_DE","og_type":"article","og_title":"Calderera Godello - Bierzo - Spanien - Unterwegs mit Weine &amp; Feinkost","og_description":"Der Calderera Godello von Dirk Niepoort aus dem portugiesischen Douro Tal und Ra\u00fal P\u00e9rez aus Bierzo ist ohne Frage einfach nur ein genialer Wei\u00dfwein!","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2017-03-05T07:54:01+00:00","article_modified_time":"2023-03-21T19:45:29+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/02\/Brots_de_Vi_Girona_Spanien_4.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Calderera Godello &#8211; Bierzo &#8211; Spanien","datePublished":"2017-03-05T07:54:01+00:00","dateModified":"2023-03-21T19:45:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/"},"wordCount":235,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/02\/Brots_de_Vi_Girona_Spanien_4.jpg","keywords":["Bierzo","Calderera","Dirk Niepoort","Godello","Ra\u00fal P\u00e9rez","Spanien"],"articleSection":["Spanien","Weine"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/","name":"Calderera Godello - Bierzo - Spanien - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/02\/Brots_de_Vi_Girona_Spanien_4.jpg","datePublished":"2017-03-05T07:54:01+00:00","dateModified":"2023-03-21T19:45:29+00:00","description":"Der Calderera Godello von Dirk Niepoort aus dem portugiesischen Douro Tal und Ra\u00fal P\u00e9rez aus Bierzo ist ohne Frage einfach nur ein genialer Wei\u00dfwein!","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/02\/Brots_de_Vi_Girona_Spanien_4.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/02\/Brots_de_Vi_Girona_Spanien_4.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/03\/33893-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Calderera Godello &#8211; Bierzo &#8211; Spanien"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2014\/02\/Brots_de_Vi_Girona_Spanien_4.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-8OF","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/33893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=33893"}],"version-history":[{"count":1,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/33893\/revisions"}],"predecessor-version":[{"id":197419,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/33893\/revisions\/197419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/144513"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=33893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=33893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=33893"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=33893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}