{"id":34282,"date":"2017-04-15T11:00:20","date_gmt":"2017-04-15T09:00:20","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=34282"},"modified":"2023-04-05T14:19:20","modified_gmt":"2023-04-05T12:19:20","slug":"34282-2","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/","title":{"rendered":"Ch\u00e2teau de Manissy Tavel ros\u00e9 2014"},"content":{"rendered":"<h2>Ch\u00e2teau de Manissy Tavel ros\u00e9 2014 &#8211; Tavel &#8211; Frankreich<\/h2>\n<p>Noch nicht einmal 1000 Hektar Weinberge stehen f\u00fcr die Produktion des ersten jemals produzierten Ros\u00e9wein Frankreichs, dem Tavel, zur Verf\u00fcgung. Rund um das D\u00f6rflein Tavel verteilen sich die teils sehr alten Rebsorten Grenache, Cinsault, Syrah, Mourv\u00e8dre, Clairette Blanche, Bourboulenc, Piquepoul Blanc und Carignan.<\/p>\n<p>Waren die Tavel Weine fr\u00fcher f\u00fcr ihre gute Lagerf\u00e4higkeit bekannt und ber\u00fchmt, werden heutzutage immer mehr dichtfarbige Ros\u00e9s mit einer hohen Fruchtf\u00fclle abgef\u00fcllt. Das Ch\u00e2teau de Manissy keltert neben einem modernen Tavel aber noch ein spannendes Pendant:<\/p>\n<p>Ein rostfarbiges, oxidiertes Gew\u00e4chs, welches erst nach fast zwei Jahren Fass- und Flaschenlagerung auf den Markt kommt. Gem\u00fcse, Erde, Blutorange und Blumennoten sind seine Hauptaromen. Wie ein frischer Fino aus Jerez mutet der Geschmack an, dazu gesellt sich eine herzhafte S\u00e4ure und sogar starke Gerbstoffe verbinden sich zum Gesamtgeschmacksbild genial hinzu. Diese stabilen Tannine entstehen durch die gemeinsame Verg\u00e4rung mit den Rappen und Stielen des Lesegutes.<\/p>\n<p>Dieser Ros\u00e9&nbsp; ist wie ein Zeitzeuge einer vergangenen Zeit, als Weine noch mit viel Handwerk und Tradition erzeugt wurden und haupts\u00e4chlich als Essensbegleiter getrunken wurden. Herzhaft, w\u00fcrzig, anders \u2026 und lecker!<\/p>\n<p><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Tavel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-160648\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Tavel.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Tavel.jpg 640w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Tavel-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Tavel-600x450.jpg 600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ch\u00e2teau de Manissy Tavel ros\u00e9 2014 &#8211; Tavel &#8211; Frankreich Noch nicht einmal 1000 Hektar Weinberge stehen f\u00fcr die Produktion des ersten jemals produzierten Ros\u00e9wein Frankreichs, dem Tavel, zur Verf\u00fcgung. Rund um das D\u00f6rflein Tavel verteilen sich die teils sehr alten Rebsorten Grenache, Cinsault, Syrah, Mourv\u00e8dre, Clairette Blanche, Bourboulenc, Piquepoul Blanc und Carignan. Waren die &#8230; <a title=\"Ch\u00e2teau de Manissy Tavel ros\u00e9 2014\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/\" aria-label=\"Mehr dazu unter Ch\u00e2teau de Manissy Tavel ros\u00e9 2014\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":164139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21,18],"tags":[131,1171,141,1179,1172],"post_folder":[],"class_list":["post-34282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frankreich","category-weine","tag-131","tag-chateau-de-manissy","tag-frankreich","tag-rose","tag-tavel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ch\u00e2teau de Manissy Tavel ros\u00e9 2014 - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Ch\u00e2teau de Manissy ros\u00e9 2014 ein mehr als klassischer Wein aus Tavel in S\u00fcdfrankreich.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ch\u00e2teau de Manissy Tavel ros\u00e9 2014 - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Ch\u00e2teau de Manissy ros\u00e9 2014 ein mehr als klassischer Wein aus Tavel in S\u00fcdfrankreich.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-15T09:00:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-05T12:19:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/08\/Halcon_Cofino_Spanien_10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Ch\u00e2teau de Manissy Tavel ros\u00e9 2014\",\"datePublished\":\"2017-04-15T09:00:20+00:00\",\"dateModified\":\"2023-04-05T12:19:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/\"},\"wordCount\":211,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/Halcon_Cofino_Spanien_10.jpg\",\"keywords\":[\"2014\",\"Ch\u00e2teau de Manissy\",\"Frankreich\",\"ros\u00e9\",\"Tavel\"],\"articleSection\":[\"Frankreich\",\"Weine\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/\",\"name\":\"Ch\u00e2teau de Manissy Tavel ros\u00e9 2014 - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/Halcon_Cofino_Spanien_10.jpg\",\"datePublished\":\"2017-04-15T09:00:20+00:00\",\"dateModified\":\"2023-04-05T12:19:20+00:00\",\"description\":\"Ch\u00e2teau de Manissy ros\u00e9 2014 ein mehr als klassischer Wein aus Tavel in S\u00fcdfrankreich.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/Halcon_Cofino_Spanien_10.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/Halcon_Cofino_Spanien_10.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/34282-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ch\u00e2teau de Manissy Tavel ros\u00e9 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ch\u00e2teau de Manissy Tavel ros\u00e9 2014 - Unterwegs mit Weine &amp; Feinkost","description":"Ch\u00e2teau de Manissy ros\u00e9 2014 ein mehr als klassischer Wein aus Tavel in S\u00fcdfrankreich.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/","og_locale":"de_DE","og_type":"article","og_title":"Ch\u00e2teau de Manissy Tavel ros\u00e9 2014 - Unterwegs mit Weine &amp; Feinkost","og_description":"Ch\u00e2teau de Manissy ros\u00e9 2014 ein mehr als klassischer Wein aus Tavel in S\u00fcdfrankreich.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2017-04-15T09:00:20+00:00","article_modified_time":"2023-04-05T12:19:20+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/08\/Halcon_Cofino_Spanien_10.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Ch\u00e2teau de Manissy Tavel ros\u00e9 2014","datePublished":"2017-04-15T09:00:20+00:00","dateModified":"2023-04-05T12:19:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/"},"wordCount":211,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/08\/Halcon_Cofino_Spanien_10.jpg","keywords":["2014","Ch\u00e2teau de Manissy","Frankreich","ros\u00e9","Tavel"],"articleSection":["Frankreich","Weine"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/","name":"Ch\u00e2teau de Manissy Tavel ros\u00e9 2014 - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/08\/Halcon_Cofino_Spanien_10.jpg","datePublished":"2017-04-15T09:00:20+00:00","dateModified":"2023-04-05T12:19:20+00:00","description":"Ch\u00e2teau de Manissy ros\u00e9 2014 ein mehr als klassischer Wein aus Tavel in S\u00fcdfrankreich.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/08\/Halcon_Cofino_Spanien_10.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/08\/Halcon_Cofino_Spanien_10.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/34282-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Ch\u00e2teau de Manissy Tavel ros\u00e9 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/08\/Halcon_Cofino_Spanien_10.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-8UW","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/34282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=34282"}],"version-history":[{"count":1,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/34282\/revisions"}],"predecessor-version":[{"id":198721,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/34282\/revisions\/198721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/164139"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=34282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=34282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=34282"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=34282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}