{"id":34285,"date":"2017-04-16T11:00:25","date_gmt":"2017-04-16T09:00:25","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=34285"},"modified":"2017-04-16T11:00:25","modified_gmt":"2017-04-16T09:00:25","slug":"langzeit-kater","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/","title":{"rendered":"Langzeit Kater"},"content":{"rendered":"<h2>Langzeit Kater<\/h2>\n<p>Schwer angeschlagen ist das einzige lebende Wein Weltkulturerbe in das neue Lebensjahr 2017 gelangt. Die Silvesternacht verbrachte er zun\u00e4chst noch frohen Mutes in der Erwartung eines kapitalen Men\u00fcs und einiger berauschender, fl\u00fcssiger Gl\u00fccksmomente; ein schwerer Filmriss und der anschlie\u00dfende kapitale Champagner- Kater am Neujahrsmorgen, plus einige verst\u00f6rende Bilder, auf denen er in kompromittierenden Posen abgeblitzt wurde, setzen dem Weinweltkulturerbe allerdings immer noch schwer zu. Dass er \u00fcber Nacht in einem alten Kleiderschrank seines gro\u00dfen Vorbildes Louis XIV. aufgewacht ist, kann er bis zum heutigen Tage noch nicht fassen.<\/p>\n<p>Eine k\u00fcrzlich abgehaltene Lesung mit begleitender Edel-Korn Probe im engsten Freundeskreis geriet zur absoluten Farce, und neben den inneren Organen scheinen nun wohl auch erste seelische Sch\u00e4den beim als \u201eFels in der Brandung\u201c betitelten Weinexperten aufgetreten zu sein. Eine professionelle Behandlung eines von der Unesco zu Hilfe geeilten \u00c4rzteteams, soll das Urgestein nun in einer aufw\u00e4ndigen Reha in einer Spezialklinik im Sauerland wieder auf die Beine bringen.<\/p>\n<p>Die besorgniserregende Diagnose eines Langzeitkaters ist bis jetzt allerdings noch nicht best\u00e4tigt worden.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-160650\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_2.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_2.jpg 640w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_2-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_2-600x450.jpg 600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Die Silvesternacht zum neuen Jahr 2017.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_4-e1487337645324.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-160652\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_4-e1487337645324.jpg\" alt=\"\" width=\"480\" height=\"640\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_4-e1487337645324.jpg 480w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_4-e1487337645324-225x300.jpg 225w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Der Schlummertrunk.<\/p>\n<p><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-160649\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_1.jpg\" alt=\"\" width=\"480\" height=\"640\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_1.jpg 480w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_1-225x300.jpg 225w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Misslungene Lesung vor Freunden mit Edel-Korn Tasting.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-160651\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_3.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_3.jpg 640w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_3-300x225.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_3-600x450.jpg 600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Warten auf das \u00c4rzteteam in einem Wartezimmer im Sauerl\u00e4ndischen Brilon. M\u00f6gliche Diagnose: Langzeitkater.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Langzeit Kater Schwer angeschlagen ist das einzige lebende Wein Weltkulturerbe in das neue Lebensjahr 2017 gelangt. Die Silvesternacht verbrachte er zun\u00e4chst noch frohen Mutes in der Erwartung eines kapitalen Men\u00fcs und einiger berauschender, fl\u00fcssiger Gl\u00fccksmomente; ein schwerer Filmriss und der anschlie\u00dfende kapitale Champagner- Kater am Neujahrsmorgen, plus einige verst\u00f6rende Bilder, auf denen er in kompromittierenden &#8230; <a title=\"Langzeit Kater\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/\" aria-label=\"Mehr dazu unter Langzeit Kater\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":160650,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[64],"tags":[1180],"post_folder":[],"class_list":["post-34285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weinminister","tag-langzeit-kater"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Langzeit Kater - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Das einzige lebende Wein Weltkulturerbe kommt nur schwer in das neue Jahr 2017. Einen Langzeit Kater schlie\u00dft ein Expertenteam zur Zeit nicht mehr aus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Langzeit Kater - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Das einzige lebende Wein Weltkulturerbe kommt nur schwer in das neue Jahr 2017. Einen Langzeit Kater schlie\u00dft ein Expertenteam zur Zeit nicht mehr aus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-16T09:00:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Langzeit Kater\",\"datePublished\":\"2017-04-16T09:00:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/\"},\"wordCount\":211,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Langzeit_Kater_2.jpg\",\"keywords\":[\"Langzeit Kater\"],\"articleSection\":[\"Weinminister (Satire)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/\",\"name\":\"Langzeit Kater - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Langzeit_Kater_2.jpg\",\"datePublished\":\"2017-04-16T09:00:25+00:00\",\"description\":\"Das einzige lebende Wein Weltkulturerbe kommt nur schwer in das neue Jahr 2017. Einen Langzeit Kater schlie\u00dft ein Expertenteam zur Zeit nicht mehr aus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Langzeit_Kater_2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Langzeit_Kater_2.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2017\\\/04\\\/langzeit-kater\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Langzeit Kater\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Langzeit Kater - Unterwegs mit Weine &amp; Feinkost","description":"Das einzige lebende Wein Weltkulturerbe kommt nur schwer in das neue Jahr 2017. Einen Langzeit Kater schlie\u00dft ein Expertenteam zur Zeit nicht mehr aus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/","og_locale":"de_DE","og_type":"article","og_title":"Langzeit Kater - Unterwegs mit Weine &amp; Feinkost","og_description":"Das einzige lebende Wein Weltkulturerbe kommt nur schwer in das neue Jahr 2017. Einen Langzeit Kater schlie\u00dft ein Expertenteam zur Zeit nicht mehr aus.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2017-04-16T09:00:25+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_2.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Langzeit Kater","datePublished":"2017-04-16T09:00:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/"},"wordCount":211,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_2.jpg","keywords":["Langzeit Kater"],"articleSection":["Weinminister (Satire)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/","name":"Langzeit Kater - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_2.jpg","datePublished":"2017-04-16T09:00:25+00:00","description":"Das einzige lebende Wein Weltkulturerbe kommt nur schwer in das neue Jahr 2017. Einen Langzeit Kater schlie\u00dft ein Expertenteam zur Zeit nicht mehr aus.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_2.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_2.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2017\/04\/langzeit-kater\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Langzeit Kater"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/02\/Langzeit_Kater_2.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-8UZ","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/34285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=34285"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/34285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/160650"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=34285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=34285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=34285"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=34285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}