{"id":39392,"date":"2018-02-13T11:00:47","date_gmt":"2018-02-13T10:00:47","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=39392"},"modified":"2023-03-24T10:03:56","modified_gmt":"2023-03-24T09:03:56","slug":"shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/","title":{"rendered":"Shafer Stags Leap District Hillside Select 2009 &#8211; Napa Valley &#8211; Kalifornien &#8211; U.S.A"},"content":{"rendered":"<h2>Shafer Stags Leap District Hillside Select 2009 &#8211; Napa Valley &#8211; Kalifornien &#8211; U.S.A<\/h2>\n<p>Der Shafer Stags Leap District Hillside Select ist einer dieser kalifornischen Rotwein Ikonen, die jeder Weinliebhaber gerne einmal im Glas haben m\u00f6chte. Oft schwingt nat\u00fcrlich schon im Vorfeld solcher Proben die Annahme im Kopf herum \u2026 \u201eOh weh, schon wieder so einer dieser aufgemotzten Neue Welt Cabernet Sauvignon\u00b4s\u201c \u2026<\/p>\n<p>Der 2009er Hillside Select straft jedoch jedem dieser Kritiker schon nach dem ersten Hineinriechen in das Glas L\u00fcgen. Hier begeistern auf Anhieb reife rote Fr\u00fcchte, Pinienwald, jede Menge reife schwarze Johannisbeeren und viel Nougat. Auch Kokosnuss und Vanille Noten vom Barriqueeinsatz lassen sich nicht verhehlen; sie wirken nicht k\u00fcnstlich oder aufgesetzt, sondern sind perfekt in das fl\u00fcssige Gesamtkunstwerk eingebunden.<\/p>\n<p>Auch geschmacklich best\u00e4tigen sich genau diese Sinneseindr\u00fccke. Der Rebensaft wirkt dabei fast schon z\u00e4hfl\u00fcssig und weisst eine Dichte und L\u00e4nge im Abgang auf, die wahrlich beeindruckt. Ein perfekter Cabernet, ohne Ecken, ohne Kanten, enormem Extrakt, einer unwiderstehlichen Fruchtf\u00fclle, die ihresgleichen sucht. Dabei wirkt dieser Shafer noch jugendlich, zeigt \u00fcberhaupt keinen Ansatz von Reife und wird wahrscheinlich noch in Jahrzehnten wie eine Eins im Glas stehen. Beeindruckend!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shafer Stags Leap District Hillside Select 2009 &#8211; Napa Valley &#8211; Kalifornien &#8211; U.S.A Der Shafer Stags Leap District Hillside Select ist einer dieser kalifornischen Rotwein Ikonen, die jeder Weinliebhaber gerne einmal im Glas haben m\u00f6chte. Oft schwingt nat\u00fcrlich schon im Vorfeld solcher Proben die Annahme im Kopf herum \u2026 \u201eOh weh, schon wieder so &#8230; <a title=\"Shafer Stags Leap District Hillside Select 2009 &#8211; Napa Valley &#8211; Kalifornien &#8211; U.S.A\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/\" aria-label=\"Mehr dazu unter Shafer Stags Leap District Hillside Select 2009 &#8211; Napa Valley &#8211; Kalifornien &#8211; U.S.A\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":162469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[25,18],"tags":[463,316,1531,1532,1162],"post_folder":[],"class_list":["post-39392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-usa","category-weine","tag-463","tag-kalifornien","tag-napa-valley","tag-shafer-stags-leap-district-hillside-select","tag-u-s-a"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Shafer Stags Leap District Hillside Select 2009 - Napa Valley - Kalifornien - U.S.A - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Eine Weinlegende und dies auch zu recht: der Shafer Stags Leap District Hillside Select 2009 aus Napa Valley\/Kalifornien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shafer Stags Leap District Hillside Select 2009 - Napa Valley - Kalifornien - U.S.A - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Eine Weinlegende und dies auch zu recht: der Shafer Stags Leap District Hillside Select 2009 aus Napa Valley\/Kalifornien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-13T10:00:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-24T09:03:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/12\/Shafer_Stags_Leap_District_Hillside_Select_2009_Napa_Valley_Kalifornien_USA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Shafer Stags Leap District Hillside Select 2009 &#8211; Napa Valley &#8211; Kalifornien &#8211; U.S.A\",\"datePublished\":\"2018-02-13T10:00:47+00:00\",\"dateModified\":\"2023-03-24T09:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/\"},\"wordCount\":215,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Shafer_Stags_Leap_District_Hillside_Select_2009_Napa_Valley_Kalifornien_USA.jpg\",\"keywords\":[\"2009\",\"Kalifornien\",\"Napa Valley\",\"Shafer Stags Leap District Hillside Select\",\"U.S.A\"],\"articleSection\":[\"USA\",\"Weine\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/\",\"name\":\"Shafer Stags Leap District Hillside Select 2009 - Napa Valley - Kalifornien - U.S.A - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Shafer_Stags_Leap_District_Hillside_Select_2009_Napa_Valley_Kalifornien_USA.jpg\",\"datePublished\":\"2018-02-13T10:00:47+00:00\",\"dateModified\":\"2023-03-24T09:03:56+00:00\",\"description\":\"Eine Weinlegende und dies auch zu recht: der Shafer Stags Leap District Hillside Select 2009 aus Napa Valley\\\/Kalifornien.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Shafer_Stags_Leap_District_Hillside_Select_2009_Napa_Valley_Kalifornien_USA.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Shafer_Stags_Leap_District_Hillside_Select_2009_Napa_Valley_Kalifornien_USA.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shafer Stags Leap District Hillside Select 2009 &#8211; Napa Valley &#8211; Kalifornien &#8211; U.S.A\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shafer Stags Leap District Hillside Select 2009 - Napa Valley - Kalifornien - U.S.A - Unterwegs mit Weine &amp; Feinkost","description":"Eine Weinlegende und dies auch zu recht: der Shafer Stags Leap District Hillside Select 2009 aus Napa Valley\/Kalifornien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/","og_locale":"de_DE","og_type":"article","og_title":"Shafer Stags Leap District Hillside Select 2009 - Napa Valley - Kalifornien - U.S.A - Unterwegs mit Weine &amp; Feinkost","og_description":"Eine Weinlegende und dies auch zu recht: der Shafer Stags Leap District Hillside Select 2009 aus Napa Valley\/Kalifornien.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2018-02-13T10:00:47+00:00","article_modified_time":"2023-03-24T09:03:56+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/12\/Shafer_Stags_Leap_District_Hillside_Select_2009_Napa_Valley_Kalifornien_USA.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Shafer Stags Leap District Hillside Select 2009 &#8211; Napa Valley &#8211; Kalifornien &#8211; U.S.A","datePublished":"2018-02-13T10:00:47+00:00","dateModified":"2023-03-24T09:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/"},"wordCount":215,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/12\/Shafer_Stags_Leap_District_Hillside_Select_2009_Napa_Valley_Kalifornien_USA.jpg","keywords":["2009","Kalifornien","Napa Valley","Shafer Stags Leap District Hillside Select","U.S.A"],"articleSection":["USA","Weine"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/","name":"Shafer Stags Leap District Hillside Select 2009 - Napa Valley - Kalifornien - U.S.A - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/12\/Shafer_Stags_Leap_District_Hillside_Select_2009_Napa_Valley_Kalifornien_USA.jpg","datePublished":"2018-02-13T10:00:47+00:00","dateModified":"2023-03-24T09:03:56+00:00","description":"Eine Weinlegende und dies auch zu recht: der Shafer Stags Leap District Hillside Select 2009 aus Napa Valley\/Kalifornien.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/12\/Shafer_Stags_Leap_District_Hillside_Select_2009_Napa_Valley_Kalifornien_USA.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/12\/Shafer_Stags_Leap_District_Hillside_Select_2009_Napa_Valley_Kalifornien_USA.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/shafer-stags-leap-district-hillside-select-2009-napa-valley-kalifornien-u-s-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Shafer Stags Leap District Hillside Select 2009 &#8211; Napa Valley &#8211; Kalifornien &#8211; U.S.A"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2017\/12\/Shafer_Stags_Leap_District_Hillside_Select_2009_Napa_Valley_Kalifornien_USA.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-afm","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/39392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=39392"}],"version-history":[{"count":1,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/39392\/revisions"}],"predecessor-version":[{"id":198151,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/39392\/revisions\/198151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/162469"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=39392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=39392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=39392"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=39392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}