{"id":40114,"date":"2018-02-16T11:00:06","date_gmt":"2018-02-16T10:00:06","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=40114"},"modified":"2018-02-16T11:00:06","modified_gmt":"2018-02-16T10:00:06","slug":"azamor-2014-selected-white-alentejo-portugal","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/","title":{"rendered":"Azamor 2014 selected white &#8211; Alentejo &#8211; Portugal"},"content":{"rendered":"<h2>Azamor 2014 selected white &#8211; Alentejo &#8211; Portugal<\/h2>\n<p>Die Hauptstadt Portugals hat in den letzten Jahren einen wahnsinnigen Wandel durchlebt. Aus vielen Bauruinen wurden kleine schnuckelige Gesch\u00e4fte, alternative Hotels wurden er\u00f6ffnet, die Menschen k\u00f6nnen hier auf einmal auch sehr nett sein und hat man vor ein paar Jahren noch verzweifelt nach einer guten Weinbar gesucht, findet man diese heute an fast jeder Ecke. Viele junge und motivierte Menschen haben ihre Zukunft selber in die Hand genommen und leben hier nun europ\u00e4isiert ihre eigene Tradition. Aus einem wehm\u00fctigen Fado Gejaule aus dunklen, einsamen Kellergew\u00f6lben ist ein selbstbewusster, stolzer Fado Gesang geworden. Auch die Wein und Tapa Bar A Muralha ist so ein neuer Prototyp eines positiven Aufbruchs. Die gut selektionierten Weine werden mit dem Coravin System glasweise ausgeschenkt. Das gro\u00dfe Schinkenhinterbein hat 24 Monate Reifezeit auf dem Buckel und steht verf\u00fchrerisch auf der Theke, die Musik aus den Lautsprechern ist fr\u00f6hlich, auch wenn die Fado Gitarre schon drohend in der Ecke auf ihren Einsatz wartet. Das Team ist hier so nett, dass man fast schon glaubt, in Italien zu verweilen. Der hier kurz vor dem Abendmahl als Aperitif probierte 2014er Azamor selected white begeistert durch eine k\u00fchle Frische am Gaumen, dem ein klarer Duft nach Zitronen, Birnen, wei\u00dfem Tee und knackigen R\u00fcben vorausgegangen ist. Der Holzeinsatz ist sp\u00fcrbar und genial in die Frucht integriert. Keinerlei Oxidation, nur klar und fein. Der Abgang ist verspielt und lang anhaltend. Eine gro\u00dfartige Cuv\u00e9e aus den beiden portugiesischen autochthonen Rebsorten Ant\u00e3o Vaz und Arinto.<\/p>\n<p><b>162 Punkte von 365 WKE Punkten*<\/b><\/p>\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Azamor 2014 selected white &#8211; Alentejo &#8211; Portugal Die Hauptstadt Portugals hat in den letzten Jahren einen wahnsinnigen Wandel durchlebt. Aus vielen Bauruinen wurden kleine schnuckelige Gesch\u00e4fte, alternative Hotels wurden er\u00f6ffnet, die Menschen k\u00f6nnen hier auf einmal auch sehr nett sein und hat man vor ein paar Jahren noch verzweifelt nach einer guten Weinbar gesucht, &#8230; <a title=\"Azamor 2014 selected white &#8211; Alentejo &#8211; Portugal\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/\" aria-label=\"Mehr dazu unter Azamor 2014 selected white &#8211; Alentejo &#8211; Portugal\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":145767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[63,18],"tags":[1537,1571,1572,850],"post_folder":[],"class_list":["post-40114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-weine","tag-alentejo","tag-azamor","tag-lissabon","tag-portugal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Azamor 2014 selected white - Alentejo - Portugal - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"In der portugiesischen Tapa Bar A Muralha in Lissabon kann man ein tolles Glas Azamor 2014 selected white verk\u00f6stigen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Azamor 2014 selected white - Alentejo - Portugal - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"In der portugiesischen Tapa Bar A Muralha in Lissabon kann man ein tolles Glas Azamor 2014 selected white verk\u00f6stigen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-16T10:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/01\/azamor_selected_white_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Azamor 2014 selected white &#8211; Alentejo &#8211; Portugal\",\"datePublished\":\"2018-02-16T10:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/\"},\"wordCount\":284,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/azamor_selected_white_1.jpg\",\"keywords\":[\"Alentejo\",\"Azamor\",\"Lissabon\",\"Portugal\"],\"articleSection\":{\"1\":\"Weine\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/\",\"name\":\"Azamor 2014 selected white - Alentejo - Portugal - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/azamor_selected_white_1.jpg\",\"datePublished\":\"2018-02-16T10:00:06+00:00\",\"description\":\"In der portugiesischen Tapa Bar A Muralha in Lissabon kann man ein tolles Glas Azamor 2014 selected white verk\u00f6stigen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/azamor_selected_white_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/azamor_selected_white_1.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/02\\\/azamor-2014-selected-white-alentejo-portugal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Azamor 2014 selected white &#8211; Alentejo &#8211; Portugal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Azamor 2014 selected white - Alentejo - Portugal - Unterwegs mit Weine &amp; Feinkost","description":"In der portugiesischen Tapa Bar A Muralha in Lissabon kann man ein tolles Glas Azamor 2014 selected white verk\u00f6stigen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/","og_locale":"de_DE","og_type":"article","og_title":"Azamor 2014 selected white - Alentejo - Portugal - Unterwegs mit Weine &amp; Feinkost","og_description":"In der portugiesischen Tapa Bar A Muralha in Lissabon kann man ein tolles Glas Azamor 2014 selected white verk\u00f6stigen.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2018-02-16T10:00:06+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/01\/azamor_selected_white_1.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Azamor 2014 selected white &#8211; Alentejo &#8211; Portugal","datePublished":"2018-02-16T10:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/"},"wordCount":284,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/01\/azamor_selected_white_1.jpg","keywords":["Alentejo","Azamor","Lissabon","Portugal"],"articleSection":{"1":"Weine"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/","name":"Azamor 2014 selected white - Alentejo - Portugal - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/01\/azamor_selected_white_1.jpg","datePublished":"2018-02-16T10:00:06+00:00","description":"In der portugiesischen Tapa Bar A Muralha in Lissabon kann man ein tolles Glas Azamor 2014 selected white verk\u00f6stigen.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/01\/azamor_selected_white_1.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/01\/azamor_selected_white_1.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/02\/azamor-2014-selected-white-alentejo-portugal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Azamor 2014 selected white &#8211; Alentejo &#8211; Portugal"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/01\/azamor_selected_white_1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-ar0","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/40114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=40114"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/40114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/145767"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=40114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=40114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=40114"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=40114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}