{"id":40788,"date":"2018-04-25T11:00:11","date_gmt":"2018-04-25T09:00:11","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=40788"},"modified":"2023-03-24T09:57:10","modified_gmt":"2023-03-24T08:57:10","slug":"francois-crochet-sancerre-2016-loire-frankreich","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/","title":{"rendered":"Fran\u00e7ois Crochet Sancerre 2016 &#8211; Loire &#8211; Frankreich"},"content":{"rendered":"<h2>Fran\u00e7ois Crochet Sancerre 2016 &#8211; Loire &#8211; Frankreich<\/h2>\n<p>Fruchtaromen hat dieser Sauvignon Blanc von Fran\u00e7ois Crochet wahrlich nicht an Bord (h\u00f6chstens ein paar Zitrusaromen).<\/p>\n<p>Eher karg, steinig und puristisch ist sein komplettes einnehmendes Wesen, dabei begeistert er mit einer pr\u00e4zisen Frische, welche schon fast als unheimlich einzustufen ist. Alles wirkt wie eine bemerkenswerte Synthese aus steinigem Boden und vollreifem Traubenmaterial.<\/p>\n<p>Die geradlinige S\u00e4urestruktur bildet bei diesem Gew\u00e4chs dann noch das geniale Momentum, welches den Mundbereich bei jedem Schluck komplett reinigt und einfach nur Durst auf mehr macht.<\/p>\n<p>Hier scheint ein wahrer Meister seines Faches mit Zauberhand am Werk gewesen zu sein. Sauvignon Blanc in Reinkultur ohne Dropsigkeit und schn\u00f6rkellos umschmeichelnd.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fran\u00e7ois Crochet Sancerre 2016 &#8211; Loire &#8211; Frankreich Fruchtaromen hat dieser Sauvignon Blanc von Fran\u00e7ois Crochet wahrlich nicht an Bord (h\u00f6chstens ein paar Zitrusaromen). Eher karg, steinig und puristisch ist sein komplettes einnehmendes Wesen, dabei begeistert er mit einer pr\u00e4zisen Frische, welche schon fast als unheimlich einzustufen ist. Alles wirkt wie eine bemerkenswerte Synthese aus &#8230; <a title=\"Fran\u00e7ois Crochet Sancerre 2016 &#8211; Loire &#8211; Frankreich\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/\" aria-label=\"Mehr dazu unter Fran\u00e7ois Crochet Sancerre 2016 &#8211; Loire &#8211; Frankreich\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":142421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21,18],"tags":[1049,1659,141,460,462],"post_folder":[],"class_list":["post-40788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frankreich","category-weine","tag-1049","tag-francois-crochet","tag-frankreich","tag-loire","tag-sancerre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fran\u00e7ois Crochet Sancerre 2016 - Loire - Frankreich - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Puristisch und klar der Sancerre von Fran\u00e7ois Crochet Sancerre aus dem Jahrgang 2016.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fran\u00e7ois Crochet Sancerre 2016 - Loire - Frankreich - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Puristisch und klar der Sancerre von Fran\u00e7ois Crochet Sancerre aus dem Jahrgang 2016.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-25T09:00:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-24T08:57:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/04\/Francois_Crochet_Sancerre_2016_Loire_Frankreich.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Fran\u00e7ois Crochet Sancerre 2016 &#8211; Loire &#8211; Frankreich\",\"datePublished\":\"2018-04-25T09:00:11+00:00\",\"dateModified\":\"2023-03-24T08:57:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/\"},\"wordCount\":124,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Francois_Crochet_Sancerre_2016_Loire_Frankreich.jpg\",\"keywords\":[\"2016\",\"Fran\u00e7ois Crochet\",\"Frankreich\",\"Loire\",\"Sancerre\"],\"articleSection\":[\"Frankreich\",\"Weine\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/\",\"name\":\"Fran\u00e7ois Crochet Sancerre 2016 - Loire - Frankreich - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Francois_Crochet_Sancerre_2016_Loire_Frankreich.jpg\",\"datePublished\":\"2018-04-25T09:00:11+00:00\",\"dateModified\":\"2023-03-24T08:57:10+00:00\",\"description\":\"Puristisch und klar der Sancerre von Fran\u00e7ois Crochet Sancerre aus dem Jahrgang 2016.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Francois_Crochet_Sancerre_2016_Loire_Frankreich.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Francois_Crochet_Sancerre_2016_Loire_Frankreich.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2018\\\/04\\\/francois-crochet-sancerre-2016-loire-frankreich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fran\u00e7ois Crochet Sancerre 2016 &#8211; Loire &#8211; Frankreich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fran\u00e7ois Crochet Sancerre 2016 - Loire - Frankreich - Unterwegs mit Weine &amp; Feinkost","description":"Puristisch und klar der Sancerre von Fran\u00e7ois Crochet Sancerre aus dem Jahrgang 2016.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/","og_locale":"de_DE","og_type":"article","og_title":"Fran\u00e7ois Crochet Sancerre 2016 - Loire - Frankreich - Unterwegs mit Weine &amp; Feinkost","og_description":"Puristisch und klar der Sancerre von Fran\u00e7ois Crochet Sancerre aus dem Jahrgang 2016.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2018-04-25T09:00:11+00:00","article_modified_time":"2023-03-24T08:57:10+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/04\/Francois_Crochet_Sancerre_2016_Loire_Frankreich.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Fran\u00e7ois Crochet Sancerre 2016 &#8211; Loire &#8211; Frankreich","datePublished":"2018-04-25T09:00:11+00:00","dateModified":"2023-03-24T08:57:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/"},"wordCount":124,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/04\/Francois_Crochet_Sancerre_2016_Loire_Frankreich.jpg","keywords":["2016","Fran\u00e7ois Crochet","Frankreich","Loire","Sancerre"],"articleSection":["Frankreich","Weine"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/","name":"Fran\u00e7ois Crochet Sancerre 2016 - Loire - Frankreich - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/04\/Francois_Crochet_Sancerre_2016_Loire_Frankreich.jpg","datePublished":"2018-04-25T09:00:11+00:00","dateModified":"2023-03-24T08:57:10+00:00","description":"Puristisch und klar der Sancerre von Fran\u00e7ois Crochet Sancerre aus dem Jahrgang 2016.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/04\/Francois_Crochet_Sancerre_2016_Loire_Frankreich.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/04\/Francois_Crochet_Sancerre_2016_Loire_Frankreich.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2018\/04\/francois-crochet-sancerre-2016-loire-frankreich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Fran\u00e7ois Crochet Sancerre 2016 &#8211; Loire &#8211; Frankreich"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2018\/04\/Francois_Crochet_Sancerre_2016_Loire_Frankreich.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-aBS","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/40788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=40788"}],"version-history":[{"count":1,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/40788\/revisions"}],"predecessor-version":[{"id":198133,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/40788\/revisions\/198133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/142421"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=40788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=40788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=40788"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=40788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}