{"id":55239,"date":"2019-02-01T11:00:25","date_gmt":"2019-02-01T10:00:25","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=55239"},"modified":"2023-03-20T10:26:58","modified_gmt":"2023-03-20T09:26:58","slug":"ristorante-la-locanda-di-federico-typisch","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/","title":{"rendered":"Ristorante La Locanda di Federico &#8211; Bari &#8211; Italien"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Ristorante La Locanda di Federico &#8211; Typisch italienisch<\/h3>\n\n\n\n<p class=\"has-drop-cap\">Am Rande der bezaubernden Altstadt von Bari an der Piazza Mercantile liegt das Ristorante La Locanda di Federico. Eine einfache, typische und rustikale Trattoria. Hier k\u00f6nnen die heimischen Gerichte Apuliens bestellt und probiert werden.<\/p>\n\n\n\n<p>Im La Locanda di Federico geht es ehrlich und klassisch zu. Kein Chichi, kein Brimborium, nur so wie die Mama in Bari schon immer gekocht hat. Hausgemachte Pasta, sehr viel aus dem direkt vor der T\u00fcr liegendem Meer, Gem\u00fcse und Salat. Bene!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_6.jpg\" alt=\"\" class=\"wp-image-55247\"\/><figcaption class=\"wp-element-caption\">Einer der Speiser\u00e4ume im Ristorante La Locanda di Federico.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_1.jpg\" alt=\"\" class=\"wp-image-55242\"\/><figcaption class=\"wp-element-caption\">Brot und Tapenade.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_4.jpg\" alt=\"\" class=\"wp-image-55245\"\/><figcaption class=\"wp-element-caption\">Gemischter Salat.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_3.jpg\" alt=\"\" class=\"wp-image-55244\"\/><figcaption class=\"wp-element-caption\">Linguine und Hummer.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_2-1.jpg\" alt=\"\" class=\"wp-image-55282\"\/><figcaption class=\"wp-element-caption\">Mit ger\u00e4uchertem Scamorza K\u00e4se gef\u00fcllte Cappelli, Artischockensauce und Bacon.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_5.jpg\" alt=\"\" class=\"wp-image-55246\"\/><figcaption class=\"wp-element-caption\">Gambas und Kaisergranat.<\/figcaption><\/figure>\n<\/div>\n\n\n<p><strong>Ristorante La Locanda di Federico<\/strong> Piazza Mercantile, 63 &#8211; 70122 Bari -Italien &#8211; Telefon: +39 080 522 7705 <a href=\"http:\/\/www.lalocandadifederico.com\/\">www.lalocandadifederico.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ristorante La Locanda di Federico &#8211; Typisch italienisch Am Rande der bezaubernden Altstadt von Bari an der Piazza Mercantile liegt das Ristorante La Locanda di Federico. Eine einfache, typische und rustikale Trattoria. Hier k\u00f6nnen die heimischen Gerichte Apuliens bestellt und probiert werden. Im La Locanda di Federico geht es ehrlich und klassisch zu. Kein Chichi, &#8230; <a title=\"Ristorante La Locanda di Federico &#8211; Bari &#8211; Italien\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/\" aria-label=\"Mehr dazu unter Ristorante La Locanda di Federico &#8211; Bari &#8211; Italien\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":164620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[34,13],"tags":[191,1958,73,1959],"post_folder":[],"class_list":["post-55239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italien-restaurants","category-restaurants","tag-apulien","tag-bari","tag-restaurant","tag-ristorante-la-locanda-di-federico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ristorante La Locanda di Federico - Bari - Italien - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"description\" content=\"Das Ristorante La Locanda di Federico in Bari ist ein typisches und ehrliches Lokal am Rande der Altstadt von Bari.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ristorante La Locanda di Federico - Bari - Italien - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Das Ristorante La Locanda di Federico in Bari ist ein typisches und ehrliches Lokal am Rande der Altstadt von Bari.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-01T10:00:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-20T09:26:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Ristorante La Locanda di Federico &#8211; Bari &#8211; Italien\",\"datePublished\":\"2019-02-01T10:00:25+00:00\",\"dateModified\":\"2023-03-20T09:26:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/\"},\"wordCount\":144,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Ristorante_La_Locanda_di_Federico_Bari_Italien_7.jpg\",\"keywords\":[\"Apulien\",\"Bari\",\"Restaurant\",\"Ristorante La Locanda di Federico\"],\"articleSection\":[\"Italien\",\"Restaurants\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/\",\"name\":\"Ristorante La Locanda di Federico - Bari - Italien - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Ristorante_La_Locanda_di_Federico_Bari_Italien_7.jpg\",\"datePublished\":\"2019-02-01T10:00:25+00:00\",\"dateModified\":\"2023-03-20T09:26:58+00:00\",\"description\":\"Das Ristorante La Locanda di Federico in Bari ist ein typisches und ehrliches Lokal am Rande der Altstadt von Bari.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Ristorante_La_Locanda_di_Federico_Bari_Italien_7.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Ristorante_La_Locanda_di_Federico_Bari_Italien_7.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/02\\\/ristorante-la-locanda-di-federico-typisch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ristorante La Locanda di Federico &#8211; Bari &#8211; Italien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ristorante La Locanda di Federico - Bari - Italien - Unterwegs mit Weine &amp; Feinkost","description":"Das Ristorante La Locanda di Federico in Bari ist ein typisches und ehrliches Lokal am Rande der Altstadt von Bari.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/","og_locale":"de_DE","og_type":"article","og_title":"Ristorante La Locanda di Federico - Bari - Italien - Unterwegs mit Weine &amp; Feinkost","og_description":"Das Ristorante La Locanda di Federico in Bari ist ein typisches und ehrliches Lokal am Rande der Altstadt von Bari.","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2019-02-01T10:00:25+00:00","article_modified_time":"2023-03-20T09:26:58+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_7.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Ristorante La Locanda di Federico &#8211; Bari &#8211; Italien","datePublished":"2019-02-01T10:00:25+00:00","dateModified":"2023-03-20T09:26:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/"},"wordCount":144,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_7.jpg","keywords":["Apulien","Bari","Restaurant","Ristorante La Locanda di Federico"],"articleSection":["Italien","Restaurants"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/","name":"Ristorante La Locanda di Federico - Bari - Italien - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_7.jpg","datePublished":"2019-02-01T10:00:25+00:00","dateModified":"2023-03-20T09:26:58+00:00","description":"Das Ristorante La Locanda di Federico in Bari ist ein typisches und ehrliches Lokal am Rande der Altstadt von Bari.","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_7.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_7.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/02\/ristorante-la-locanda-di-federico-typisch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Ristorante La Locanda di Federico &#8211; Bari &#8211; Italien"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/01\/Ristorante_La_Locanda_di_Federico_Bari_Italien_7.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-emX","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/55239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=55239"}],"version-history":[{"count":2,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/55239\/revisions"}],"predecessor-version":[{"id":196929,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/55239\/revisions\/196929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/164620"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=55239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=55239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=55239"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=55239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}