{"id":67207,"date":"2019-07-05T11:00:12","date_gmt":"2019-07-05T09:00:12","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=67207"},"modified":"2023-03-20T06:34:17","modified_gmt":"2023-03-20T05:34:17","slug":"le-clos-des-sens-bedeutungsvoll","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/","title":{"rendered":"Le Clos des Sens &#8211; Annecy-le-Vieux &#8211; Frankreich"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Le Clos des Sens &#8211; Bedeutungsvoll<\/h3>\n\n\n\n<p class=\"has-drop-cap\">Seit 26 Jahren verw\u00f6hnen der Koch Laurent Petit und sein Team die G\u00e4ste im Restaurant Clos des Sens in der wunderh\u00fcbschen Ortschaft Annecy am gleichnamigen See in den franz\u00f6sischen Savoyen. Dem urigen Restaurant sind noch ein paar Hotelzimmer angeschlossen. Je nach Sitzplatz kann der Gast in dem mit dunklem Holz verkleideten Raum direkt in die offene K\u00fcche oder auf den Lac de Annecy schauen. Herzlich warm wie das Interieur mutet hier auch der unaufgeregte und professionelle Service an.  <\/p>\n\n\n\n<p>Nach ein paar leckersten Gr\u00fc\u00dfen aus der K\u00fcche hat der Gast hier die Qual der Wahl zwischen einem \u00dcberraschungsmen\u00fcs, welches aus f\u00fcnf, sieben oder zehn G\u00e4ngen besteht. Vor ein paar Jahren wurde hier den goldenen Zutaten der Hochk\u00fcche wie G\u00e4nseleber, Hummer, Taube und Co. Adieu gesagt und ein sinnvolles regionales Konzept geboren.  <\/p>\n\n\n\n<p>Die verarbeiteten Zutaten kommen nun aus einem Umkreis von h\u00f6chstens 100 Kilometern und stammen von kleinen Produzenten, die auch auf der Speisekarte aufgef\u00fchrt werden. Auf Fleisch wird komplett verzichtet und auch bei Fischspeisen gibt es nur S\u00fc\u00dfwasserfische auf den Teller, die auch aus einem der drei im Umkreis liegenden Seen geangelt wurden. Ein eigener Garten sorgt zudem f\u00fcr Gem\u00fcse, Salat und frische Gew\u00fcrze auf den Tellern. Die Produkte sind in allen Belangen die offensichtlichen Stars im Le Clos des Sens, und Laurent Petit schafft es auf wundersame Weise, sehr komplexe und im Geschmack lang anhaltende Gerichte in unterschiedlichen Texturen zu erschaffen. Kein Gang wirkt konstruiert oder gar \u00fcberzeichnet. Die Geschmacksexplosionen werden aus dem Reich der Natur geschaffen und hier und da nur ein wenig mit mehr oder weniger Butter getunt.  <\/p>\n\n\n\n<p>Die sehr lockere und nat\u00fcrliche Atmosph\u00e4re sorgt f\u00fcr den richtigen Wohlf\u00fchlfaktor vor Ort. Ein magischer Ort, wo der Koch Laurent Petit eine kunstvolle, eigene Handschrift entwickelt hat. Bauch, Herz und Seele, was willst Du mehr?<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_0.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_0.jpg\" alt=\"\" class=\"wp-image-67212\"\/><\/a><figcaption class=\"wp-element-caption\"> <\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_1.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_1.jpg\" alt=\"\" class=\"wp-image-67213\"\/><\/a><figcaption class=\"wp-element-caption\">Piniennadel Wasser, um den Gaumen vor der gro\u00dfen Show zu reinigen.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_01.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_01.jpg\" alt=\"\" class=\"wp-image-67214\"\/><\/a><figcaption class=\"wp-element-caption\">Fisch Chip und Knoblauch.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_2.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_2.jpg\" alt=\"\" class=\"wp-image-67215\"\/><\/a><figcaption class=\"wp-element-caption\">Pilze in verschiedenen Texturen. Champignon &#8211; Pilzcreme &#8211; Pilzsalz\/Cracker.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_02.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_02.jpg\" alt=\"\" class=\"wp-image-67216\"\/><\/a><figcaption class=\"wp-element-caption\">Fischcreme Tartelette.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_3.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_3.jpg\" alt=\"\" class=\"wp-image-67217\"\/><\/a><figcaption class=\"wp-element-caption\">Aromensalat aus dem Garten mit Knoblauch und Senf. <\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_4.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_4.jpg\" alt=\"\" class=\"wp-image-67218\"\/><\/a><figcaption class=\"wp-element-caption\">Seekrabben aus dem Lac d\u00b4Annecy.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_5.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_5.jpg\" alt=\"\" class=\"wp-image-67219\"\/><\/a><figcaption class=\"wp-element-caption\">Bestes Sauerteigbrot.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_6.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_6.jpg\" alt=\"\" class=\"wp-image-67220\"\/><\/a><figcaption class=\"wp-element-caption\">Seekrabben Carpaccio und Senf aus dem eigenen Garten.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_7.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_7.jpg\" alt=\"\" class=\"wp-image-67221\"\/><\/a><figcaption class=\"wp-element-caption\">  Das pers\u00f6nliche Highlight des Men\u00fcs. Wilde Champignons in verschiedenen Texturen. Roh geschnitten auf einer Waldpilzcreme, karamellisierten Zwiebeln und einem Pilz Cappuccino. So schmeckt der Wald in seiner puren und ehrlichsten Form. Ein absolutes Genusshighlight.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_8.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_8.jpg\" alt=\"\" class=\"wp-image-67222\"\/><\/a><figcaption class=\"wp-element-caption\">&#8230; der Pilze Cappuccino.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_9.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_9.jpg\" alt=\"\" class=\"wp-image-67223\"\/><\/a><figcaption class=\"wp-element-caption\">  Der zweite H\u00f6hepunkt: marinierte Spargelstreifen, Spargelp\u00fcree und Spargels\u00fcppchen. Drei verschiedene Texturen eines Top Produktes, welches jeweils unterschiedlich zubereitet wurde, knallen am Gaumen zusammen und f\u00fchren dort zu einer fulminanten Eruption. Ein gelungener Festakt der Natur. <\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_10.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_10.jpg\" alt=\"\" class=\"wp-image-67224\"\/><\/a><figcaption class=\"wp-element-caption\"> <\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_11.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_11.jpg\" alt=\"\" class=\"wp-image-67225\"\/><\/a><figcaption class=\"wp-element-caption\"> Ger\u00e4uchertes Felchenfilet auf  gegrilltem Kohl. <\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_12.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_12.jpg\" alt=\"\" class=\"wp-image-67226\"\/><\/a><figcaption class=\"wp-element-caption\">Forelle, Schnecken auf einer Chignin-Bergeron Weinsauce.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_14.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_14.jpg\" alt=\"\" class=\"wp-image-67228\"\/><\/a><figcaption class=\"wp-element-caption\">Allerfeinste K\u00e4seselektion aus den Savoyen.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_15.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_15.jpg\" alt=\"\" class=\"wp-image-67229\"\/><\/a><figcaption class=\"wp-element-caption\">Frischer Salat zur K\u00e4seauswahl.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_16.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_16.jpg\" alt=\"\" class=\"wp-image-67230\"\/><\/a><figcaption class=\"wp-element-caption\">  Buttermilcheis vom Reblochon K\u00e4se mit Hagebutte Variationen.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_17.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_17.jpg\" alt=\"\" class=\"wp-image-67231\"\/><\/a><figcaption class=\"wp-element-caption\">Chicor\u00e9e Variationen in verschiedenen Texturen.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_18.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_18.jpg\" alt=\"\" class=\"wp-image-67232\"\/><\/a><figcaption class=\"wp-element-caption\">Madeleines.<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_20.jpg\"><img decoding=\"async\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_20.jpg\" alt=\"\" class=\"wp-image-67233\"\/><\/a><figcaption class=\"wp-element-caption\"> <\/figcaption><\/figure>\n<\/div>\n\n\n<p><strong>Le Clos Des Sens<\/strong> &#8211; 13 Rue Jean Mermoz &#8211;  74940 Annecy-le-Vieux &#8211; Frankreich &#8211; Telefon: +33 4 50 23 07 90 &#8211; <a href=\"https:\/\/www.closdessens.com\/\">www.closdessens.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Clos des Sens &#8211; Bedeutungsvoll Seit 26 Jahren verw\u00f6hnen der Koch Laurent Petit und sein Team die G\u00e4ste im Restaurant Clos des Sens in der wunderh\u00fcbschen Ortschaft Annecy am gleichnamigen See in den franz\u00f6sischen Savoyen. Dem urigen Restaurant sind noch ein paar Hotelzimmer angeschlossen. Je nach Sitzplatz kann der Gast in dem mit dunklem &#8230; <a title=\"Le Clos des Sens &#8211; Annecy-le-Vieux &#8211; Frankreich\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/\" aria-label=\"Mehr dazu unter Le Clos des Sens &#8211; Annecy-le-Vieux &#8211; Frankreich\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":142773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3326,41,13],"tags":[2227,141,2228,2229,73],"post_folder":[],"class_list":["post-67207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frankreich-restaurants","category-michelin-star","category-restaurants","tag-annecy-le-vieux","tag-frankreich","tag-laurent-petit","tag-le-clos-des-sens","tag-restaurant"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Clos des Sens - Annecy-le-Vieux - Frankreich - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Clos des Sens - Annecy-le-Vieux - Frankreich - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Le Clos des Sens &#8211; Bedeutungsvoll Seit 26 Jahren verw\u00f6hnen der Koch Laurent Petit und sein Team die G\u00e4ste im Restaurant Clos des Sens in der wunderh\u00fcbschen Ortschaft Annecy am gleichnamigen See in den franz\u00f6sischen Savoyen. Dem urigen Restaurant sind noch ein paar Hotelzimmer angeschlossen. Je nach Sitzplatz kann der Gast in dem mit dunklem ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-05T09:00:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-20T05:34:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Le Clos des Sens &#8211; Annecy-le-Vieux &#8211; Frankreich\",\"datePublished\":\"2019-07-05T09:00:12+00:00\",\"dateModified\":\"2023-03-20T05:34:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/\"},\"wordCount\":515,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_13.jpg\",\"keywords\":[\"Annecy-le-Vieux\",\"Frankreich\",\"Laurent Petit\",\"Le Clos des Sens\",\"Restaurant\"],\"articleSection\":[\"Frankreich\",\"Michelin Star\",\"Restaurants\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/\",\"name\":\"Le Clos des Sens - Annecy-le-Vieux - Frankreich - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_13.jpg\",\"datePublished\":\"2019-07-05T09:00:12+00:00\",\"dateModified\":\"2023-03-20T05:34:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_13.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_13.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/07\\\/le-clos-des-sens-bedeutungsvoll\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Clos des Sens &#8211; Annecy-le-Vieux &#8211; Frankreich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Clos des Sens - Annecy-le-Vieux - Frankreich - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/","og_locale":"de_DE","og_type":"article","og_title":"Le Clos des Sens - Annecy-le-Vieux - Frankreich - Unterwegs mit Weine &amp; Feinkost","og_description":"Le Clos des Sens &#8211; Bedeutungsvoll Seit 26 Jahren verw\u00f6hnen der Koch Laurent Petit und sein Team die G\u00e4ste im Restaurant Clos des Sens in der wunderh\u00fcbschen Ortschaft Annecy am gleichnamigen See in den franz\u00f6sischen Savoyen. Dem urigen Restaurant sind noch ein paar Hotelzimmer angeschlossen. Je nach Sitzplatz kann der Gast in dem mit dunklem ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2019-07-05T09:00:12+00:00","article_modified_time":"2023-03-20T05:34:17+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_13.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Le Clos des Sens &#8211; Annecy-le-Vieux &#8211; Frankreich","datePublished":"2019-07-05T09:00:12+00:00","dateModified":"2023-03-20T05:34:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/"},"wordCount":515,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_13.jpg","keywords":["Annecy-le-Vieux","Frankreich","Laurent Petit","Le Clos des Sens","Restaurant"],"articleSection":["Frankreich","Michelin Star","Restaurants"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/","name":"Le Clos des Sens - Annecy-le-Vieux - Frankreich - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_13.jpg","datePublished":"2019-07-05T09:00:12+00:00","dateModified":"2023-03-20T05:34:17+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_13.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_13.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/07\/le-clos-des-sens-bedeutungsvoll\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Le Clos des Sens &#8211; Annecy-le-Vieux &#8211; Frankreich"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/05\/Le_Clos_des_Sens_Annecy-le-Vieux_Frankreich_13.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-htZ","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/67207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=67207"}],"version-history":[{"count":2,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/67207\/revisions"}],"predecessor-version":[{"id":196783,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/67207\/revisions\/196783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/142773"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=67207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=67207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=67207"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=67207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}