{"id":69585,"date":"2019-06-28T11:00:40","date_gmt":"2019-06-28T09:00:40","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=69585"},"modified":"2019-06-28T11:00:40","modified_gmt":"2019-06-28T09:00:40","slug":"langer-tisch-2019-wuppertal-feiert-wir-feiern-mit","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/","title":{"rendered":"Langer Tisch 2019 &#8211; Wuppertal feiert, wir feiern mit!"},"content":{"rendered":"\n<p>Liebe Weinfreunde,<\/p>\n\n\n\n<p>auch wir freuen uns riesig, beim Langen Tisch zum 90- j\u00e4hrigen Stadtgeburtstag Wuppertals dabei zu sein. Unseren Stand haben wir zusammen mit dem Kulturzentrum \u201eDie B\u00f6rse\u201c an der Ecke Friedrich-Engels-Allee\/Pauluskirchstra\u00dfe (siehe Lageplan anbei). Wir werden mit guter Laune ein paar frisch gek\u00fchlte Tropfen bereit halten! An alle, die Spa\u00df und Lust haben vorbeizuschauen &#8230; wir freuen uns auf ein tolles Fest!<\/p>\n\n\n\n<p>Ihr<\/p>\n\n\n\n<p>Christian Fenske und Team<\/p>\n\n\n\n<p>?<strong> Wann:<\/strong> 29.06.2019 ab 17\u00b0\u00b0 Uhr<\/p>\n\n\n\n<p><strong>Wo: <\/strong>?<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"884\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/06\/Lageplan_Langer_Tisch_2019_Abschnitt_I07-I09_bearbeitet-1.jpg\" alt=\"\" class=\"wp-image-146131\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/06\/Lageplan_Langer_Tisch_2019_Abschnitt_I07-I09_bearbeitet-1.jpg 1280w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/06\/Lageplan_Langer_Tisch_2019_Abschnitt_I07-I09_bearbeitet-1-300x207.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/06\/Lageplan_Langer_Tisch_2019_Abschnitt_I07-I09_bearbeitet-1-1200x829.jpg 1200w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/06\/Lageplan_Langer_Tisch_2019_Abschnitt_I07-I09_bearbeitet-1-768x530.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Weinfreunde, auch wir freuen uns riesig, beim Langen Tisch zum 90- j\u00e4hrigen Stadtgeburtstag Wuppertals dabei zu sein. Unseren Stand haben wir zusammen mit dem Kulturzentrum \u201eDie B\u00f6rse\u201c an der Ecke Friedrich-Engels-Allee\/Pauluskirchstra\u00dfe (siehe Lageplan anbei). Wir werden mit guter Laune ein paar frisch gek\u00fchlte Tropfen bereit halten! An alle, die Spa\u00df und Lust haben vorbeizuschauen &#8230; <a title=\"Langer Tisch 2019 &#8211; Wuppertal feiert, wir feiern mit!\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/\" aria-label=\"Mehr dazu unter Langer Tisch 2019 &#8211; Wuppertal feiert, wir feiern mit!\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":166080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[63],"tags":[2217,2218,138],"post_folder":[],"class_list":["post-69585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-2217","tag-langer-tisch","tag-wuppertal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Langer Tisch 2019 - Wuppertal feiert, wir feiern mit! - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Langer Tisch 2019 - Wuppertal feiert, wir feiern mit! - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Liebe Weinfreunde, auch wir freuen uns riesig, beim Langen Tisch zum 90- j\u00e4hrigen Stadtgeburtstag Wuppertals dabei zu sein. Unseren Stand haben wir zusammen mit dem Kulturzentrum \u201eDie B\u00f6rse\u201c an der Ecke Friedrich-Engels-Allee\/Pauluskirchstra\u00dfe (siehe Lageplan anbei). Wir werden mit guter Laune ein paar frisch gek\u00fchlte Tropfen bereit halten! An alle, die Spa\u00df und Lust haben vorbeizuschauen ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-28T09:00:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/06\/langer_tisch_wuppertal_2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"576\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Langer Tisch 2019 &#8211; Wuppertal feiert, wir feiern mit!\",\"datePublished\":\"2019-06-28T09:00:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/\"},\"wordCount\":84,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/langer_tisch_wuppertal_2019.jpg\",\"keywords\":[\"2019\",\"Langer Tisch\",\"Wuppertal\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/\",\"name\":\"Langer Tisch 2019 - Wuppertal feiert, wir feiern mit! - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/langer_tisch_wuppertal_2019.jpg\",\"datePublished\":\"2019-06-28T09:00:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/langer_tisch_wuppertal_2019.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/langer_tisch_wuppertal_2019.jpg\",\"width\":576,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/06\\\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Langer Tisch 2019 &#8211; Wuppertal feiert, wir feiern mit!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Langer Tisch 2019 - Wuppertal feiert, wir feiern mit! - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/","og_locale":"de_DE","og_type":"article","og_title":"Langer Tisch 2019 - Wuppertal feiert, wir feiern mit! - Unterwegs mit Weine &amp; Feinkost","og_description":"Liebe Weinfreunde, auch wir freuen uns riesig, beim Langen Tisch zum 90- j\u00e4hrigen Stadtgeburtstag Wuppertals dabei zu sein. Unseren Stand haben wir zusammen mit dem Kulturzentrum \u201eDie B\u00f6rse\u201c an der Ecke Friedrich-Engels-Allee\/Pauluskirchstra\u00dfe (siehe Lageplan anbei). Wir werden mit guter Laune ein paar frisch gek\u00fchlte Tropfen bereit halten! An alle, die Spa\u00df und Lust haben vorbeizuschauen ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2019-06-28T09:00:40+00:00","og_image":[{"width":576,"height":768,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/06\/langer_tisch_wuppertal_2019.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Langer Tisch 2019 &#8211; Wuppertal feiert, wir feiern mit!","datePublished":"2019-06-28T09:00:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/"},"wordCount":84,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/06\/langer_tisch_wuppertal_2019.jpg","keywords":["2019","Langer Tisch","Wuppertal"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/","name":"Langer Tisch 2019 - Wuppertal feiert, wir feiern mit! - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/06\/langer_tisch_wuppertal_2019.jpg","datePublished":"2019-06-28T09:00:40+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/06\/langer_tisch_wuppertal_2019.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/06\/langer_tisch_wuppertal_2019.jpg","width":576,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/06\/langer-tisch-2019-wuppertal-feiert-wir-feiern-mit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Langer Tisch 2019 &#8211; Wuppertal feiert, wir feiern mit!"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/06\/langer_tisch_wuppertal_2019.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-i6l","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/69585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=69585"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/69585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/166080"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=69585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=69585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=69585"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=69585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}