{"id":73320,"date":"2019-10-06T11:00:23","date_gmt":"2019-10-06T09:00:23","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=73320"},"modified":"2023-03-21T15:25:08","modified_gmt":"2023-03-21T14:25:08","slug":"dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/","title":{"rendered":"Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 &#8211; Noblesse oblige"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Dr. B\u00fcrklin-Wolf Riesling Ruppertsberger Gaisb\u00f6hl GC Monopol &#8211; Pfalz &#8211; Deutschland<\/h3>\n\n\n\n<p>Die Einzellage Ruppertsberger Gaisb\u00f6hl gilt mit ihren gut acht Hektar Buntsandsteinger\u00f6ll B\u00f6den als der beste Riesling Wingert in ganz Ruppertsberg. Das Weingut Dr. B\u00fcrklin-Wolf darf als Alleineigent\u00fcmer und Bewirtschafter mit Fug und Recht sehr stolz auf dieses au\u00dfergew\u00f6hnliche St\u00fcck Land sein. Der k\u00fcrzlich probierte und mit unglaublicher Freude auch ziemlich schnell ausgetrunkene 2015er Jahrgang pr\u00e4sentierte sich schon erstaunlich reif und hatte einen perfekten Trinkfluss.  <\/p>\n\n\n\n<p>Die Reife bezieht sich hier allerdings nicht auf irgendwelche Alterungst\u00f6ne des Weines, sondern kennzeichnete den puren Reifegrad der im Wein erkennbaren Fruchtnoten. Pfirsich und Aprikosen waren hier die vorherrschenden Merkmale. Leicht w\u00fcrzige und warme Erdt\u00f6ne legten sich dann wie ein fluffiger Seidenschal um diese Kernfr\u00fcchte, um das Geschmacksbild und die Intensit\u00e4t immer weiter zu verst\u00e4rken. Geschmacklich wirkte der Wein dann wie eine perfekt ausgebackene zarte Waffel, plus etwas Puderzucker und jede Menge reifer, eingekochter Jonagold \u00c4pfel. Dezent, aber auch sehr pr\u00e4sent dann die im Mund aufmarschierende S\u00e4urestruktur. Diese gab dem Gaisb\u00f6hl noch den n\u00f6tigen Druck und exemplarische Frische am Z\u00e4pfchen. (Wein)Adel verpflichtet! \u2026 und bei dieser Flasche kann man sich auf das Weingut Dr. B\u00fcrklin-Wolf einfach uneingeschr\u00e4nkt verlassen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dr. B\u00fcrklin-Wolf Riesling Ruppertsberger Gaisb\u00f6hl GC Monopol &#8211; Pfalz &#8211; Deutschland Die Einzellage Ruppertsberger Gaisb\u00f6hl gilt mit ihren gut acht Hektar Buntsandsteinger\u00f6ll B\u00f6den als der beste Riesling Wingert in ganz Ruppertsberg. Das Weingut Dr. B\u00fcrklin-Wolf darf als Alleineigent\u00fcmer und Bewirtschafter mit Fug und Recht sehr stolz auf dieses au\u00dfergew\u00f6hnliche St\u00fcck Land sein. Der k\u00fcrzlich probierte &#8230; <a title=\"Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 &#8211; Noblesse oblige\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/\" aria-label=\"Mehr dazu unter Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 &#8211; Noblesse oblige\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":166544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[19,18],"tags":[529,120,991,992,2324,123,290],"post_folder":[],"class_list":["post-73320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-weine","tag-529","tag-deutschland","tag-dr-buerklin-wolf","tag-gaisboehl","tag-monopol","tag-pfalz","tag-riesling"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 - Noblesse oblige - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 - Noblesse oblige - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Dr. B\u00fcrklin-Wolf Riesling Ruppertsberger Gaisb\u00f6hl GC Monopol &#8211; Pfalz &#8211; Deutschland Die Einzellage Ruppertsberger Gaisb\u00f6hl gilt mit ihren gut acht Hektar Buntsandsteinger\u00f6ll B\u00f6den als der beste Riesling Wingert in ganz Ruppertsberg. Das Weingut Dr. B\u00fcrklin-Wolf darf als Alleineigent\u00fcmer und Bewirtschafter mit Fug und Recht sehr stolz auf dieses au\u00dfergew\u00f6hnliche St\u00fcck Land sein. Der k\u00fcrzlich probierte ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-06T09:00:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T14:25:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/08\/Dr_Buerklin_Wolf_Riesling_Ruppertsberger_Gaisboehl_GC_Monopol_Pfalz_Deutschland.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 &#8211; Noblesse oblige\",\"datePublished\":\"2019-10-06T09:00:23+00:00\",\"dateModified\":\"2023-03-21T14:25:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/\"},\"wordCount\":226,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Dr_Buerklin_Wolf_Riesling_Ruppertsberger_Gaisboehl_GC_Monopol_Pfalz_Deutschland.jpg\",\"keywords\":[\"2015\",\"Deutschland\",\"Dr. B\u00fcrklin Wolf\",\"Gaisb\u00f6hl\",\"Monopol\",\"Pfalz\",\"Riesling\"],\"articleSection\":[\"Deutschland\",\"Weine\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/\",\"name\":\"Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 - Noblesse oblige - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Dr_Buerklin_Wolf_Riesling_Ruppertsberger_Gaisboehl_GC_Monopol_Pfalz_Deutschland.jpg\",\"datePublished\":\"2019-10-06T09:00:23+00:00\",\"dateModified\":\"2023-03-21T14:25:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Dr_Buerklin_Wolf_Riesling_Ruppertsberger_Gaisboehl_GC_Monopol_Pfalz_Deutschland.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Dr_Buerklin_Wolf_Riesling_Ruppertsberger_Gaisboehl_GC_Monopol_Pfalz_Deutschland.jpg\",\"width\":480,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2019\\\/10\\\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 &#8211; Noblesse oblige\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 - Noblesse oblige - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/","og_locale":"de_DE","og_type":"article","og_title":"Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 - Noblesse oblige - Unterwegs mit Weine &amp; Feinkost","og_description":"Dr. B\u00fcrklin-Wolf Riesling Ruppertsberger Gaisb\u00f6hl GC Monopol &#8211; Pfalz &#8211; Deutschland Die Einzellage Ruppertsberger Gaisb\u00f6hl gilt mit ihren gut acht Hektar Buntsandsteinger\u00f6ll B\u00f6den als der beste Riesling Wingert in ganz Ruppertsberg. Das Weingut Dr. B\u00fcrklin-Wolf darf als Alleineigent\u00fcmer und Bewirtschafter mit Fug und Recht sehr stolz auf dieses au\u00dfergew\u00f6hnliche St\u00fcck Land sein. Der k\u00fcrzlich probierte ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2019-10-06T09:00:23+00:00","article_modified_time":"2023-03-21T14:25:08+00:00","og_image":[{"width":480,"height":640,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/08\/Dr_Buerklin_Wolf_Riesling_Ruppertsberger_Gaisboehl_GC_Monopol_Pfalz_Deutschland.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 &#8211; Noblesse oblige","datePublished":"2019-10-06T09:00:23+00:00","dateModified":"2023-03-21T14:25:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/"},"wordCount":226,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/08\/Dr_Buerklin_Wolf_Riesling_Ruppertsberger_Gaisboehl_GC_Monopol_Pfalz_Deutschland.jpg","keywords":["2015","Deutschland","Dr. B\u00fcrklin Wolf","Gaisb\u00f6hl","Monopol","Pfalz","Riesling"],"articleSection":["Deutschland","Weine"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/","name":"Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 - Noblesse oblige - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/08\/Dr_Buerklin_Wolf_Riesling_Ruppertsberger_Gaisboehl_GC_Monopol_Pfalz_Deutschland.jpg","datePublished":"2019-10-06T09:00:23+00:00","dateModified":"2023-03-21T14:25:08+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/08\/Dr_Buerklin_Wolf_Riesling_Ruppertsberger_Gaisboehl_GC_Monopol_Pfalz_Deutschland.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/08\/Dr_Buerklin_Wolf_Riesling_Ruppertsberger_Gaisboehl_GC_Monopol_Pfalz_Deutschland.jpg","width":480,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2019\/10\/dr-buerklin-wolf-gaisboehl-2015-noblesse-oblige\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Dr. B\u00fcrklin-Wolf Gaisb\u00f6hl 2015 &#8211; Noblesse oblige"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2019\/08\/Dr_Buerklin_Wolf_Riesling_Ruppertsberger_Gaisboehl_GC_Monopol_Pfalz_Deutschland.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-j4A","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/73320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=73320"}],"version-history":[{"count":1,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/73320\/revisions"}],"predecessor-version":[{"id":197093,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/73320\/revisions\/197093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/166544"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=73320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=73320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=73320"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=73320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}