{"id":88152,"date":"2020-02-29T11:00:00","date_gmt":"2020-02-29T10:00:00","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=88152"},"modified":"2020-02-29T11:00:00","modified_gmt":"2020-02-29T10:00:00","slug":"garnacha-im-bogen-des-ebro","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/","title":{"rendered":"Garnacha im Bogen des Ebro"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Garnacha im Bogen des Ebro<\/h3>\n\n\n\n<p>Der bislang letzte spanische B\u00fcrgerkrieg war eigentlich schon entschieden, in Mittelkatalonien war eine breite Bresche geschlagen, frei f\u00fcr den Vormarsch der Franquisten (unter Unterst\u00fctzung von Hitler-Deutschland und Mussolini-Italien) gen Barcelona zu marschieren. Doch da gibt es eine kleine Delle des Ebro, nahe des Ortes Mora d&#8217;Ebre, in der sich Republikaner gehalten hatten. Sie wollte Franco ausl\u00f6schen, zumindest aber vertreiben. Es begann ein Gemetzel, das als das wohl grausamste des B\u00fcrgerkrieges in die Geschichte eingehen sollte.<\/p>\n\n\n\n<p>In der armen, rein landwirtschaftlich aufgestellten Region Terra Alta besetzte man einen H\u00fcgel im Norden von Corbera d&#8217;Ebre, Cota 402 (die absolute H\u00f6he \u00fcber Meeresniveau). Von dort aus kann man die wellige Landschaft gen Gandesa einsehen, das Unheil nahm seinen Lauf, tausende Menschen beider Seiten starben in einem unn\u00fctzen Gefecht, das noch viel unn\u00fctzer war als es kriegerische Handlungen ohnehin sind. Besucht man Celler Frisach, gelegen mitten in Corbera d&#8217;Ebre, dann ist ein Besuch dieser Stelle Teil des Programms, niemand soll glauben, dass die heute so ruhig daherkommende Region auch schon immer ruhig war.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/02\/Garnacha_im_Bogen_des_Ebro_03498.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/02\/Garnacha_im_Bogen_des_Ebro_03498.jpg\" alt=\"\" class=\"wp-image-167695\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/02\/Garnacha_im_Bogen_des_Ebro_03498.jpg 800w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/02\/Garnacha_im_Bogen_des_Ebro_03498-300x200.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/02\/Garnacha_im_Bogen_des_Ebro_03498-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption>Corbera d&#8217;Ebre.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Weinbau spielte in dieser Region damals eine durchaus bedeutende Rolle, schon Ende des neunzehnten Jahrhundert wurden Genossenschaften gegr\u00fcndet, deren Geb\u00e4ude eher Kathedralen denn Weinproduktionsst\u00e4tten gleichkommen. Derer zwei, die Genossenschaften in Gandesa und in El Pinell de Brai, werden nicht zu Unrecht als Catedral de V\u00ed bezeichnet, noch heute, mehr als einhundert zwanzig Jahre nach der Fertigstellung, haben sie nichts an ihrem Glanz verloren.<\/p>\n\n\n\n<p>Von dem Weinbau in Terra Alta kann man dies nicht unbedingt behaupten. Terra Alta ist die einzige Weinregion Kataloniens, die rechts des Ebro gelegen ist, noch hinter dem Priorat, auf der anderen Seite des Matarra\u00f1a, der Grenzbach gen Arag\u00f3n, ist erst einmal nichts. Dann nicht viel, irgendwann trifft man in Alca\u00f1iz ein. Mit anderen Worten: ein nat\u00fcrliches Absatzgebiet gibt es eigentlich nicht. In der Bl\u00fctezeit der Region, Anfang des zwanzigsten Jahrhunderts, lebten in den zw\u00f6lf Orten gerade einmal zweiundzwanzig tausend Menschen, heute ist es gerade einmal die H\u00e4lfte.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/02\/Garnacha_im_Bogen_des_Ebro_03508.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/02\/Garnacha_im_Bogen_des_Ebro_03508.jpg\" alt=\"\" class=\"wp-image-167696\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/02\/Garnacha_im_Bogen_des_Ebro_03508.jpg 800w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/02\/Garnacha_im_Bogen_des_Ebro_03508-300x200.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/02\/Garnacha_im_Bogen_des_Ebro_03508-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption>Hangparzellen in Terra Alta.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Garnacha Blanca war und ist die wichtigste Rebsorte der Region, in keiner anderen Ecke Kataloniens wird mehr davon angebaut. Aber auch diese Sorte hat es schwer in den trockenen \u00c4ckern, vor allem dort, wo die Krume aus Lehm besteht, fettem Lehm, wie etwa in Batea. Dort gibt es inzwischen viele Rebanlagen, Garnacha h\u00e4lt wohl noch immer die Mehrheit, aber die internationalen Sorten nehmen zu. Seitdem dort die Parzellen generell bew\u00e4ssert werden k\u00f6nnen, keltert man dort massenhaft massentaugliche Massenweine, die man auch ungekeltert sein lassen k\u00f6nnte. Oder aber man arbeitet mit einer in El Pacs del Pened\u00e8s ans\u00e4ssigen Firma, die sich Torres nennt.<\/p>\n\n\n\n<p>Torres war der Lebensretter der Region (und aus von Montsant), sagen die einen, w\u00e4hrend andere beklagen, dass Torres der Totengr\u00e4ber beider Regionen sei. Beide Ansichten haben etwas f\u00fcr sich. Denn Miguel A. Torres half den Weinbauern der Region, zu \u00fcberleben. In den achtziger und neunziger Jahren des letzten Jahrhundert begann die Pened\u00e8s-Gro\u00dfkellerei, Trauben aus Terra Alta zu kaufen, tief dunkel und papps\u00fc\u00df: Merlot. An Garnacha Blanca ist Torres bis heute nicht interessiert. Und gerade Batea und der ebenfalls im Norden der Region gelegene Ort Vilalba dels Arcs bieten gute Voraussetzungen f\u00fcr Massenweinbau: relativ gro\u00dfe Parzellen, gut maschinentauglich, mit ertragreichen Klonen kann man da ein Business aufbauen.<\/p>\n\n\n\n<p>Dies machten einige Bodegas, Ende des letzten Jahrhunderts war die Region vor allem f\u00fcr Weine aus internationalen Sorten bekannt, Bodegas wie Celler Pujol oder B\u00e0rbara For\u00e9s, damals die Zugpferde der Region, setzten vor allem auf Syrah und Cabernet, auf Merlot und anderes Zeuch, sie kelterten zwar auch Weine aus Garnacha blanca, man schmeckte ihnen aber schnell an, dass die Kenntnisse von gutem Wei\u00dfweinausbau noch nicht \u00fcber den Ebro gesprungen waren. Viel Barrique hilft viel, dies war damals die Losung.<\/p>\n\n\n\n<p>Als die D.O. Catalunya ins Leben gerufen wurde, kamen viele Bodegas aus Zentralkatalonien, um in Terra Alta Wein zu keltern. Das Ergebnis indes verschwand in anonymen Weinen, die in den Superm\u00e4rkten dieser Welt f\u00fcr schmale M\u00fcnze angeboten wurden.<\/p>\n\n\n\n<p>Es kamen, wie so oft in Spanien, Gl\u00fccksritter, Weinmacher, die mal hier ein Fass aufmachten, mal dort einen Wein kelterten. Nur wenige blieben, Jordi Mir\u00f3 etwa, in Corbera, oder Jordi Vidal, in Batea. Beide geh\u00f6ren zu den besseren Produzenten der Region.<\/p>\n\n\n\n<p>Inzwischen ist auch der Consejo Regulador aus dem Tiefschlaf erwacht, man hat sich Garnacha 100&#215;100 auf die Fahne geschrieben, sortenreine Garnachas werden seitdem bevorzugt pr\u00e4sentiert. Das Ansinnen ist nett, es hat nur einen kleinen Haken: da die meisten Weing\u00fcter nicht wissen, wie man ordentliche wei\u00dfe Garnachas bastelt, kommen \u00fcppige Tropfen heraus. Aber da man nun einmal auf manchen Pr\u00e4sentationen nur pr\u00e4sent sein darf, wenn man einen 100&#215;100 auf den Tisch stellen kann, machen die Bodegas das halt.<\/p>\n\n\n\n<p>Langsam, ganz langsam beginnt die Region, in die Spur zu finden. Wie immer sind es kleine Bodegas, die den Wechsel einleiten. Celler Arrelats ist eines dieser Projekte: gelegen im Zentrum von Gandesa, in einer umgebauten Garage, begann man vor drei Jahren, etwa f\u00fcnftausend Flaschen Wein zu bereiten; viel gr\u00f6\u00dfer ist die Produktion bis heute nicht. Man verf\u00fcgt \u00fcber Rebland in Gandesa, nebst Corbera d&#8217;Ebre der interessanteste Ort f\u00fcr Weinbau in Terra Alta. Hier stehen die Rebst\u00f6cke auf Verwitterungskalksandstein, die Krume ist knapp, die Weine weisen etwas mehr S\u00e4ure auf, sind daf\u00fcr aber auch deutlich eleganter als die Wuchtbrummen aus Batea.<\/p>\n\n\n\n<p>Francesc Ferr\u00e9 Frisach ist aktuell der wohl beste Winzer der Region, gerade erst hat er die an der Hauptstra\u00dfe von Corbera d&#8217;Ebre gelegene Bodega, in der schon seit Generationen Wein gekeltert wird, modernisiert. Zweiundzwanzig Hektar Rebfl\u00e4che, derer zwanzig entfallen auf Garnacha, die H\u00e4lfte davon ist wei\u00df. Alle Wei\u00dfweine sind Lagenweine, auch jene, die als \u201eNaturweine\u201c daherkommen, will sagen, deren Most durchaus lange auf der Maische ruhte. H\u00f6henunterschiede, Erdkrumen und die genaue Zusammensetzung des Gesteins machen die Unterschiede. Sogar einen Ancestral-Lagen-Garnacha-Schaumwein gibt es, er reift bislang achtzig Monate in der Flasche. Das Ziel ist es, derer einhundert zu erreichen. Nat\u00fcrlich gibt es hier, wie auch in anderen Weing\u00fctern, auch rote Garnacha, sogar etwas Garnacha peluda, das ist die Variante mit den behaarten Bl\u00e4ttern, und ein klein wenig Garnacha gris, sonst eigentlich nur in l&#8217;Alt Empord\u00e0 anzutreffen.<\/p>\n\n\n\n<p>Mit dem, was die meisten anderen Bodegas so machen, hat das nicht sonderlich viel zu tun, mit dem, was man in der Region vor vielen Jahrzehnten machte, das, worauf der zumindest regional vorhandene Ruhm basiert, dann doch schon viel. Und dennoch: die Bodega gibt es in ihrer heutigen Form schon seit mehr als zehn Jahren. Au\u00dfer Arrelats hat sich bislang niemand auf den Weg gemacht, Frisach Konkurrenz zu bieten. Text: Text: el oso alem\u00e1n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Garnacha im Bogen des Ebro Der bislang letzte spanische B\u00fcrgerkrieg war eigentlich schon entschieden, in Mittelkatalonien war eine breite Bresche geschlagen, frei f\u00fcr den Vormarsch der Franquisten (unter Unterst\u00fctzung von Hitler-Deutschland und Mussolini-Italien) gen Barcelona zu marschieren. Doch da gibt es eine kleine Delle des Ebro, nahe des Ortes Mora d&#8217;Ebre, in der sich Republikaner &#8230; <a title=\"Garnacha im Bogen des Ebro\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/\" aria-label=\"Mehr dazu unter Garnacha im Bogen des Ebro\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":195903,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1004],"tags":[2514,1318,347,79,2515],"post_folder":[],"class_list":["post-88152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-oso-aleman-klartext","tag-francesc-ferre-frisach","tag-garnacha-blanca","tag-katalonien","tag-spanien","tag-terra-alta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Garnacha im Bogen des Ebro - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garnacha im Bogen des Ebro - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Garnacha im Bogen des Ebro Der bislang letzte spanische B\u00fcrgerkrieg war eigentlich schon entschieden, in Mittelkatalonien war eine breite Bresche geschlagen, frei f\u00fcr den Vormarsch der Franquisten (unter Unterst\u00fctzung von Hitler-Deutschland und Mussolini-Italien) gen Barcelona zu marschieren. Doch da gibt es eine kleine Delle des Ebro, nahe des Ortes Mora d&#8217;Ebre, in der sich Republikaner ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-29T10:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/02\/Garnacha_im_Bogen_des_Ebro_03498.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Garnacha im Bogen des Ebro\",\"datePublished\":\"2020-02-29T10:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/\"},\"wordCount\":1158,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/el_oso_aleman.jpg\",\"keywords\":[\"Francesc Ferr\u00e9 Frisach\",\"Garnacha Blanca\",\"Katalonien\",\"Spanien\",\"Terra Alta\"],\"articleSection\":[\"El oso alem\u00e1n\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/\",\"name\":\"Garnacha im Bogen des Ebro - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/el_oso_aleman.jpg\",\"datePublished\":\"2020-02-29T10:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/el_oso_aleman.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/el_oso_aleman.jpg\",\"width\":670,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/02\\\/garnacha-im-bogen-des-ebro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Garnacha im Bogen des Ebro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Garnacha im Bogen des Ebro - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/","og_locale":"de_DE","og_type":"article","og_title":"Garnacha im Bogen des Ebro - Unterwegs mit Weine &amp; Feinkost","og_description":"Garnacha im Bogen des Ebro Der bislang letzte spanische B\u00fcrgerkrieg war eigentlich schon entschieden, in Mittelkatalonien war eine breite Bresche geschlagen, frei f\u00fcr den Vormarsch der Franquisten (unter Unterst\u00fctzung von Hitler-Deutschland und Mussolini-Italien) gen Barcelona zu marschieren. Doch da gibt es eine kleine Delle des Ebro, nahe des Ortes Mora d&#8217;Ebre, in der sich Republikaner ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2020-02-29T10:00:00+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/02\/Garnacha_im_Bogen_des_Ebro_03498.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Garnacha im Bogen des Ebro","datePublished":"2020-02-29T10:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/"},"wordCount":1158,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/el_oso_aleman.jpg","keywords":["Francesc Ferr\u00e9 Frisach","Garnacha Blanca","Katalonien","Spanien","Terra Alta"],"articleSection":["El oso alem\u00e1n"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/","name":"Garnacha im Bogen des Ebro - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/el_oso_aleman.jpg","datePublished":"2020-02-29T10:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/el_oso_aleman.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/el_oso_aleman.jpg","width":670,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/02\/garnacha-im-bogen-des-ebro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Garnacha im Bogen des Ebro"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/el_oso_aleman.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-mVO","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/88152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=88152"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/88152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/195903"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=88152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=88152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=88152"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=88152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}