{"id":94602,"date":"2020-08-14T11:00:00","date_gmt":"2020-08-14T09:00:00","guid":{"rendered":"https:\/\/www.weine-feinkost.de\/unterwegs\/?p=94602"},"modified":"2020-08-14T11:00:00","modified_gmt":"2020-08-14T09:00:00","slug":"94602-2","status":"publish","type":"post","link":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/","title":{"rendered":"Maskenfreie 2020 B\u00e4ren-summer-school &#8211; Costers del Segre"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Lunya wird politisch: Costers del Segre<\/h3>\n\n\n\n<p>Um diese Region zu verstehen, w\u00e4re ein Grundstudium in \u201epolitischer Winkelz\u00fcgelei\u201c nicht verkehrt, ein Master in spanischer Geographie hilfreich, gesunder Menschenverstand indes ist nicht vonn\u00f6ten; Miguel A. Torres schon. Aber der Reihe nach:<\/p>\n\n\n\n<p>Catalunya gliedert sich in acht Vegueries, Provinzen gelten als von Zentralspanien aufoktroyiert und damit des Teufels; derer zwei beschreiben den Westen von Catalunya: Ponent und Alt Pirineu i Aran. Erstere umfasst den ganzen S\u00fcden, Flachland mit einigen Bergen an allen Seiten; letzteres reicht bis an die Grenze zu Frankreich, die Gebirgskette Montsec de Pallars ist deren s\u00fcdliches Ende. Diese beiden Vegueries bilden die Weinbauregion Costers del Segre. Wobei: so wirklich richtig ist das auch schon wieder nicht.<\/p>\n\n\n\n<p>Im Jahr neunzehnhundert und achtzehn wurde die Kellerei Raimat gegr\u00fcndet. Vier Jahre zuvor hatte die Familie Ravent\u00f3s eine dreitausend zweihundert Hektar umfassende Fl\u00e4che erworben, einen Kanal gegraben, um sie bew\u00e4ssern zu k\u00f6nnen; man begann, Reben zu setzen. Einhundert Jahre sp\u00e4ter sind es mindestens zweitausend dreihundert Hektar Rebland, vielleicht auch mehr. Die Familie Ravent\u00f3s hatte nun neben dem Stammhaus Codorn\u00edu in Sant Sadurn\u00ed d&#8217;Anoia ein zweites, gigantisch anmutendes Projekt. Es dauerte etwa sechzig Jahre, bis man begriff, dass es da ein kleines Problem gibt: denn auch wenn man modern war und innovativ und auch nicht gerade arm, so war dies auch der Nachbar aus El Pacs de Pened\u00e8s, der aber konnte seine Weine als Denominci\u00f3n de Origen Pened\u00e8s verkaufen. Raimat befindet sich wenige Kilometer n\u00f6rdlich von Lleida Stadt, dort gab es keine amtliche Weinbauregion, die Raimat-Weine waren Vinos de Mesa, man durfte keinen Jahrgang, keine Rebsorte, keine Ausbauart auf das Etikett schreiben, w\u00e4hrend Miguel A. Torres stolz mit Etiketten aus dem Pened\u00e8s wedelte. Dies konnte so nicht bleiben. Und daher rannte die Familie Ravent\u00f3s im katalanischen Weinbauinstitut INCAVI offene T\u00fcren ein und nur wenige Augenblicke sp\u00e4ter war die Weinbauregion Costers del Segre in trockenen T\u00fcchern.<\/p>\n\n\n\n<p>Der Familie Ravent\u00f3s half, dass sie zwar eine alte Bodega mit viel Historie war, aber etwas weiter im Osten, hinter den sieben Zwergen, \u00e4hhh Bergen, da stand noch eine Bodega, die viel, viel, viel \u00e4lter war als Raimat: Castell de Remei, gegr\u00fcndet im Jahr siebzehnhundert achtzig. Ansonsten gab es nur ein paar Genossenschaften und \u00e4hnliche Betriebe, die neben Weizen auch Reben auf ihren \u00c4ckern stehen hatte. Castell de Remei spielte eine wesentliche Rolle, denn anders als Raimat, die nur von den Trauben ihrer eigenen Finca in Raimat lebten, arbeitete Remei mit Vertragsweinbauern und anderen Weinbauern zusammen, die \u00fcber ganz Ponent und halb Alt Pirineu i Aran verstreut ackerten. Ohne Remei w\u00e4re Costers del Segre wohl bestenfalls eine Miniweinbauregion geworden, so ist sie, nimmt man die Fl\u00e4che als Ma\u00dfstab, die gr\u00f6\u00dfte in Catalunya, gr\u00f6\u00dfer als alle Weinbauregionen in Arag\u00f3n. Arag\u00f3n ist auch ein nicht unwichtiges Thema, denn in jener Zeit wurde die Weinbauregion Somontano designt, eine Art Blaupause f\u00fcr Costers del Segre.<\/p>\n\n\n\n<p>Wer nun gedacht hatte, dass dies einen Boom ausl\u00f6sen w\u00fcrde, sah sich erst best\u00e4tigt, dann aber schwer entt\u00e4uscht. Denn dieser mittlere Teil von Costers ist eigentlich f\u00fcr Weinbau nur bedingt geeignet. Raimat hat das Riesenprojekt verwirklicht, weil man mehrere hundert Kilometer Wasserkan\u00e4le gegraben hatte, Brachland war pl\u00f6tzlich fruchtbar. Brachland wurde auch an anderen Stellen in Ponent fruchtbar, schlie\u00dflich ist dies die zentrale Fruchtquelle Spaniens, insbesondere \u00c4pfel und Birnen werden hier kultiviert, jede Menge Gem\u00fcse auch. Dies aber hatte und hat Vorrang, Reben findet man nur an wenigen Stellen. Sei es im Osten, in der Gegend um das Dorf Verd\u00fa, sei es im Norden von Raimat, gen Arag\u00f3n, sei es im S\u00fcdwesten von Lleida Stadt: \u00fcberall stehen Reben dort, wo sonst nun auch wirklich gar nichts w\u00e4chst, selbst nach Regenf\u00e4llen ist der Boden staubtrocken, die Weine sind eindimensional, alkohollastig, erm\u00fcdend. Aus internationalen Rebsorten keltert man belanglose Weine, so etwas wie einheimische Sorten, Garnacha etwa, findet man wenig, Macabeo nur dort, wo Cava-Plantagen erlaubt sind. Gut zwei Dutzend Weing\u00fcter begannen in den letzten zwanzig Jahren. Die durchschnittliche Lebensdauer der Bodegas ist so hoch nicht, viele haben keine zehn Jahre durchgehalten. Andere m\u00fchen sich auf dem lokalen Markt ab oder verkaufen zu Preisen, die nicht einmal in Somontano aufgerufen werden.<\/p>\n\n\n\n<p>Will man interessante Weine aus Costers del Segre kennenlernen, oder zumindest interessante Projekte, dann muss man in den Norden reisen oder in den S\u00fcden.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/baldomar_montsec.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/baldomar_montsec.jpg\" alt=\"\" class=\"wp-image-168263\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/baldomar_montsec.jpg 800w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/baldomar_montsec-300x200.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/baldomar_montsec-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption>Baldomar.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Artesa d&#8217;Segre ist ein netter, kleiner Ort, es gibt eine Genossenschaft, ein paar M\u00f6belfabrikanten und auch das eine oder andere Weingut. Vall de Baldomar etwa, eine kleine Bodega aus dem Nachbardorf Baldomar, die das Pech hatte, genau in der Phase auf die Welt zu kommen, in der internationale Sorten gefragt waren. Merlot etwa, nur wer will Stahltankmerlot aus Baldomar. Oder aber Incrocio Manzoni; Weine aus Rebsorten, die schwer auszusprechen sind, verkaufen sich nicht. Oder aber die Cooperative: dort keltert man einen guten frischen Wein, Stahltankausbau, Tempranillo und Garnacha. Das kleine Problem: Weinbau macht etwa zwei Prozent der Handelsaktivit\u00e4t der Genossenschaft aus, da kommt man auf keinen gr\u00fcnen Zweig. Der M\u00f6belproduzent ist M\u00f6belproduzent, sein Weingut ist ein besseres Hobby, sobald er sich zur Ruhe setzt, wird sich auch das Weingut zur Ruhe setzen. Ein paar weitere Weing\u00fcter runden die Szene ab, allen haben mindestens einen guten Wein im Programm, aber niemand ist willens, den m\u00fchsamen Weg hin zu einer angesehenen Bodega mit erstklassigen Weinen zu gehen. Hierf\u00fcr muss man etwas weiter gen Norden laufen, gen Tremp, durch die engen Schluchten, die der Segre oder die beiden Nogueras, der Noguera Pallaresa im Osten und der Noguera Ribagor\u00e7ana im Westen, in den Fels geschlagen haben. Hat man das geschafft, dann ist man in der Vegueria Alt Pirineu.<\/p>\n\n\n\n<p>Der Weinbau in Alt Pirineu hat mit dem in Ponent nichts zu tun. Seit Jahren versucht man, sich abzuspalten, eine neue Weinbauregion soll entstehen. Dumm nur, dass die beiden wichtigsten Weinentscheidungstr\u00e4ger dieser Ecke gar nichts davon halten. Pallars, der inoffizielle Name der Region, erstreckt sich von den Montsec-Bergen bis kurz vor die Pyren\u00e4en, Sort ist der n\u00f6rdlichste Weinbauort, Tremp, etwas weiter s\u00fcdlich gelegen, der wichtigste. Die klimatischen Gegebenheiten sind speziell, man kann dies unschwer an den Weinen erkennen, die Ra\u00fcl Bobet in Castell d&#8217;Encus keltert. Man kann nun diskutieren, ob dies Terroir ist oder einfach \u201enur\u201c interpretiertes Klima. Ra\u00fcl hat auf eintausend Meter \u00fcber Meeresniveau etwa f\u00fcnfzehn verschiedene Rebsorten stehen, die in sechs bis zehn Weinen m\u00fcnden. Riesling findet man da, auch Sauvignon blanc und Albari\u00f1o; Pinot Noir neben Cabernet Franc, und noch dies und noch das. Ra\u00fcl interessiert sich nicht so sehr f\u00fcr Rebsorten, er will K\u00fchle und Granitnoten in Flaschen packen. Das ist gut, manche Weine sind sogar sehr gut, nur hilft das der Region Pallars nicht wirklich weiter.<\/p>\n\n\n\n<p>Der andere Herr, die andere \u201eBodega\u201c, hat mit Terroir ohnehin nichts am Hut. Miguel A. Torres hat vor \u00fcber zehn Jahren im Westen von Tremp einhundert und siebzig Hektar Rebland bestockt, fast alles mit Merlot, seine Lieblingsrebsorte. Hier stiftet dies Sinn, da Merlot dort gut ausreifen kann. Es ist aber nicht geplant, diesen Merlot als Pallars-Wein abzuf\u00fcllen, die D.O. Catalunya l\u00e4sst gr\u00fc\u00dfen.<\/p>\n\n\n\n<p>R\u00fcckblende: vor ein paar hundert Jahren wurden in Pallars an vielen Stellen Reben kultiviert, es wurden diverse Weine gekeltert. Damals indes war die Region weit dichter besiedelt als heute, es gab einen gr\u00f6\u00dferen Markt, Wein war ein wichtiges Produkt. Mit der Zeit \u00e4nderte sich dies, die Menschen folgten den Arbeitspl\u00e4tzen, und die gab und gibt es nun einmal im S\u00fcden, in Ponent, in Lleida Stadt oder l\u00e4ngs der Autobahn, die Lleida mit Barcelona verbindet. Oder gleich in und um Barcelona. Inzwischen ist Alt Pirineu gut an den S\u00fcden angebunden, f\u00fcr den Weinbau indes kommt dies zu sp\u00e4t. Vor f\u00fcnfzig Jahren gab es in den engen Schluchten, die Fl\u00fcsse durch das Montsec-Gebirge getrieben haben, kaum gut befestigte Stra\u00dfen, Weintransport war ein Gl\u00fccksspiel. Im B\u00fcrgerkrieg nutzte Franco die Stauseen im Norden, um mit pl\u00f6tzlichem \u00d6ffnen der Wehre den Ebro im S\u00fcden zu fluten, um die Truppen der Republikaner vor Probleme zu stellen.&nbsp;<\/p>\n\n\n\n<p>Mitte der neunziger Jahre des letzten Jahrhunderts gab es mit Vila-Corona in Pallars genau ein Weingut, und in dem wurden auch noch fast nur internationaltypische Weine gekeltert. Inzwischen gibt es dort wieder einige Betriebe, Batlliu de Sort und Miquel Roca, Sauvella und noch ein paar mehr: einige sind sehr gut, andere wiederum keltern extrem traditionelle Weine.<\/p>\n\n\n\n<p>Mal wieder der klassische Zielkonflikt: die kleinen Bodegas keltern f\u00fcnftausend Liter Wein, vielleicht derer zehntausend, die gr\u00f6\u00dften der Kleinen derer zwanzigtausend. Die kriegen sie inzwischen in Barcelona, in Lleida, aber auch in der Region (Hebsttourismus im Vorpyren\u00e4enland) ganz gut vermarktet. F\u00fcr alles andere fehlen erst einmal Rebfl\u00e4chen und, so diese einmal gepflanzt w\u00e4ren, Menschen, um sie zu beackern. Und Ra\u00fcl Bobet, Mitinhaber der Priorat-Kellerei Ferrer-Bobet, hat keine Lust, die Lokomotive zu spielen, wissend, dass an ihm die ganze Arbeit h\u00e4ngenbleiben w\u00fcrde, w\u00e4hrend die anderen bequem in seinem Windschatten segeln w\u00fcrden.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/cervoles_das_dorf.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/cervoles_das_dorf.jpg\" alt=\"\" class=\"wp-image-168264\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/cervoles_das_dorf.jpg 800w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/cervoles_das_dorf-300x200.jpg 300w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/cervoles_das_dorf-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption>Das Dorf Cervoles.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Richtig spannend ist dann wieder der S\u00fcden, dort, wo die Comarca Les Garrigues an Montsant, an das Priorat und an Conca de Barber\u00e0 grenzt. Dies ist welliges Bergland, die Gipfel enden knapp \u00fcber eintausend H\u00f6henmetern, Sandstein, Sandmergel, kalkhaltig, knappe Lehmkrumen, dichte Steinauflage. Und halt, das ist so unwichtig dann doch nicht: H\u00e4nge, die gen Norden abfallen, oder gen Nordwesten oder gen Nordosten, etwas besser gesch\u00fctzt vor den Sonnenplage am Nachmittag. Hier kann man Garnacha mit vierzehn Umdrehungen ernten, im Priorat geht das nur bedingt. Das Problem: hier gibt es mit El Vilosell und La Pobla de C\u00e9rvoles gerade einmal zwei D\u00f6rfer, in denen vor allem alte Leute leben. Eine Zukunft hat der Weinbau hier nur, weil zwei Bodegas am Start sind, die schon bestrebt sind, Weine der Region zu pr\u00e4sentieren. Wobei: bei einer der beiden ist das so eine Sache, da muss man halt glauben, was Tomas so sagt. Tomas Cusin\u00e9 hat in El Vilosell vor einigen Jahren seine eigene Bodega gegr\u00fcndet, er verf\u00fcgt dort \u00fcber eine gute Menge an Rebland, hier entstehen vor allem Weine, die in die Kategorie \u201eeinfach zu trinken\u201c fallen, aber auch der eine oder andere durchaus individuellere Wein. Im Nachbardorf gibt es die Bodega C\u00e9rvoles, die Zweitbodega von Castell de Remei, das Stammhaus der Familie Cusin\u00e9, Hauptsitz der Bodegagruppe, in Remei, mitten im Flachland. Inzwischen ist Tomas technischer Direktor in allen drei Bodegas, alleiniger Eigent\u00fcmer seiner Kellerei in El Vilosell. Als dem noch nicht so waren, da waren die Dinge gut getrennt. Heute, das sagt er selbst, wandert schon Wein aus dem S\u00fcden gen Hauptbodega, umgekehrt eher nicht, da im S\u00fcden vor allem Garnacha steht, die gibt es im zentralen Tiefland nicht wirklich.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/mas_blanch_dasei.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/mas_blanch_dasei.jpg\" alt=\"\" class=\"wp-image-168267\" srcset=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/mas_blanch_dasei.jpg 533w, https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/mas_blanch_dasei-200x300.jpg 200w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><\/a><figcaption>Zement Ei bei Mas Blanch.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Das ist schon alles nicht schlecht (zumindest die Weine aus den beiden S\u00fcd-Bodegas), es ist aber vor allem wichtig, weil so nicht alles auf den Schultern einer kleinen Bodega lastet, die derzeit zumindest im S\u00fcden der Region Costers del Segre den Ton angibt: Mas Blanch i Jov\u00e9. Joan Jov\u00e9 und seine Tochter Sara wollen gar nicht Costers del Segre repr\u00e4sentieren, sie wollen aber das herausarbeiten, was Les Garrigues darstellen soll: stoffige, aber dennoch frische und von Frucht getragene Weine, vor allem aus Garnacha,&nbsp; komplettiert mit ein paar Einsprengseln internationaler Art, vor allem Cabernet Sauvignon und Tempranillo, Syrah f\u00fcr einen Quietsch-Rosado. Es gibt inzwischen Lagenweine von durchaus guter Qualit\u00e4t, die neueste Kreation ist der Troballa (Entdeckung), der in Amphoren, in einem Zementei und in ein paar Barricas reift. Ganz neu ist eine Zement-Entdeckung, dieser Wein kommt vielleicht in diesem Herbst erstmals auf den Markt. Frische Wei\u00dfweine, unkomplizierte Rotweine, dies sind die wichtigsten Weine der Bodega. Die Barriqueweine leiden noch etwas unter traditionellem Barriqueverst\u00e4ndnis, aber auch das ist nur eine Frage der Zeit.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.04670000186101%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/kunst_kannnichtweg_3.jpg?ssl=1\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/kunst_kannnichtweg_3.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/kunst_kannnichtweg_3.jpg?strip=info&#038;w=800&#038;ssl=1 800w\" alt=\"\" data-height=\"532\" data-id=\"94665\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=94665\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/kunst_kannnichtweg_3.jpg\" data-width=\"800\" src=\"https:\/\/i0.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/kunst_kannnichtweg_3.jpg?ssl=1\" layout=\"responsive\"\/><\/a><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:49.953299998138995%\"><figure class=\"tiled-gallery__item\"><a href=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/kunst_kannnichtweg_2.jpg?ssl=1\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/kunst_kannnichtweg_2.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/kunst_kannnichtweg_2.jpg?strip=info&#038;w=800&#038;ssl=1 800w\" alt=\"\" data-height=\"533\" data-id=\"94664\" data-link=\"https:\/\/www.weine-feinkost.de\/unterwegs\/?attachment_id=94664\" data-url=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/kunst_kannnichtweg_2.jpg\" data-width=\"800\" src=\"https:\/\/i2.wp.com\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/kunst_kannnichtweg_2.jpg?ssl=1\" layout=\"responsive\"\/><\/a><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p>Mas Blanch i Jov\u00e9 ist in der Kunst- und K\u00fcnstlerszene von Barcelona stark verwurzelt, einmal im Jahr, am ersten Samstag im Juli, gibt es die Festa de Artistes, Jahr f\u00fcr Jahr kommen etwa f\u00fcnfhundert Menschen, um zu feiern, zu essen und zu trinken. Die Gruppe der Artisten besitzt und beackert einen eigenen Weinberg, jedes Jahr installieren sie etwas in der Region, nach und nach entsteht dort ein kleines Freilichtmuseum. Auch so wird Les Garrigues, der S\u00fcden von Costers del Segre, bekannt.<\/p>\n\n\n\n<p>Der Fall Costers del Segre ist anders gelagert als der Fall Conca de Barber\u00e0, denn hier k\u00f6nnte zumindest eine regionale Pr\u00e4sentation (Alt Pirineu, Les Garrigues) funktionieren, Raimat aka Codorn\u00edu aka Carlyle interessiert sich f\u00fcr so etwas nicht. Text: El oso alem\u00e1n<\/p>\n\n\n\n<p><strong>Teil 3. Terra Alta <\/strong>erscheint auf diesem Blog am 21.08.2020 um 11.00 Uhr.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lunya wird politisch: Costers del Segre Um diese Region zu verstehen, w\u00e4re ein Grundstudium in \u201epolitischer Winkelz\u00fcgelei\u201c nicht verkehrt, ein Master in spanischer Geographie hilfreich, gesunder Menschenverstand indes ist nicht vonn\u00f6ten; Miguel A. Torres schon. Aber der Reihe nach: Catalunya gliedert sich in acht Vegueries, Provinzen gelten als von Zentralspanien aufoktroyiert und damit des Teufels; &#8230; <a title=\"Maskenfreie 2020 B\u00e4ren-summer-school &#8211; Costers del Segre\" class=\"read-more\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/\" aria-label=\"Mehr dazu unter Maskenfreie 2020 B\u00e4ren-summer-school &#8211; Costers del Segre\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":195903,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1004],"tags":[2619,346,79],"post_folder":[],"class_list":["post-94602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-oso-aleman-klartext","tag-catalunya","tag-costers-del-segre","tag-spanien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maskenfreie 2020 B\u00e4ren-summer-school - Costers del Segre - Unterwegs mit Weine &amp; Feinkost<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maskenfreie 2020 B\u00e4ren-summer-school - Costers del Segre - Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"og:description\" content=\"Lunya wird politisch: Costers del Segre Um diese Region zu verstehen, w\u00e4re ein Grundstudium in \u201epolitischer Winkelz\u00fcgelei\u201c nicht verkehrt, ein Master in spanischer Geographie hilfreich, gesunder Menschenverstand indes ist nicht vonn\u00f6ten; Miguel A. Torres schon. Aber der Reihe nach: Catalunya gliedert sich in acht Vegueries, Provinzen gelten als von Zentralspanien aufoktroyiert und damit des Teufels; ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterwegs mit Weine &amp; Feinkost\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-14T09:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/kunst_kannnichtweg_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Fenske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fenske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/\"},\"author\":{\"name\":\"Christian Fenske\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\"},\"headline\":\"Maskenfreie 2020 B\u00e4ren-summer-school &#8211; Costers del Segre\",\"datePublished\":\"2020-08-14T09:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/\"},\"wordCount\":2177,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/el_oso_aleman.jpg\",\"keywords\":[\"Catalunya\",\"Costers del Segre\",\"Spanien\"],\"articleSection\":[\"El oso alem\u00e1n\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/\",\"name\":\"Maskenfreie 2020 B\u00e4ren-summer-school - Costers del Segre - Unterwegs mit Weine &amp; Feinkost\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/el_oso_aleman.jpg\",\"datePublished\":\"2020-08-14T09:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/el_oso_aleman.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/el_oso_aleman.jpg\",\"width\":670,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/2020\\\/08\\\/94602-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maskenfreie 2020 B\u00e4ren-summer-school &#8211; Costers del Segre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#website\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"description\":\"Entdecken Sie Genuss\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#organization\",\"name\":\"Unterwegs mit Weine &amp; Feinkost\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_weinefeinkost_unterwegs_450x171.png\",\"width\":450,\"height\":171,\"caption\":\"Unterwegs mit Weine &amp; Feinkost\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/#\\\/schema\\\/person\\\/c07d66169fd0e04307bfe7cdc99ac26a\",\"name\":\"Christian Fenske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-christian_profilbild-96x96.png\",\"caption\":\"Christian Fenske\"},\"description\":\"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.\",\"url\":\"https:\\\/\\\/www.weine-feinkost.de\\\/unterwegs\\\/author\\\/christian-fenske\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maskenfreie 2020 B\u00e4ren-summer-school - Costers del Segre - Unterwegs mit Weine &amp; Feinkost","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/","og_locale":"de_DE","og_type":"article","og_title":"Maskenfreie 2020 B\u00e4ren-summer-school - Costers del Segre - Unterwegs mit Weine &amp; Feinkost","og_description":"Lunya wird politisch: Costers del Segre Um diese Region zu verstehen, w\u00e4re ein Grundstudium in \u201epolitischer Winkelz\u00fcgelei\u201c nicht verkehrt, ein Master in spanischer Geographie hilfreich, gesunder Menschenverstand indes ist nicht vonn\u00f6ten; Miguel A. Torres schon. Aber der Reihe nach: Catalunya gliedert sich in acht Vegueries, Provinzen gelten als von Zentralspanien aufoktroyiert und damit des Teufels; ... Weiterlesen","og_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/","og_site_name":"Unterwegs mit Weine &amp; Feinkost","article_published_time":"2020-08-14T09:00:00+00:00","og_image":[{"width":800,"height":532,"url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2020\/08\/kunst_kannnichtweg_3.jpg","type":"image\/jpeg"}],"author":"Christian Fenske","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Fenske","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/#article","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/"},"author":{"name":"Christian Fenske","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a"},"headline":"Maskenfreie 2020 B\u00e4ren-summer-school &#8211; Costers del Segre","datePublished":"2020-08-14T09:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/"},"wordCount":2177,"commentCount":0,"publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/el_oso_aleman.jpg","keywords":["Catalunya","Costers del Segre","Spanien"],"articleSection":["El oso alem\u00e1n"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/","name":"Maskenfreie 2020 B\u00e4ren-summer-school - Costers del Segre - Unterwegs mit Weine &amp; Feinkost","isPartOf":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/#primaryimage"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/el_oso_aleman.jpg","datePublished":"2020-08-14T09:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/#primaryimage","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/el_oso_aleman.jpg","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/el_oso_aleman.jpg","width":670,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/2020\/08\/94602-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.weine-feinkost.de\/unterwegs\/"},{"@type":"ListItem","position":2,"name":"Maskenfreie 2020 B\u00e4ren-summer-school &#8211; Costers del Segre"}]},{"@type":"WebSite","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#website","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","name":"Unterwegs mit Weine &amp; Feinkost","description":"Entdecken Sie Genuss","publisher":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weine-feinkost.de\/unterwegs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#organization","name":"Unterwegs mit Weine &amp; Feinkost","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/logo_weinefeinkost_unterwegs_450x171.png","width":450,"height":171,"caption":"Unterwegs mit Weine &amp; Feinkost"},"image":{"@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/#\/schema\/person\/c07d66169fd0e04307bfe7cdc99ac26a","name":"Christian Fenske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","contentUrl":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2023\/01\/cropped-christian_profilbild-96x96.png","caption":"Christian Fenske"},"description":"Zusammen an einem Tisch sitzen, gemeinsam zu kommunizieren und zu genie\u00dfen, das ist eine der herausragenden kulturellen Errungenschaft der Menschheit.","url":"https:\/\/www.weine-feinkost.de\/unterwegs\/author\/christian-fenske\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-content\/uploads\/2022\/10\/el_oso_aleman.jpg","jetpack_shortlink":"https:\/\/wp.me\/p68Tjo-oBQ","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/94602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/comments?post=94602"}],"version-history":[{"count":0,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/posts\/94602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media\/195903"}],"wp:attachment":[{"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/media?parent=94602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/categories?post=94602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/tags?post=94602"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.weine-feinkost.de\/unterwegs\/wp-json\/wp\/v2\/post_folder?post=94602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}